{"id":11422,"date":"2022-07-15T16:03:16","date_gmt":"2022-07-15T19:03:16","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=11422"},"modified":"2022-07-15T16:03:19","modified_gmt":"2022-07-15T19:03:19","slug":"recuperado-marco-antonio-volta-a-ser-relacionado-apos-um-mes-e-meio-de-ausencia","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2022\/07\/15\/recuperado-marco-antonio-volta-a-ser-relacionado-apos-um-mes-e-meio-de-ausencia\/","title":{"rendered":"Recuperado, Marco Ant\u00f4nio volta a ser relacionado ap\u00f3s um m\u00eas e meio de aus\u00eancia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"280\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/07\/IMAGEM_BAHIA_5-4.jpg\" alt=\"\" class=\"wp-image-11427\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/07\/IMAGEM_BAHIA_5-4.jpg 380w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/07\/IMAGEM_BAHIA_5-4-300x221.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/07\/IMAGEM_BAHIA_5-4-80x60.jpg 80w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><figcaption>Foto: Felipe Oliveira\/ Divulga\u00e7\u00e3o \/EC Bahia<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O meia-atacante Marco Ant\u00f4nio est\u00e1 na rela\u00e7\u00e3o de atletas do Bahia que vai enfrentar o Guarani neste s\u00e1bado (16), \u00e0s 18h30, em Campinas, pela 18\u00aa rodada da S\u00e9rie B. Recuperado de um estiramento grau 2 na coxa, o jogador viajou com o grupo na tarde desta sexta-feira (15) e pode voltar a jogar ap\u00f3s um m\u00eas e meio.<\/p>\n\n\n\n<p>A \u00faltima partida de Marco Ant\u00f4nio foi no dia 27 de maio, na derrota por 1 a 0 contra o Tombense em Muria\u00e9. Desde ent\u00e3o, ele encarou um longo processo de recupera\u00e7\u00e3o cl\u00ednica e f\u00edsica.<\/p>\n\n\n\n<p>Em seu retorno, Marco ir\u00e1 reencontrar Enderson Moreira, com quem teve uma parceria de sucesso no Botafogo em 2021 ao conquistar o t\u00edtulo da S\u00e9rie B. Na \u00faltima edi\u00e7\u00e3o da divis\u00e3o de acesso, ele disputou 37 partidas, com nove gols e tr\u00eas assist\u00eancias.<\/p>\n\n\n\n<p>Na temporada 2022, o paraense revelado na base tricolor ainda tenta se reencontrar. At\u00e9 o momento, ele disputou 26 partidas, balan\u00e7ou a rede cinco vezes e deu tr\u00eas assist\u00eancias para gol.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O meia-atacante Marco Ant\u00f4nio est\u00e1 na rela\u00e7\u00e3o de atletas do Bahia que vai enfrentar o Guarani neste s\u00e1bado (16), \u00e0s 18h30, em Campinas, pela 18\u00aa rodada da S\u00e9rie B. Recuperado de um estiramento grau 2 na coxa, o jogador viajou com o grupo na tarde desta sexta-feira (15) e pode voltar a jogar ap\u00f3s um [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11427,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-11422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/11422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=11422"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/11422\/revisions"}],"predecessor-version":[{"id":11428,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/11422\/revisions\/11428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/11427"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=11422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=11422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=11422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}