{"id":12776,"date":"2022-09-21T10:50:46","date_gmt":"2022-09-21T13:50:46","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=12776"},"modified":"2022-09-21T10:50:48","modified_gmt":"2022-09-21T13:50:48","slug":"laboratorio-brasileiro-vai-estabelecer-base-na-nasa","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2022\/09\/21\/laboratorio-brasileiro-vai-estabelecer-base-na-nasa\/","title":{"rendered":"Laborat\u00f3rio brasileiro vai estabelecer base na Nasa"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/09\/image-61.png\" alt=\"\" class=\"wp-image-12784\" width=\"540\" height=\"235\"\/><figcaption>O laborat\u00f3rio ser\u00e1 instalado no Centro Espacial Kennedy, na Fl\u00f3rida, Estados Unidos | Foto: Reprodu\u00e7\u00e3o\/Flickr<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Um laborat\u00f3rio brasileiro vai estabelecer uma base no Centro Espacial Kennedy, da Nasa, na Fl\u00f3rida, Estados Unidos. Os pesquisadores v\u00e3o usar c\u00e9lulas-tronco no desenvolvimento da medicina regenerativa e observar seu comportamento em ambiente com microgravidade.<\/p>\n\n\n\n<p>O laborat\u00f3rio isola, expande e armazena c\u00e9lulas-tronco do dente, tecido adiposo e c\u00e9u da boca. A viabilidade do projeto se deu por meio de acordo de coopera\u00e7\u00e3o in\u00e9dito com o Academia Espacial Internacional (KSCIA, na sigla em ingl\u00eas).<\/p>\n\n\n\n<p>O laborat\u00f3rio R-Crio, localizado em Campinas, no interior de S\u00e3o Paulo, iniciou as negocia\u00e7\u00f5es em 2014 e considera esse um grande acontecimento para a ci\u00eancia brasileira.<\/p>\n\n\n\n<p>Por meio da parceria com a Nasa, ser\u00e1 dedicado \u201cum bra\u00e7o\u201d de seu segmento de pesquisa e desenvolvimento ao estudo do comportamento das c\u00e9lulas-tronco em ambiente com microgravidade. \u201cIsso pode melhorar a solu\u00e7\u00e3o de entrega para a medicina regenerativa, seja para a produ\u00e7\u00e3o de medicamentos ou o uso direto das c\u00e9lulas-tronco em terapias\u201d, explicou o cientista que est\u00e1 \u00e0 frente do projeto, Jos\u00e9 Ricardo Muniz Ferreira.<\/p>\n\n\n\n<p>\u201cNa Nasa, estamos pr\u00f3ximos de divis\u00f5es cient\u00edficas de estudos muito importantes, como os da Universidade de Zurique, os da Universidade da Fl\u00f3rida e os de tantos outros importantes grupos internacionais\u201d, acrescentou Ferreira.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Revista Oeste<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um laborat\u00f3rio brasileiro vai estabelecer uma base no Centro Espacial Kennedy, da Nasa, na Fl\u00f3rida, Estados Unidos. Os pesquisadores v\u00e3o usar c\u00e9lulas-tronco no desenvolvimento da medicina regenerativa e observar seu comportamento em ambiente com microgravidade. O laborat\u00f3rio isola, expande e armazena c\u00e9lulas-tronco do dente, tecido adiposo e c\u00e9u da boca. A viabilidade do projeto se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12784,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-12776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/12776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=12776"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/12776\/revisions"}],"predecessor-version":[{"id":12785,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/12776\/revisions\/12785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/12784"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=12776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=12776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=12776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}