{"id":12961,"date":"2022-09-28T07:15:39","date_gmt":"2022-09-28T10:15:39","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=12961"},"modified":"2022-09-28T07:15:42","modified_gmt":"2022-09-28T10:15:42","slug":"quaest-lula-tem-505-dos-votos-validos-contra-363-de-bolsonaro","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2022\/09\/28\/quaest-lula-tem-505-dos-votos-validos-contra-363-de-bolsonaro\/","title":{"rendered":"Quaest: Lula tem 50,5% dos votos v\u00e1lidos contra 36,3% de Bolsonaro"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"309\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/09\/5e574f00-0ed0-11ed-a8e5-f72294073c81.jpg\" alt=\"\" class=\"wp-image-12962\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/09\/5e574f00-0ed0-11ed-a8e5-f72294073c81.jpg 550w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/09\/5e574f00-0ed0-11ed-a8e5-f72294073c81-300x169.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o Uol <\/figcaption><\/figure>\n<\/div>\n\n\n<p>Pesquisa Genial\/Quaest divulgada nesta quarta (28) mostra o ex-presidente Luiz In\u00e1cio Lula da Silva (PT) com 50,5% das inten\u00e7\u00f5es de votos v\u00e1lidos na corrida presidencial, contra 36,3% de Jair Bolsonaro (PL). Com este n\u00famero, o petista seria eleito no primeiro turno.<\/p>\n\n\n\n<p>Nos votos totais, Lula tem 46%, oscila\u00e7\u00e3o positiva de dois pontos em rela\u00e7\u00e3o \u00e0 pesquisa da semana passada. Bolsonaro oscilou um ponto para baixo e foi para 33%. Ciro Gomes (PDT) manteve os 6%, assim como Simone Tebet (MDB) com 5%. Soraia Thronicke (Uni\u00e3o Brasil) continua com 1%.<\/p>\n\n\n\n<p>O n\u00famero de indecisos \u00e9 de 5% nessa nova rodada, enquanto brancos ou nulos somam 4%. Os demais candidatos n\u00e3o pontuaram na pesquisa, que \u00e9 financiada pela corretora de investimentos digital Genial Investimentos, controlada pelo banco Genial. A margem de erro \u00e9 de dois pontos, para mais ou para menos.<\/p>\n\n\n\n<p>VOTOS TOTAIS<br>Lula (PT) \u2013 46% (tinha 44%)<br>Bolsonaro (PL) \u2013 33% (tinha 34%)<br>Ciro Gomes (PDT) \u2013 6% (tinha 6%)<br>Simone Tebet (MDB) \u2013 5% (tinha 5%)<br>Soraia Thronicke (Uni\u00e3o Brasil) \u2013 1% (tinha 1%)<br>Indecisos \u2013 5% (eram 5%)<br>Branco\/nulo \u2013 4% (eram 5%)<br>A sondagem da Quaest, empresa de consultoria e pesquisa, ouviu 2.000 pessoas com mais de 16 anos nos domic\u00edlios de s\u00e1bado (24) at\u00e9 a noite desta ter\u00e7a (27). O n\u00famero do registro na Justi\u00e7a Eleitoral \u00e9 BR-04371\/2022.<\/p>\n\n\n\n<p>Na simula\u00e7\u00e3o de segundo turno, Lula registra 52% das inten\u00e7\u00f5es de voto, variando dois pontos percentuais para cima em rela\u00e7\u00e3o \u00e0 rodada anterior (50%). J\u00e1 Bolsonaro oscilou negativamente de 40% para 38% no per\u00edodo.<\/p>\n\n\n\n<p>Entre os entrevistados da Genial\/Quaest, 79% est\u00e3o decididos sobre os seus votos, enquanto 20% ainda podem mudar. Para Lula ganhar j\u00e1 no primeiro turno, 24% dizem que trocariam de candidato (eram 26% h\u00e1 uma semana); 66% n\u00e3o topariam a manobra (eram 64%).<\/p>\n\n\n\n<p>O levantamento mostra ainda que a avalia\u00e7\u00e3o negativa do governo continua a subir e foi de 39% para 42%. A avalia\u00e7\u00e3o positiva mant\u00e9m os 31%.<\/p>\n\n\n\n<p>Bolsonaro segue como o mais rejeitado. Entre os entrevistados, 55% dizem que n\u00e3o votariam no presidente de jeito nenhum. Ciro \u00e9 o segundo com 53% seguido por Lula, com 44%.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*<em>Fernando Pedroso\/Folhapress<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisa Genial\/Quaest divulgada nesta quarta (28) mostra o ex-presidente Luiz In\u00e1cio Lula da Silva (PT) com 50,5% das inten\u00e7\u00f5es de votos v\u00e1lidos na corrida presidencial, contra 36,3% de Jair Bolsonaro (PL). Com este n\u00famero, o petista seria eleito no primeiro turno. Nos votos totais, Lula tem 46%, oscila\u00e7\u00e3o positiva de dois pontos em rela\u00e7\u00e3o \u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12962,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-12961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/12961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=12961"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/12961\/revisions"}],"predecessor-version":[{"id":12963,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/12961\/revisions\/12963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/12962"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=12961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=12961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=12961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}