{"id":13698,"date":"2022-11-02T21:01:56","date_gmt":"2022-11-03T00:01:56","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=13698"},"modified":"2022-11-02T21:02:11","modified_gmt":"2022-11-03T00:02:11","slug":"homem-morre-em-hospital-apos-ser-baleado-na-frente-de-casa-em-santaluz","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2022\/11\/02\/homem-morre-em-hospital-apos-ser-baleado-na-frente-de-casa-em-santaluz\/","title":{"rendered":"Homem morre em hospital ap\u00f3s ser baleado na frente de casa em Santaluz"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/11\/image-9.png\" alt=\"\" class=\"wp-image-13699\" width=\"473\" height=\"354\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/11\/image-9.png 630w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/11\/image-9-300x225.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/11\/image-9-561x420.png 561w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/11\/image-9-80x60.png 80w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/11\/image-9-265x198.png 265w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><figcaption>Foto: Divulga\u00e7\u00e3o Redes Sociais<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Um homem morreu ap\u00f3s ser baleado na frente de casa, na noite da ter\u00e7a-feira (2\u00ba), em Santaluz, cidade que fica a cerca de 48 km distante de Concei\u00e7\u00e3o do Coit\u00e9. Segundo apura\u00e7\u00e3o da reportagem do Informe Coit\u00e9, a v\u00edtima chegou a ser levada para o Hospital Cl\u00e9riston Andrade, em Feira de Santana, mas n\u00e3o resistiu aos ferimentos e morreu na unidade de sa\u00fade. A reportagem \u00e9 do jornalista e radialista Renny Maia.<\/p>\n\n\n\n<p>O caso aconteceu por volta das 20h45, no bairro do Recreio. Segundo a PM, Cleber Machado Souza, conhecido por \u2019Clebinho\u2019, de 39 anos, estava em frente \u00e0 casa dele quando o suspeito armado chegou em uma motocicleta e fizeram v\u00e1rios disparos contra a v\u00edtima.<\/p>\n\n\n\n<p>A pol\u00edcia informou que a guarni\u00e7\u00e3o foi informada por volta das 20h50, em face den\u00fancia de que um homem havia sido alvejado na Rua Estrada Velha de Valente. No local, a guarni\u00e7\u00e3o encontrou a v\u00edtima no colo da esposa, visto que estava com vida e foi solicitado socorro. Uma ambul\u00e2ncia do SAMU se fez presente e encaminhou Clebinho para o Hospital Municipal.&nbsp; Por conta da gravidade ele foi transferido para o Hospital Geral Cl\u00e9riston Andrade (HGCA) em Feira de Santana, onde faleceu na tarde desta quarta-feira, 02\/11.<\/p>\n\n\n\n<p>O caso \u00e9 investigado pela delegacia de Santaluz. Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre a localiza\u00e7\u00e3o do suspeito e ou motiva\u00e7\u00e3o do crime. Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre sepultamento.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Informe Coit\u00e9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem morreu ap\u00f3s ser baleado na frente de casa, na noite da ter\u00e7a-feira (2\u00ba), em Santaluz, cidade que fica a cerca de 48 km distante de Concei\u00e7\u00e3o do Coit\u00e9. Segundo apura\u00e7\u00e3o da reportagem do Informe Coit\u00e9, a v\u00edtima chegou a ser levada para o Hospital Cl\u00e9riston Andrade, em Feira de Santana, mas n\u00e3o resistiu [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13699,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-13698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/13698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=13698"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/13698\/revisions"}],"predecessor-version":[{"id":13700,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/13698\/revisions\/13700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/13699"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=13698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=13698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=13698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}