{"id":14716,"date":"2022-12-20T15:33:58","date_gmt":"2022-12-20T18:33:58","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=14716"},"modified":"2022-12-20T15:34:01","modified_gmt":"2022-12-20T18:34:01","slug":"filha-de-carlinhos-brown-clara-buarque-estreia-em-travessia-realizando-mais-um-sonho","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2022\/12\/20\/filha-de-carlinhos-brown-clara-buarque-estreia-em-travessia-realizando-mais-um-sonho\/","title":{"rendered":"Filha de Carlinhos Brown, Clara Buarque estreia em \u2018Travessia\u2019: \u2018Realizando mais um sonho\u2019"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-56.png\" alt=\"\" class=\"wp-image-14724\" width=\"512\" height=\"307\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-56.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-56-300x180.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-56-768x461.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-56-696x417.png 696w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-56-700x420.png 700w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o\/Instagram<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Filha de Carlinhos Brown, Clara Buarque, 24 anos, ir\u00e1 estrear na novela \u2018Travessia\u2019 ainda nesta semana. A personagem da artista se chama \u201cBia\u201d e chega para movimentar a trama em buscas de respostas pelo sumi\u00e7o de D\u00e9bora (Grazi Massafera).<\/p>\n\n\n\n<p>\u201cBia chega essa semana em \u2018Travessia\u2019. Sempre soube que a hora certa de estar aqui ia chegar. E c\u00e1 estou eu, realizando mais um sonho\u201d, escreveu Clara Buarque nos stories do Instagram.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-55.png\" alt=\"\" class=\"wp-image-14723\" width=\"512\" height=\"307\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-55.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-55-300x180.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-55-768x461.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-55-696x417.png 696w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/image-55-700x420.png 700w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><figcaption>Foto: Reprodu\u00e7\u00e3o \/ Redes sociais<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Bia \u00e9 uma estudante de biologia que j\u00e1 teve passagem por outras \u00e1reas e tem muita intimidade com arquivos e com pesquisa, tanto que est\u00e1 acostumada a pegar uns trabalhos extras. Ela ser\u00e1 escolhida por Monteiro (Ailton Gra\u00e7a) para ajudar o professor Dante (Marcos Caruso) e Sara (Isabelle Nassar) na busca por D\u00e9bora.<\/p>\n\n\n\n<p>Vale lembrar que al\u00e9m de ser filha de um dos maiores m\u00fasicos da Bahia, Clara \u00e9 neta de Marieta Severo e Chico Buarque. Ela tamb\u00e9m poder\u00e1 ser vista na continua\u00e7\u00e3o do filme \u2018\u00d3 pa\u00ed \u00f3\u2019, que ser\u00e1 lan\u00e7ado nos cinemas logo em breve. <\/p>\n\n\n\n<p class=\"has-text-align-right\">*iBahia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Filha de Carlinhos Brown, Clara Buarque, 24 anos, ir\u00e1 estrear na novela \u2018Travessia\u2019 ainda nesta semana. A personagem da artista se chama \u201cBia\u201d e chega para movimentar a trama em buscas de respostas pelo sumi\u00e7o de D\u00e9bora (Grazi Massafera). \u201cBia chega essa semana em \u2018Travessia\u2019. Sempre soube que a hora certa de estar aqui ia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14724,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-14716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/14716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=14716"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/14716\/revisions"}],"predecessor-version":[{"id":14725,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/14716\/revisions\/14725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/14724"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=14716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=14716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=14716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}