{"id":14728,"date":"2022-12-20T15:45:45","date_gmt":"2022-12-20T18:45:45","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=14728"},"modified":"2022-12-20T15:45:48","modified_gmt":"2022-12-20T18:45:48","slug":"elon-musk-se-manifesta-apos-usuarios-votarem-para-ele-deixar-o-twitter","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2022\/12\/20\/elon-musk-se-manifesta-apos-usuarios-votarem-para-ele-deixar-o-twitter\/","title":{"rendered":"Elon Musk se manifesta ap\u00f3s usu\u00e1rios votarem para ele deixar o Twitter"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"338\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/Elon.jpg\" alt=\"\" class=\"wp-image-14729\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/Elon.jpg 500w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/Elon-300x203.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div>\n\n\n<p>Elon Musk fez uma enquete no Twitter questionando os usu\u00e1rios se ele deveria ou n\u00e3o deixar o cargo de CEO da rede social. Por\u00e9m, o tiro parece ter acabado saindo pela culatra e o resultado n\u00e3o agradou muito o bilion\u00e1rio.<\/p>\n\n\n\n<p>A vota\u00e7\u00e3o recebeu mais de 17,5 milh\u00f5es de votos e 57,5% dos usu\u00e1rios pediram que Musk deixe o cargo de chefe do Twitter, enquanto 42,5% acreditam que ele deve continuar comandando a rede social.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p lang=\"en\" dir=\"ltr\">Should I step down as head of Twitter? I will abide by the results of this poll.<\/p>&mdash; Elon Musk (@elonmusk) <a href=\"https:\/\/twitter.com\/elonmusk\/status\/1604617643973124097?ref_src=twsrc%5Etfw\">December 18, 2022<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p>No entanto, parece que Musk n\u00e3o ficou muito empolgado com o resultado da enquete. Ap\u00f3s um per\u00edodo de sil\u00eancio, o empres\u00e1rio respondeu com \u201cInteressante\u201d \u00e0 uma publica\u00e7\u00e3o que apontava que os resultados da pesquisa foram distorcidos por perfis falsos.<\/p>\n\n\n\n<p>Outro tweet dizia que \u201cos assinantes da Blue devem ser os \u00fanicos que podem votar em pesquisas relacionadas a pol\u00edticas\u201d. Elon Musk parece ter concordado com a recomenda\u00e7\u00e3o e afirmou que o Twitter colocar\u00e1 essa mudan\u00e7a em pr\u00e1tica.<\/p>\n\n\n\n<p>No \u00faltimo final de semana, Elon Musk havia decidido que usu\u00e1rios n\u00e3o poderiam mais compartilhar links de outras redes sociais no Twitter. Ap\u00f3s a rea\u00e7\u00e3o negativa dos usu\u00e1rios, o bilion\u00e1rio desistiu da mudan\u00e7a e disse que todas as decis\u00f5es importantes sobre as diretrizes ser\u00e3o decididas pelos pr\u00f3prios usu\u00e1rios da plataforma.<\/p>\n\n\n\n<p>O perfil do Twitter Safety lan\u00e7ou uma enquete questionando os usu\u00e1rios sobre a poss\u00edvel mudan\u00e7a. \u201cDevemos ter uma pol\u00edtica que impe\u00e7a a cria\u00e7\u00e3o ou o uso de contas existentes com o objetivo principal de anunciar outras plataformas de m\u00eddia social?\u201d, dizia a mensagem. O resultado da enquete acabou sendo negativo, como j\u00e1 se esperava.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Olhar Digital<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elon Musk fez uma enquete no Twitter questionando os usu\u00e1rios se ele deveria ou n\u00e3o deixar o cargo de CEO da rede social. Por\u00e9m, o tiro parece ter acabado saindo pela culatra e o resultado n\u00e3o agradou muito o bilion\u00e1rio. A vota\u00e7\u00e3o recebeu mais de 17,5 milh\u00f5es de votos e 57,5% dos usu\u00e1rios pediram que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14729,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-14728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/14728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=14728"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/14728\/revisions"}],"predecessor-version":[{"id":14730,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/14728\/revisions\/14730"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/14729"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=14728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=14728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=14728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}