{"id":20600,"date":"2023-10-23T15:09:33","date_gmt":"2023-10-23T18:09:33","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=20600"},"modified":"2023-10-23T15:09:34","modified_gmt":"2023-10-23T18:09:34","slug":"lula-diz-que-salario-minimo-precisa-aumentar-todo-ano","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2023\/10\/23\/lula-diz-que-salario-minimo-precisa-aumentar-todo-ano\/","title":{"rendered":"Lula diz que sal\u00e1rio m\u00ednimo precisa aumentar todo ano"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2023\/10\/image-96.png\" alt=\"\" class=\"wp-image-20603\" width=\"450\" height=\"308\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2023\/10\/image-96.png 900w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2023\/10\/image-96-300x205.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2023\/10\/image-96-768x525.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2023\/10\/image-96-218x150.png 218w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2023\/10\/image-96-696x476.png 696w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2023\/10\/image-96-615x420.png 615w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><figcaption>Foto: Ricardo Stuckert\/PR\/Divulga\u00e7\u00e3o\/Arquivo<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O presidente Lula (PT) disse, nesta segunda-feira (23), que o sal\u00e1rio m\u00ednimo precisa aumentar todo ano, acima da infla\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u201cEu acho que a meninada tem que aprender uma profiss\u00e3o. Por conta de uma profiss\u00e3o, eu fui o primeiro de oito filhos da minha m\u00e3e a ter uma casa pr\u00f3pria, a ter um carro, uma televis\u00e3o. Porque a gente foge do sal\u00e1rio m\u00ednimo\u201d, disse.<\/p>\n\n\n\n<p>\u201cPor isso, precisamos aumentar o sal\u00e1rio m\u00ednimo todo ano. \u00c9 por isso que a gente n\u00e3o pode [ficar] dando apenas a infla\u00e7\u00e3o. A infla\u00e7\u00e3o n\u00e3o \u00e9 aumento, \u00e9 apenas reposi\u00e7\u00e3o daquilo que comeu do nosso sal\u00e1rio\u201d, completou.<\/p>\n\n\n\n<p>O presidente Lula (PT) disse, nesta segunda-feira (23), que o sal\u00e1rio m\u00ednimo precisa aumentar todo ano, acima da infla\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u201cEu acho que a meninada tem que aprender uma profiss\u00e3o. Por conta de uma profiss\u00e3o, eu fui o primeiro de oito filhos da minha m\u00e3e a ter uma casa pr\u00f3pria, a ter um carro, uma televis\u00e3o. Porque a gente foge do sal\u00e1rio m\u00ednimo\u201d, disse.<\/p>\n\n\n\n<p>\u201cPor isso, precisamos aumentar o sal\u00e1rio m\u00ednimo todo ano. \u00c9 por isso que a gente n\u00e3o pode [ficar] dando apenas a infla\u00e7\u00e3o. A infla\u00e7\u00e3o n\u00e3o \u00e9 aumento, \u00e9 apenas reposi\u00e7\u00e3o daquilo que comeu do nosso sal\u00e1rio\u201d, completou.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Pol\u00edtica Livre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Lula (PT) disse, nesta segunda-feira (23), que o sal\u00e1rio m\u00ednimo precisa aumentar todo ano, acima da infla\u00e7\u00e3o. \u201cEu acho que a meninada tem que aprender uma profiss\u00e3o. Por conta de uma profiss\u00e3o, eu fui o primeiro de oito filhos da minha m\u00e3e a ter uma casa pr\u00f3pria, a ter um carro, uma televis\u00e3o. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":20603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-20600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/20600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=20600"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/20600\/revisions"}],"predecessor-version":[{"id":20604,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/20600\/revisions\/20604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/20603"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=20600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=20600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=20600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}