{"id":23386,"date":"2024-04-08T12:11:00","date_gmt":"2024-04-08T15:11:00","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=23386"},"modified":"2024-04-08T12:11:00","modified_gmt":"2024-04-08T15:11:00","slug":"de-autoria-do-deputado-alex-da-piata-governador-sanciona-pl-que-garante-sanitarios-quimicos-para-pessoas-com-necessidades-especiais-em-todos-os-eventos-publicos-na-bahia","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/04\/08\/de-autoria-do-deputado-alex-da-piata-governador-sanciona-pl-que-garante-sanitarios-quimicos-para-pessoas-com-necessidades-especiais-em-todos-os-eventos-publicos-na-bahia\/","title":{"rendered":"De autoria do deputado Alex da Piat\u00e3, governador sanciona PL que garante sanit\u00e1rios qu\u00edmicos para pessoas com necessidades especiais em todos os eventos p\u00fablicos na Bahia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"969\" height=\"570\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-23.png\" alt=\"\" class=\"wp-image-23387\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-23.png 969w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-23-300x176.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-23-768x452.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-23-357x210.png 357w\" sizes=\"auto, (max-width: 969px) 100vw, 969px\" \/><\/figure>\n<\/div>\n\n\n<p>O deputado estadual Alex da Piat\u00e3 (PSD) apresentou na Assembleia Legislativa da Bahia (ALBA) e teve aprova\u00e7\u00e3o dos demais colegas parlamentares, o Projeto de Lei 21.698\/2015 que garante sanit\u00e1rios qu\u00edmicos adaptados \u00e1s pessoas portadoras de necessidades especiais.<\/p>\n\n\n\n<p>Os sanit\u00e1rios colocados em eventos atualmente atendem pessoas com as condi\u00e7\u00f5es f\u00edsicas normais do sexo masculino e feminino. O projeto aprovado na Alba estava aguardando a san\u00e7\u00e3o do Governo do Estado e o&nbsp; governador Jer\u00f4nimo Rodrigues sancionou na manh\u00e3 deste s\u00e1bado, 6, em um grande ato no Centro Estadual de Preven\u00e7\u00e3o e Reabilita\u00e7\u00e3o da Pessoa com Defici\u00eancia (CEPRED), durante o an\u00fancio do pacote de a\u00e7\u00f5es para pessoas com defici\u00eancia e estabelece novo marco para a inclus\u00e3o social na Bahia.<\/p>\n\n\n\n<p>Somente na Sa\u00fade, o Governo do Estado est\u00e1 investindo um total de R$ 123 milh\u00f5es para uma s\u00e9rie de a\u00e7\u00f5es, entre elas a abertura imediata de 400 novas vagas, a partir da amplia\u00e7\u00e3o de estruturas pr\u00e9-existentes na capital baiana, voltadas ao atendimento de pessoas com autismo. As vagas ser\u00e3o abertas no Centro Estadual de Preven\u00e7\u00e3o e Reabilita\u00e7\u00e3o da Pessoa com Defici\u00eancia (Cepred) e no Centro Especializado em Reabilita\u00e7\u00e3o das Obras Sociais Irm\u00e3 Dulce (Osid), com um investimento superior a R$ 5,4 milh\u00f5es.<\/p>\n\n\n\n<p>O deputado estadual Alex da Piat\u00e3 comemorou em dobro tudo que aconteceu neste s\u00e1bado. Os investimentos que ser\u00e3o realizados na sa\u00fade, j\u00e1 que ele tem a miss\u00e3o de presidir o Colegiado da Sa\u00fade e Saneamento na ALBA e a san\u00e7\u00e3o do PL que visa contribuir com as pessoas com limita\u00e7\u00f5es fisicas para terem acesso aos banheiros quimicos exclusivos.<\/p>\n\n\n\n<p>\u201cApresentamos esse Projeto que visa garantir que os portadores de necessidades especiais encontrem condi\u00e7\u00f5es adequadas na utiliza\u00e7\u00e3o de sanit\u00e1rios a quando da realiza\u00e7\u00e3o de eventos socioculturais, esportivos, religiosos e assemelhados, particularmente, quando esses eventos necessitam da instala\u00e7\u00e3o de sanit\u00e1rios qu\u00edmicos. Devemos, incansavelmente, buscar condi\u00e7\u00f5es que reduzam as in\u00fameras dificuldades impostas aos portadores de necessidades especiais, objetivando a t\u00e3o propalada inclus\u00e3o social dos mesmos, justificou Alex da Piat\u00e3.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"787\" height=\"558\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-25.png\" alt=\"\" class=\"wp-image-23388\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-25.png 787w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-25-300x213.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/04\/image-25-768x545.png 768w\" sizes=\"auto, (max-width: 787px) 100vw, 787px\" \/><\/figure>\n<\/div>\n\n\n<p>Jer\u00f4nimo sancionou, ainda, duas leis estaduais. A primeira estabelece prazo de validade indeterminado para laudos e per\u00edcias m\u00e9dicas que atestam o Transtorno do Espectro Autista (TEA) e a S\u00edndrome de Down, no \u00e2mbito do Estado da Bahia. A segunda assegura meia-entrada em eventos culturais, art\u00edsticos e desportivos realizados na Bahia, \u00e0s pessoas com autismo e seu acompanhante.<\/p>\n\n\n\n<p>Durante o evento, o governador anunciou tamb\u00e9m a concess\u00e3o do Passe Livre Intermunicipal e a inclus\u00e3o do atendimento em L\u00edngua Brasileira de Sinais (Libras), em sete Unidades de Servi\u00e7os Integrados do SAC (USIs\/SAC), em Salvador e munic\u00edpios; emiss\u00e3o da Carteira de Identifica\u00e7\u00e3o da Pessoa com Autismo; e a assinatura de Termos de Parceria com as Organiza\u00e7\u00f5es da Sociedade Civil (OSCs), contempladas pelo Edital 01\/2024. As OSCs v\u00e3o dispor de quase R$ 1 milh\u00e3o para projetos voltados a pessoas com defici\u00eancia.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Calila Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Alex da Piat\u00e3 (PSD) apresentou na Assembleia Legislativa da Bahia (ALBA) e teve aprova\u00e7\u00e3o dos demais colegas parlamentares, o Projeto de Lei 21.698\/2015 que garante sanit\u00e1rios qu\u00edmicos adaptados \u00e1s pessoas portadoras de necessidades especiais. Os sanit\u00e1rios colocados em eventos atualmente atendem pessoas com as condi\u00e7\u00f5es f\u00edsicas normais do sexo masculino e feminino. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23387,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-23386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=23386"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23386\/revisions"}],"predecessor-version":[{"id":23390,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23386\/revisions\/23390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/23387"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=23386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=23386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=23386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}