{"id":23807,"date":"2024-05-06T06:58:23","date_gmt":"2024-05-06T09:58:23","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=23807"},"modified":"2024-05-10T12:57:13","modified_gmt":"2024-05-10T15:57:13","slug":"equipamento-de-som-e-apreendido-em-retirolandia-apos-policia-ser-acionada","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/05\/06\/equipamento-de-som-e-apreendido-em-retirolandia-apos-policia-ser-acionada\/","title":{"rendered":"Equipamento de som \u00e9 apreendido em Retirol\u00e2ndia ap\u00f3s pol\u00edcia ser acionada"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"618\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/Imagem-do-WhatsApp-de-2024-05-05-as-13.29.51_818a7adf-1024x618.jpg\" alt=\"\" class=\"wp-image-23808\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/Imagem-do-WhatsApp-de-2024-05-05-as-13.29.51_818a7adf-1024x618.jpg 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/Imagem-do-WhatsApp-de-2024-05-05-as-13.29.51_818a7adf-300x181.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/Imagem-do-WhatsApp-de-2024-05-05-as-13.29.51_818a7adf-768x464.jpg 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/Imagem-do-WhatsApp-de-2024-05-05-as-13.29.51_818a7adf.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Por volta das 04h17 deste domingo (5), a pol\u00edcia militar de Retirol\u00e2ndia foi acionada para averiguar uma situa\u00e7\u00e3o de perturba\u00e7\u00e3o do sossego p\u00fablico, ao chegar na localidade conhecida como Fazenda Cascalheira ou Lagoa Cerena, a denuncia foi confirmada.<\/p>\n\n\n\n<p>O Informe Bahia apurou que, ao se aproximar do local cerca de 100 metros j\u00e1 era poss\u00edvel ouvir o som automotivo em alt\u00edssimo volume e uma mulher de iniciais E.O. da S., bebendo ao lado do aparelho sonoro o qual estava ligado e acoplado ao ve\u00edculo VW\/GOL 1.0. Diante do exposto, fizemos a apreens\u00e3o do som e ve\u00edculo, onde ser\u00e1 apresentado a delegacia posteriormente via of\u00edcio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 04h17 deste domingo (5), a pol\u00edcia militar de Retirol\u00e2ndia foi acionada para averiguar uma situa\u00e7\u00e3o de perturba\u00e7\u00e3o do sossego p\u00fablico, ao chegar na localidade conhecida como Fazenda Cascalheira ou Lagoa Cerena, a denuncia foi confirmada. O Informe Bahia apurou que, ao se aproximar do local cerca de 100 metros j\u00e1 era poss\u00edvel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23808,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-23807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=23807"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23807\/revisions"}],"predecessor-version":[{"id":23809,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23807\/revisions\/23809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/23808"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=23807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=23807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=23807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}