{"id":23837,"date":"2024-05-07T14:52:53","date_gmt":"2024-05-07T17:52:53","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=23837"},"modified":"2024-05-07T14:52:54","modified_gmt":"2024-05-07T17:52:54","slug":"a-nossa-missao-e-resolver-os-problemas-do-nosso-povo-destaca-governador-durante-entrega-de-obras-de-mobilidade-esporte-e-equipamentos-de-saude-em-alcobaca","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/05\/07\/a-nossa-missao-e-resolver-os-problemas-do-nosso-povo-destaca-governador-durante-entrega-de-obras-de-mobilidade-esporte-e-equipamentos-de-saude-em-alcobaca\/","title":{"rendered":"\u201cA nossa miss\u00e3o \u00e9 resolver os problemas do nosso povo\u201d, destaca governador durante entrega de obras de mobilidade, esporte e equipamentos de sa\u00fade em Alcoba\u00e7a"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-22-1024x683.png\" alt=\"\" class=\"wp-image-23838\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-22-1024x683.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-22-300x200.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-22-768x512.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-22-1536x1024.png 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-22.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>A entrega da requalifica\u00e7\u00e3o do est\u00e1dio municipal de Alcoba\u00e7a, nesta ter\u00e7a-feira (7), marcou o in\u00edcio de uma s\u00e9rie de obras realizadas pelo Governo do Estado, no extremo sul baiano. A reforma, que teve um investimento de R$ 1,1 milh\u00e3o de reais, se somou a um pacote de a\u00e7\u00f5es no munic\u00edpio, que inclu\u00edram a aquisi\u00e7\u00e3o de equipamentos de sa\u00fade, pavimenta\u00e7\u00f5es, sistema de abastecimento de \u00e1gua, internet gratuita e uma van escolar. At\u00e9 a pr\u00f3xima sexta-feira (10), Caravelas, Vereda, Lajed\u00e3o, Ibirapu\u00e3 e Teixeira de Freitas tamb\u00e9m ser\u00e3o contempladas.&nbsp;<\/p>\n\n\n\n<p>\u201cA nossa miss\u00e3o \u00e9 resolver os problemas do nosso povo. \u00c9 levar \u00e1gua pot\u00e1vel para as comunidades, servi\u00e7os de sa\u00fade, estradas. Estamos no caminho certo e tenho certeza de que vamos avan\u00e7ar ainda mais. Iniciei a agenda em Alcoba\u00e7a e vou ficar mais cinco dias no extremo sul, entregando diversas obras e vistoriando os munic\u00edpios para trazer ainda mais melhorias\u201d, destacou Jer\u00f4nimo Rodrigues.<\/p>\n\n\n\n<p>Para oferecer mais conforto e comodidade para atletas e torcidas apaixonadas por futebol, o Est\u00e1dio Municipal Francisco de Assis Castro, modernizado pela Secretaria do Trabalho, Emprego, Renda e Esporte (Setre), atrav\u00e9s da Superintend\u00eancia dos Desportos do Estado da Bahia ( Sudesb), conta agora com gramado natural, um novo sistema de drenagem das \u00e1guas fluviais, arquibancada recuperada, totem externo e um moderno sistema de ilumina\u00e7\u00e3o, com postes e refletores de alta efici\u00eancia energ\u00e9tica. \u201cS\u00f3 aqui no extremo sul, s\u00e3o mais de 50 milh\u00f5es de investimentos em equipamentos esportivos. Esse \u00e9 um dos motivos que fazem a Bahia se destacar nacionalmente com a proje\u00e7\u00e3o de atletas em todas as modalidades. M\u00e9rito tamb\u00e9m dos projetos de inclus\u00e3o social e de alto rendimento. \u00c9 esporte por toda parte\u201d, comentou o titular da Setre, Davidson Magalh\u00e3es.&nbsp;<\/p>\n\n\n\n<p>Um dos 180 alunos da escolinha de futebol de Alcoba\u00e7a, Jo\u00e3o Enzo Reis da Silva, 10 anos, contou como era o est\u00e1dio antes da reforma. \u201cEu nem jogava aqui, era um local muito feio. A grama n\u00e3o estava boa, n\u00e3o tinha vesti\u00e1rio. Precisava mesmo mudar e mudou. Agora est\u00e1 muito bonito e tenho muita vontade de treinar aqui. Sou zagueiro na escolinha e pretendo seguir carreira como jogador\u201d.&nbsp;<\/p>\n\n\n\n<p>Na sa\u00fade, o Hospital Municipal S\u00e3o Bernardo e quatro Unidades B\u00e1sicas de Sa\u00fade (UBS) dos distritos de Taquari, S\u00e3o Jos\u00e9 Volante, Caxang\u00e1 e Para\u00edso Verde ganharam refor\u00e7o com a entrega de equipamentos de sa\u00fade e quatro kits odontol\u00f3gicos, respectivamente, mais uma ambul\u00e2ncia.&nbsp;<\/p>\n\n\n\n<p>De acordo com a secret\u00e1ria da Sa\u00fade, Roberta Santana, a partir de uma vistoria nos equipamentos de sa\u00fade do munic\u00edpio, sentiu-se a necessidade de trazer essas melhorias. \u201cEstamos equipando o hospital com uma sala de estabiliza\u00e7\u00e3o, reposi\u00e7\u00e3o e a troca de todas as camas e um respirador. Foram R$ 490 mil s\u00f3 em equipamentos. Autorizamos aqui hoje tamb\u00e9m um conv\u00eanio para a constru\u00e7\u00e3o de uma UBS no distrito S\u00e3o Jos\u00e9, onde vamos ampliar a cobertura da aten\u00e7\u00e3o prim\u00e1ria aqui na regi\u00e3o\u201d, disse. &nbsp;<\/p>\n\n\n\n<p>Ainda foram dados por entregue, um novo sistema de abastecimento de \u00e1gua na localidade de Aparaj\u00fa, distante 30 km da sede, com 139 liga\u00e7\u00f5es domiciliares; uma van escolar para atender aos estudantes; um trator e a conex\u00e3o de internet gratuita na Pra\u00e7a da Caixa D&#8217;\u00e1gua, no centro da cidade.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A entrega da requalifica\u00e7\u00e3o do est\u00e1dio municipal de Alcoba\u00e7a, nesta ter\u00e7a-feira (7), marcou o in\u00edcio de uma s\u00e9rie de obras realizadas pelo Governo do Estado, no extremo sul baiano. A reforma, que teve um investimento de R$ 1,1 milh\u00e3o de reais, se somou a um pacote de a\u00e7\u00f5es no munic\u00edpio, que inclu\u00edram a aquisi\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23838,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-23837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=23837"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23837\/revisions"}],"predecessor-version":[{"id":23839,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23837\/revisions\/23839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/23838"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=23837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=23837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=23837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}