{"id":23911,"date":"2024-05-15T21:25:54","date_gmt":"2024-05-16T00:25:54","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=23911"},"modified":"2024-05-15T21:26:29","modified_gmt":"2024-05-16T00:26:29","slug":"wegovy-medicamento-irmao-do-ozempic-mantem-perda-de-peso-por-quatro-anos","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/05\/15\/wegovy-medicamento-irmao-do-ozempic-mantem-perda-de-peso-por-quatro-anos\/","title":{"rendered":"Wegovy, medicamento irm\u00e3o do Ozempic, mant\u00e9m perda de peso por quatro anos"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-44.png\" alt=\"\" class=\"wp-image-23920\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-44.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-44-300x200.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-44-768x512.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagem: KK Stock\/Shutterstock<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Pacientes que fizeram uso do medicamento Wegovy, da farmac\u00eautica dinamarquesa Novo Nordisk, mantiveram perda m\u00e9dia de peso de 10% ap\u00f3s quatro anos de tratamento. O rem\u00e9dio baseado na semaglutida, mesmo princ\u00edpio ativo do Ozempic, \u00e9 usado no tratamento da obesidade.<\/p>\n\n\n\n<p>A esperan\u00e7a da empresa \u00e9 usar os dados para convencer seguradoras a cobrir o custo do medicamento que, apesar de caro, \u00e9 eficaz.<\/p>\n\n\n\n<p><strong>Wegovy para perda de peso<\/strong><\/p>\n\n\n\n<p>Dados do estudo a longo prazo da Novo Nordisk (que tamb\u00e9m \u00e9 dona do Ozempic) foram apresentados no Congresso Europeu sobre Obesidade em Veneza (It\u00e1lia), na \u00faltima ter\u00e7a-feira (14).<\/p>\n\n\n\n<p>De acordo com a ag\u00eancia de not\u00edcias&nbsp;<em><a href=\"https:\/\/www.reuters.com\/business\/healthcare-pharmaceuticals\/wegovy-weight-loss-sustained-four-years-trial-novo-nordisk-says-2024-05-13\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Reuters<\/strong><\/a><\/em>, Martin Holst Lange, chefe de desenvolvimento da empresa, em entrevista, afirmou que este \u00e9 o estudo mais longo conduzido at\u00e9 agora sobre os benef\u00edcios da semaglutida na perda de peso.<\/p>\n\n\n\n<p><em>\u201cVemos que, uma vez acumulada a maior parte da perda de peso, voc\u00ea n\u00e3o retrocede e n\u00e3o come\u00e7a a aumentar de peso se continuar tomando o medicamento.\u201d<\/em><\/p>\n\n\n\n<p><strong><em>Martin Holst Lange, chefe de desenvolvimento da Novo Nordisk, em entrevista \u00e0&nbsp;Reuters<\/em><\/strong><\/p>\n\n\n\n<p>O Wegovy e o Ozempic s\u00e3o medicamentos direcionados ao tratamento de obesidade e diabetes (respectivamente), mas foram associados \u00e0 perda de peso.<\/p>\n\n\n\n<p>A efic\u00e1cia do Wegovy a longo prazo havia sido questionada e o estudo pretende convencer governo e seguradoras que vale a pena o investimento. O medicamento custa entre US$ 200 a quase US$ 2 mil (entre R$ 1 mil e R$ 10 mil) nos dez pa\u00edses em que est\u00e1 dispon\u00edvel.<\/p>\n\n\n\n<p><strong>Como o estudo foi feito<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O ensaio com Wegovy, batizado de Select, foi feito com 17.604 pacientes;<\/li>\n\n\n\n<li>No entanto, o teste n\u00e3o era voltado \u00e0 perda de peso e, sim, aos benef\u00edcios card\u00edacos em pacientes com sobrepeso ou obesidade que j\u00e1 tinham doen\u00e7as card\u00edacas pr\u00e9-existentes, mas n\u00e3o diabetes;<\/li>\n\n\n\n<li>Por isso, os participantes n\u00e3o tiveram de monitorar dietas e rotina de exerc\u00edcios;<\/li>\n\n\n\n<li>Do total, 17% parou de usar Wegovy devido a efeitos colaterais, principalmente n\u00e1usea;<\/li>\n\n\n\n<li>Dos que se mantiveram no estudo, a perda de peso m\u00e9dia foi de 10% ap\u00f3s 65 semanas de tratamento. A taxa foi sustentada ao longo de quatro anos;<\/li>\n\n\n\n<li>Benef\u00edcios card\u00edacos tamb\u00e9m foram constatados, como diminui\u00e7\u00e3o do risco de eventos cardiovasculares ou vasculares cerebrais em 20%.<\/li>\n<\/ul>\n\n\n\n<p>O Wegovy tem previs\u00e3o de chegar ao Brasil no segundo semestre deste ano.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Olhar Digital<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pacientes que fizeram uso do medicamento Wegovy, da farmac\u00eautica dinamarquesa Novo Nordisk, mantiveram perda m\u00e9dia de peso de 10% ap\u00f3s quatro anos de tratamento. O rem\u00e9dio baseado na semaglutida, mesmo princ\u00edpio ativo do Ozempic, \u00e9 usado no tratamento da obesidade. A esperan\u00e7a da empresa \u00e9 usar os dados para convencer seguradoras a cobrir o custo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23920,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-23911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=23911"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23911\/revisions"}],"predecessor-version":[{"id":23921,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23911\/revisions\/23921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/23920"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=23911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=23911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=23911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}