{"id":23932,"date":"2024-05-16T14:33:46","date_gmt":"2024-05-16T17:33:46","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=23932"},"modified":"2024-05-16T14:33:46","modified_gmt":"2024-05-16T17:33:46","slug":"morre-missinho-primeiro-vocalista-do-chiclete-com-banana","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/05\/16\/morre-missinho-primeiro-vocalista-do-chiclete-com-banana\/","title":{"rendered":"Morre Missinho, primeiro vocalista do Chiclete com Banana"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-48-1024x538.png\" alt=\"\" class=\"wp-image-23939\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-48-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-48-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-48-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-48.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O m\u00fasico Missinho, primeiro vocalista da banda Chiclete com Banana, teve a morte confirmada nesta quinta-feira (15) aos 64 anos. O artista estava internado no Hospital Roberto Santos, em Salvador, e faleceu ap\u00f3s dar entrada no hospital com uma crise renal. O artista teve fal\u00eancia m\u00faltipla dos \u00f3rg\u00e3os.<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es obtidas pelo Bahia Not\u00edcias, o sepultamento do artista ser\u00e1 na sexta-feira (17).<\/p>\n\n\n\n<p>O artista, um dos fundadores do Chiclete com Banana na \u00e9poca que o grupo ainda se chamava Scorpions, foi respons\u00e1vel por sucessos como &#8216;Mist\u00e9rio das Estrelas&#8217;, e deu voz a m\u00fasica &#8216;Beijo Cigano&#8217;.<\/p>\n\n\n\n<p>Em entrevista ao Bargun\u00e7a Podcast, o ex-baterista do Chiclete, Rey, relembrou a sa\u00edda de Missinho do grupo em 1986. O m\u00fasico deixou a banda de forma repentina no meio de uma apresenta\u00e7\u00e3o da Micareta de Feira. Segundo Rey, o cantor se irritou com uma situa\u00e7\u00e3o e abandonou o show:<\/p>\n\n\n\n<p>&#8220;N\u00f3s est\u00e1vamos tocando na Micareta de Feira, estavamos cantando com o bloco Nacionais, e o bloco vinha e tava tudo muito engarrafado l\u00e1 na frente. E como ja tinha muito tempo do bloco, ele pediu para a gente entrar em uma rua para fazer o retorno, quando a gente fez, ficou pouco tempo. A\u00ed Edinho pediu para a gente dar outra volta, s\u00f3 que terminou come\u00e7ando a ficar de noite. A gente j\u00e1 tinha mais de 4 horas tocando, ningu\u00e9m queria ir mais, mas ele queria. [&#8230;] Ele n\u00e3o era um cara mal educado, mas no dia zangou. Deu aquele xilique assim. N\u00e3o sei se foi Bell, ou Vadinho, e falou &#8220;nunca mais eu entro na sua casa&#8221;, e a\u00ed Bell e Vadinho, n\u00e3o lembro quem foi disse &#8216;rapaz, pode ir embora&#8217;.&#8221;<\/p>\n\n\n\n<p>Em entrevistas, o artista afirmou que deixou o grupo por um desgaste natural e que precisava respirar novos ares. Ao deixar a banda, Missinho se dedicou a projetos pessoais e chegou a montar um est\u00fadio. Depois que saiu do grupo, o artista n\u00e3o manteve rela\u00e7\u00e3o com os colegas de banda.<\/p>\n\n\n\n<p>O cantor chegou a fazer shows na Bahia entre 2010 e 2018. Um dos \u00faltimos registros de uma apresenta\u00e7\u00e3o de Missinho na m\u00eddia foi de 2017, em Petrolina, Pernambuco, quando se apresentou em um evento beneficente que arrecadou fundos para constru\u00e7\u00e3o do Hospital do C\u00e2ncer na cidade.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O m\u00fasico Missinho, primeiro vocalista da banda Chiclete com Banana, teve a morte confirmada nesta quinta-feira (15) aos 64 anos. O artista estava internado no Hospital Roberto Santos, em Salvador, e faleceu ap\u00f3s dar entrada no hospital com uma crise renal. O artista teve fal\u00eancia m\u00faltipla dos \u00f3rg\u00e3os. De acordo com informa\u00e7\u00f5es obtidas pelo Bahia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23939,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-23932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=23932"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23932\/revisions"}],"predecessor-version":[{"id":23940,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/23932\/revisions\/23940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/23939"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=23932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=23932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=23932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}