{"id":24176,"date":"2024-05-28T09:44:25","date_gmt":"2024-05-28T12:44:25","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24176"},"modified":"2024-06-03T07:04:20","modified_gmt":"2024-06-03T10:04:20","slug":"criadores-vendiam-cobras-pela-internet-e-enviavam-pelos-correios-em-serrinha","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/05\/28\/criadores-vendiam-cobras-pela-internet-e-enviavam-pelos-correios-em-serrinha\/","title":{"rendered":"Criadores vendiam cobras pela internet e enviavam pelos Correios em Serrinha"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-124.png\" alt=\"\" class=\"wp-image-24177\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-124.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-124-300x225.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-124-86x64.png 86w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p>A Pol\u00edcia Federal cumpriu dois mandados de busca e apreens\u00e3o contra uma rede criminosa de criadores clandestinos de animais, nesta ter\u00e7a-feira (28), em Serrinha. Durante a opera\u00e7\u00e3o, foram apreendidos animais que eram criados pelos suspeito para venda, com envio, de forma fraudulenta, pelos Correios. A investiga\u00e7\u00e3o teve in\u00edcio ap\u00f3s serem apreendidos diversos r\u00e9pteis na Ag\u00eancia Central dos Correios, em Sim\u00f5es Filho, na Regi\u00e3o Metropolitana de Salvador (RMS).\u00a0<\/p>\n\n\n\n<p>A Pol\u00edcia Federal informou que, no decorrer da apura\u00e7\u00e3o, foi constatada a exist\u00eancia de uma rede criminosa formada por criadores clandestinos de animais, da fauna silvestre e ex\u00f3tica, que comercializava as esp\u00e9cies atrav\u00e9s da internet e utilizava o servi\u00e7o postal para realiza\u00e7\u00e3o da sua entrega. Registra-se que o tr\u00e1fico de animais, silvestres ou ex\u00f3ticos, causa enorme preju\u00edzo \u00e0 fauna brasileira, criando graves desequil\u00edbrios ambientais, inclusive em ecossistemas protegidos, podendo expor determinadas esp\u00e9cies ao risco de extin\u00e7\u00e3o.<\/p>\n\n\n\n<p>Alguns r\u00e9pteis ex\u00f3ticos comercializados pelos investigados, caso soltos, al\u00e9m de amea\u00e7ar \u00e0s esp\u00e9cies nativas da regi\u00e3o, podem transmitir parasitas nocivos e desencadear o surgimento de novas doen\u00e7as no pa\u00eds, segundo a PF. As cobras do g\u00eanero p\u00edton, por exemplo, sendo natural da \u00c1sia, podem dizimar a fauna local, por viverem 30 anos, n\u00e3o terem predadores no Brasil e serem capazes de reproduzir-se por si s\u00f3.<\/p>\n\n\n\n<p>A opera\u00e7\u00e3o, denominada Ojuara, contou com a participa\u00e7\u00e3o da Companhia Independente de Pol\u00edcia de Prote\u00e7\u00e3o Ambiental (Coppa) e do Centro de Triagem de Animais Silvestres (Cetas), que \u00e9 vinculado ao Instituto do Meio Ambiente e Recursos H\u00eddricos (Inema). Os mandados foram expedidos pela 17\u00aa Vara Federal da Se\u00e7\u00e3o Judici\u00e1ria da Bahia, tendo os animais aprendidos sido encaminhados ao Centro de Triagem de Animais Silvestres do Inema, para reabilita\u00e7\u00e3o e, quando poss\u00edvel, devolu\u00e7\u00e3o a natureza.&nbsp;<\/p>\n\n\n\n<p>Os investigados pela comercializa\u00e7\u00e3o dos animais ir\u00e3o responder pelos crimes de tr\u00e1fico e maus-tratos de animais; introdu\u00e7\u00e3o de esp\u00e9cime animal no pa\u00eds, sem autoriza\u00e7\u00e3o; recepta\u00e7\u00e3o e falsidade ideol\u00f3gica. As penas, somadas, podem chegar a 12 anos.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Fonte: Portal de Cleriston Silva <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Federal cumpriu dois mandados de busca e apreens\u00e3o contra uma rede criminosa de criadores clandestinos de animais, nesta ter\u00e7a-feira (28), em Serrinha. Durante a opera\u00e7\u00e3o, foram apreendidos animais que eram criados pelos suspeito para venda, com envio, de forma fraudulenta, pelos Correios. A investiga\u00e7\u00e3o teve in\u00edcio ap\u00f3s serem apreendidos diversos r\u00e9pteis na Ag\u00eancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24177,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-24176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24176"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24176\/revisions"}],"predecessor-version":[{"id":24178,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24176\/revisions\/24178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24177"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}