{"id":24187,"date":"2024-05-28T17:33:57","date_gmt":"2024-05-28T20:33:57","guid":{"rendered":"http:\/\/informebahia.com\/site\/?p=24187"},"modified":"2024-05-28T17:33:57","modified_gmt":"2024-05-28T20:33:57","slug":"psd-fecha-questao-e-dara-quorum-para-votacao-de-emprestimo-de-r-2-bilhoes-e-reajuste-de-servidores-estaduais","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/05\/28\/psd-fecha-questao-e-dara-quorum-para-votacao-de-emprestimo-de-r-2-bilhoes-e-reajuste-de-servidores-estaduais\/","title":{"rendered":"PSD fecha quest\u00e3o e dar\u00e1 qu\u00f3rum para vota\u00e7\u00e3o de empr\u00e9stimo de R$ 2 bilh\u00f5es e reajuste de servidores estaduais"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"615\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-127.png\" alt=\"\" class=\"wp-image-24192\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-127.png 900w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-127-300x205.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/05\/image-127-768x525.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<\/div>\n\n\n<p>A bancada do PSD na Assembleia Legislativa da Bahia (AL-BA) fechou quest\u00e3o para garantir qu\u00f3rum e votar favoravelmente aos projetos do Executivo que est\u00e3o na pauta de vota\u00e7\u00e3o desta ter\u00e7a-feira (28). Entre eles, o empr\u00e9stimo de R$ 2 bilh\u00f5es e o reajuste de 4% para os servidores p\u00fablicos estaduais.<\/p>\n\n\n\n<p>A decis\u00e3o foi tomada ap\u00f3s duas reuni\u00f5es realizadas nesta segunda (27), uma com o chefe de gabinete do governador Jer\u00f4nimo Rodrigues (PT), Adolpho Loyola, e outra com o presidente estadual do PSD, senador Otto Alencar.<\/p>\n\n\n\n<p>Segundo apurou o Pol\u00edtica Livre, na reuni\u00e3o com Adolpho Loyola os deputados cobraram a resolu\u00e7\u00e3o de pend\u00eancias que se arrastam h\u00e1 algum tempo, como a nomea\u00e7\u00e3o de cargos em terceirizadas, o andamento de obras prometidas no interior e que est\u00e3o com o andamento comprometido, espa\u00e7o na agenda do governador para receber prefeitos e, em outros casos, agendar a visita de Jer\u00f4nimo ao munic\u00edpio.<\/p>\n\n\n\n<p>O encontro com Otto Alencar \u00e9 rotineiro, seria nesta ter\u00e7a, mas foi antecipado para ontem por causa da agenda de alguns parlamentares.<\/p>\n\n\n\n<p>\u201cT\u00e1 tudo ajustado. Vamos votar o que estiver em pauta. Como eu disse, casamento tem crise, mas a gente conversa e resolve\u201d, afirmou Ivana Bastos, l\u00edder do PSD na AL-BA, em conversa com o Pol\u00edtica Livre.<\/p>\n\n\n\n<p>Segundo ela, apenas Angelo Coronel Filho n\u00e3o estar\u00e1 na sess\u00e3o desta ter\u00e7a porque viajou para S\u00e3o Paulo. Alex da Piat\u00e3 fica na Casa at\u00e9 \u00e0s 16h, mas depois viajar\u00e1 para um compromisso tamb\u00e9m em S\u00e3o Paulo.<\/p>\n\n\n\n<p>Ivana Bastos confirmou tamb\u00e9m que haver\u00e1 um almo\u00e7o entre os l\u00edderes partid\u00e1rios da base convocado pelo l\u00edder do governo, Rosemberg Pinto (PT), para fazer ajustes antes da vota\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Pol\u00edtica Livre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A bancada do PSD na Assembleia Legislativa da Bahia (AL-BA) fechou quest\u00e3o para garantir qu\u00f3rum e votar favoravelmente aos projetos do Executivo que est\u00e3o na pauta de vota\u00e7\u00e3o desta ter\u00e7a-feira (28). Entre eles, o empr\u00e9stimo de R$ 2 bilh\u00f5es e o reajuste de 4% para os servidores p\u00fablicos estaduais. A decis\u00e3o foi tomada ap\u00f3s duas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24192,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-24187","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24187"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24187\/revisions"}],"predecessor-version":[{"id":24193,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24187\/revisions\/24193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24192"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}