{"id":24335,"date":"2024-06-10T09:18:11","date_gmt":"2024-06-10T12:18:11","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24335"},"modified":"2024-06-11T12:46:04","modified_gmt":"2024-06-11T15:46:04","slug":"cachorro-provoca-acidente-de-moto-no-centro-da-cidade-de-conceicao-do-coite","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/06\/10\/cachorro-provoca-acidente-de-moto-no-centro-da-cidade-de-conceicao-do-coite\/","title":{"rendered":"Cachorro provoca acidente de moto no centro da cidade de Concei\u00e7\u00e3o do Coit\u00e9"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/Imagem-do-WhatsApp-de-2024-06-10-as-08.53.57_e31ad11c-1024x613.jpg\" alt=\"\" class=\"wp-image-24336\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/Imagem-do-WhatsApp-de-2024-06-10-as-08.53.57_e31ad11c-1024x613.jpg 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/Imagem-do-WhatsApp-de-2024-06-10-as-08.53.57_e31ad11c-300x180.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/Imagem-do-WhatsApp-de-2024-06-10-as-08.53.57_e31ad11c-768x460.jpg 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/Imagem-do-WhatsApp-de-2024-06-10-as-08.53.57_e31ad11c-1536x919.jpg 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/Imagem-do-WhatsApp-de-2024-06-10-as-08.53.57_e31ad11c-2048x1226.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto; Divulga\u00e7\u00e3o \u00c1guia Resgate<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Por volta das 7h54 desta segunda-feira (10), a equipe de socorristas \u00c1guia Resgate foi acionada para socorrer uma pessoa v\u00edtima de acidente de moto provocado por um cachorro.<\/p>\n\n\n\n<p>Segundo o socorrista Gildo Carneiro, a mulher foi identificada como Danuzia, no bairro Cidade Jardim, em Concei\u00e7\u00e3o do Coit\u00e9, estava conduzindo quando o animal atravessou na frente da moto e foi atropelado, a mesma perdeu o controle do ve\u00edculo e caiu. O acidente aconteceu pr\u00f3ximo da Igreja Assembleia de Deus e o Atacad\u00e3o Casa de Arroz no centro da cidade.  \u00a0<\/p>\n\n\n\n<p>Compareceram no local o \u00c1guia Resgate, Samu e a Guarda Municipal, a v\u00edtima foi encaminhada para o hospital na ambul\u00e2ncia da Samu.&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-right\">Por Informe Bahia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 7h54 desta segunda-feira (10), a equipe de socorristas \u00c1guia Resgate foi acionada para socorrer uma pessoa v\u00edtima de acidente de moto provocado por um cachorro. Segundo o socorrista Gildo Carneiro, a mulher foi identificada como Danuzia, no bairro Cidade Jardim, em Concei\u00e7\u00e3o do Coit\u00e9, estava conduzindo quando o animal atravessou na frente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24336,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-24335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24335"}],"version-history":[{"count":4,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24335\/revisions"}],"predecessor-version":[{"id":24355,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24335\/revisions\/24355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24336"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}