{"id":24359,"date":"2024-06-11T17:52:15","date_gmt":"2024-06-11T20:52:15","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24359"},"modified":"2024-06-11T17:52:16","modified_gmt":"2024-06-11T20:52:16","slug":"empresas-firmam-acordo-com-mp-ba-para-proibir-comercializacao-de-cigarros-eletronicos","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/06\/11\/empresas-firmam-acordo-com-mp-ba-para-proibir-comercializacao-de-cigarros-eletronicos\/","title":{"rendered":"Empresas firmam acordo com MP-BA para proibir comercializa\u00e7\u00e3o de cigarros eletr\u00f4nicos"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/image-29-1024x538.png\" alt=\"\" class=\"wp-image-24368\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/image-29-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/image-29-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/image-29-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/image-29.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Jo\u00e9dson Alves \/ Ag\u00eancia Brasil<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O Minist\u00e9rio P\u00fablico da Bahia (MP-BA) firmou Termos de Ajustamento de Conduta (TACs) com as empresas Tabacaria SR Haxi LTDA e LM Tabacos e Presentes LTDA para que n\u00e3o comercializem, importem ou fa\u00e7am propaganda de quaisquer dispositivos eletr\u00f4nicos para fumar, conhecidos como cigarros eletr\u00f4nicos, ecigaretes e e-ciggy, dentre outros, assim como quaisquer acess\u00f3rios e refis tais como ess\u00eancias, destinados ao uso em qualquer dispositivo eletr\u00f4nico para fumar.<\/p>\n\n\n\n<p>Segundo o promotor de Justi\u00e7a Saulo Mattos, autor do TAC, o C\u00f3digo de Defesa do Consumidor (CDC) veda, dentre outras pr\u00e1ticas abusivas, a de \u201ccolocar no mercado de consumo servi\u00e7o em desacordo com as normas expedidas pelos \u00f3rg\u00e3os oficiais competentes\u201d.<\/p>\n\n\n\n<p>Nos acordos, as empresas se comprometeram a atuar em conformidade com a Resolu\u00e7\u00e3o n\u00b0 46\/2009 da Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) e demais resolu\u00e7\u00f5es e legisla\u00e7\u00f5es que tratem sobre a proibi\u00e7\u00e3o da comercializa\u00e7\u00e3o, importa\u00e7\u00e3o e a propaganda de quaisquer dispositivos eletr\u00f4nicos para fumar.<\/p>\n\n\n\n<p>Segundo o promotor de Justi\u00e7a Saulo Mattos, as empresas j\u00e1 foram autuadas pela Vigil\u00e2ncia Sanit\u00e1ria por transgredirem as normas que vedam a comercializa\u00e7\u00e3o dos conhecidos cigarros eletr\u00f4nicos.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico da Bahia (MP-BA) firmou Termos de Ajustamento de Conduta (TACs) com as empresas Tabacaria SR Haxi LTDA e LM Tabacos e Presentes LTDA para que n\u00e3o comercializem, importem ou fa\u00e7am propaganda de quaisquer dispositivos eletr\u00f4nicos para fumar, conhecidos como cigarros eletr\u00f4nicos, ecigaretes e e-ciggy, dentre outros, assim como quaisquer acess\u00f3rios e refis [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24368,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-24359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24359"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24359\/revisions"}],"predecessor-version":[{"id":24369,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24359\/revisions\/24369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24368"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}