{"id":24394,"date":"2024-06-14T09:21:47","date_gmt":"2024-06-14T12:21:47","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24394"},"modified":"2024-06-20T09:42:00","modified_gmt":"2024-06-20T12:42:00","slug":"homem-residente-em-conceicao-do-coite-e-preso-suspeito-de-assedio-sexual-em-serrinha","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/06\/14\/homem-residente-em-conceicao-do-coite-e-preso-suspeito-de-assedio-sexual-em-serrinha\/","title":{"rendered":"Homem residente em Concei\u00e7\u00e3o do Coit\u00e9 \u00e9 preso suspeito de ass\u00e9dio sexual em Serrinha"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"309\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/viatura-pm.jpeg\" alt=\"\" class=\"wp-image-14520\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/viatura-pm.jpeg 550w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2022\/12\/viatura-pm-300x169.jpeg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/div>\n\n\n<p>Na manh\u00e3 desta quinta-feira (13), uma guarni\u00e7\u00e3o da Pol\u00edcia Militar de Serrinha, foi acionada ap\u00f3s receber uma liga\u00e7\u00e3o telef\u00f4nica de uma mulher, alegando ter sido assediada sexualmente durante procedimento m\u00e9dico. Ao chegar no local pr\u00f3ximo da cl\u00ednica, a v\u00edtima se apresentou e disse que durante realiza\u00e7\u00e3o de uma sess\u00e3o de Quiropraxia, recebeu contato f\u00edsico n\u00e3o desejado, momento esse em que ela demonstrou recusa, saiu do estabelecimento e acionou a pol\u00edcia.<\/p>\n\n\n\n<p>Segundo a guarni\u00e7\u00e3o, a v\u00edtima embarcou na viatura e foi at\u00e9 o estabelecimento, na qual a propriet\u00e1ria afirmou que o denunciado havia sa\u00eddo do local e que certamente retornaria. A propriet\u00e1ria afirmou ainda que ouviu coment\u00e1rios de terceiros sobre a m\u00e1 conduta do profissional em quest\u00e3o sobre ass\u00e9dio sexual, vindo a conversar sobre o assunto com ele no dia anterior, pedindo a devolu\u00e7\u00e3o da sala em 5 dias \u00fateis e o encerramento do contrato.<\/p>\n\n\n\n<p>A v\u00edtima de 29 anos, residente na cidade de Curitiba-PR, foi conduzida \u00e0 Delegacia para formaliza\u00e7\u00e3o de queixa, momento esse em que a propriet\u00e1ria do estabelecimento manteve contato com a guarni\u00e7\u00e3o informando sobre o retorno do denunciado. A guarni\u00e7\u00e3o deslocou mais uma vez, fazendo a pris\u00e3o em flagrante delito e condu\u00e7\u00e3o para a Delegacia do homem de Iniciais A.C.J.J, 41 anos, residente em Concei\u00e7\u00e3o do Coit\u00e9.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Por Informe Bahia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta quinta-feira (13), uma guarni\u00e7\u00e3o da Pol\u00edcia Militar de Serrinha, foi acionada ap\u00f3s receber uma liga\u00e7\u00e3o telef\u00f4nica de uma mulher, alegando ter sido assediada sexualmente durante procedimento m\u00e9dico. Ao chegar no local pr\u00f3ximo da cl\u00ednica, a v\u00edtima se apresentou e disse que durante realiza\u00e7\u00e3o de uma sess\u00e3o de Quiropraxia, recebeu contato f\u00edsico n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14520,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-24394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24394"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24394\/revisions"}],"predecessor-version":[{"id":24395,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24394\/revisions\/24395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/14520"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}