{"id":24447,"date":"2024-06-19T09:35:03","date_gmt":"2024-06-19T12:35:03","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24447"},"modified":"2024-06-19T09:35:03","modified_gmt":"2024-06-19T12:35:03","slug":"policia-civil-prende-suspeito-de-envolvimento-no-desaparecimento-de-homem-em-santaluz","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/06\/19\/policia-civil-prende-suspeito-de-envolvimento-no-desaparecimento-de-homem-em-santaluz\/","title":{"rendered":"Pol\u00edcia Civil prende suspeito de envolvimento no desaparecimento de homem em Santaluz"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"636\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/image-48.png\" alt=\"\" class=\"wp-image-24448\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/image-48.png 540w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/image-48-255x300.png 255w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/figure>\n<\/div>\n\n\n<p>A Pol\u00edcia Civil cumpriu nesta ter\u00e7a-feira (18) um mandado de pris\u00e3o contra um suspeito de envolvimento no desaparecimento de um homem identificado como Ant\u00f4nio Guimar Junqueira do Nascimento, ocorrido no fim do ano passado em Santaluz, na regi\u00e3o sisaleira da Bahia. De acordo com a pol\u00edcia, as investiga\u00e7\u00f5es come\u00e7aram ap\u00f3s familiares denunciarem o desaparecimento e informarem que o suspeito, que \u00e9 amigo de Ant\u00f4nio, estaria em posse de dois carros e da casa dele.<\/p>\n\n\n\n<p>Conforme a pol\u00edcia, o suspeito alega ter comprado os bens de Ant\u00f4nio, mas n\u00e3o apresentou nenhum recibo para comprovar a transa\u00e7\u00e3o. H\u00e1 cerca de dois meses, os agentes apreenderam os ve\u00edculos.<\/p>\n\n\n\n<p>Na manh\u00e3 desta ter\u00e7a-feira, o suspeito foi preso no povoado Limeira, zona rural de Santaluz, em cumprimento a um mandado de pris\u00e3o tempor\u00e1ria v\u00e1lido por 30 dias, que pode ser prorrogado por mais 30. Segundo a pol\u00edcia, ao ser interrogado, o suspeito optou por permanecer em sil\u00eancio.<\/p>\n\n\n\n<p>Durante todo o dia, os policiais realizaram dilig\u00eancias e chegaram a ir at\u00e9 a casa de Ant\u00f4nio Guimar, localizada pr\u00f3xima ao est\u00e1dio municipal, onde efetuaram novas buscas. No entanto, ele ainda n\u00e3o foi encontrado. A Pol\u00edcia Civil informou que as investiga\u00e7\u00f5es continuam visando esclarecer o paradeiro de Ant\u00f4nio e o poss\u00edvel envolvimento do suspeito preso.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Por Not\u00edcias de Santaluz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil cumpriu nesta ter\u00e7a-feira (18) um mandado de pris\u00e3o contra um suspeito de envolvimento no desaparecimento de um homem identificado como Ant\u00f4nio Guimar Junqueira do Nascimento, ocorrido no fim do ano passado em Santaluz, na regi\u00e3o sisaleira da Bahia. De acordo com a pol\u00edcia, as investiga\u00e7\u00f5es come\u00e7aram ap\u00f3s familiares denunciarem o desaparecimento e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24449,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-24447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24447"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24447\/revisions"}],"predecessor-version":[{"id":24450,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24447\/revisions\/24450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24449"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}