{"id":24619,"date":"2024-07-08T21:55:08","date_gmt":"2024-07-09T00:55:08","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24619"},"modified":"2024-07-08T21:55:09","modified_gmt":"2024-07-09T00:55:09","slug":"vitoria-inicia-preparacao-para-enfrentar-o-botafogo-pela-16a-rodada-da-serie-a","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/07\/08\/vitoria-inicia-preparacao-para-enfrentar-o-botafogo-pela-16a-rodada-da-serie-a\/","title":{"rendered":"Vit\u00f3ria inicia prepara\u00e7\u00e3o para enfrentar o Botafogo pela 16\u00aa rodada da S\u00e9rie A"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-21-1024x538.png\" alt=\"\" class=\"wp-image-24626\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-21-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-21-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-21-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-21.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Victor Ferreira\/EC Vit\u00f3ria<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Ap\u00f3s vencer o Crici\u00fama por 2 a 1, no \u00faltimo domingo (7), o Vit\u00f3ria iniciou nesta segunda-feira (8) a sua prepara\u00e7\u00e3o para enfrentar o Botafogo, na pr\u00f3xima quinta-feira (11), \u00e0s 21h30, no Barrad\u00e3o, pela 16\u00aa rodada da S\u00e9rie A.<\/p>\n\n\n\n<p>A reapresenta\u00e7\u00e3o do grupo ocorreu \u00e0s 14h30. Os atletas que come\u00e7aram jogando contra o Crici\u00fama foram direcionados \u00e0 academia C\u00e9sar Dau e cumpriram a primeira parte do recovery.<\/p>\n\n\n\n<p>Os demais tamb\u00e9m passaram pela academia e foram em seguida para o campo 2 do Centro de Treinamento. Fizeram aquecimento e treino de posse de bola em espa\u00e7o reduzido. Depois, no gramado do campo Bebeto Gama, participaram de um coletivo de 8 x 8 comandado pelo assistente t\u00e9cnico Estephan Djian. O t\u00e9cnico Thiago Carpini acompanhou a movimenta\u00e7\u00e3o realizada em campo reduzido.<\/p>\n\n\n\n<p>Dos jogadores que estavam no departamento m\u00e9dico rubro-negro, somente Caio Vin\u00edcius n\u00e3o foi ao campo. Ele fez tratamento da les\u00e3o muscular na posterior e segue como desfalque para o duelo contra o Botafogo.<\/p>\n\n\n\n<p>Rodrigo Andrade correu em torno dos campos e depois realizou alguns movimentos controlados com a orienta\u00e7\u00e3o de Vinicius Franco, preparador f\u00edsico assistente. J\u00e1 Iury Castilho trabalhou finaliza\u00e7\u00e3o e a partir desta ter\u00e7a-feira come\u00e7a a terceira etapa da transi\u00e7\u00e3o. Osvaldo tamb\u00e9m correu nos campos com supervis\u00e3o do fisioterapeuta Cl\u00edcio Alves.<\/p>\n\n\n\n<p>O Vit\u00f3ria volta a treinar na tarde desta ter\u00e7a-feira (8), a partir das 14h. Com 15 pontos, o Le\u00e3o ocupa a 15\u00aa coloca\u00e7\u00e3o da S\u00e9rie A. O time rubro-negro est\u00e1 com tr\u00eas pontos a mais que o Corinthians, primeiro time dentro da zona de rebaixamento.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s vencer o Crici\u00fama por 2 a 1, no \u00faltimo domingo (7), o Vit\u00f3ria iniciou nesta segunda-feira (8) a sua prepara\u00e7\u00e3o para enfrentar o Botafogo, na pr\u00f3xima quinta-feira (11), \u00e0s 21h30, no Barrad\u00e3o, pela 16\u00aa rodada da S\u00e9rie A. A reapresenta\u00e7\u00e3o do grupo ocorreu \u00e0s 14h30. Os atletas que come\u00e7aram jogando contra o Crici\u00fama foram [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24626,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-24619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24619"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24619\/revisions"}],"predecessor-version":[{"id":24627,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24619\/revisions\/24627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24626"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}