{"id":24621,"date":"2024-07-08T22:09:10","date_gmt":"2024-07-09T01:09:10","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24621"},"modified":"2024-07-08T22:09:11","modified_gmt":"2024-07-09T01:09:11","slug":"ministerio-da-saude-desrespeita-prazo-para-incorporar-medicamentos-contra-o-cancer-de-mama-no-sus","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/07\/08\/ministerio-da-saude-desrespeita-prazo-para-incorporar-medicamentos-contra-o-cancer-de-mama-no-sus\/","title":{"rendered":"Minist\u00e9rio da Sa\u00fade desrespeita prazo para incorporar medicamentos contra o c\u00e2ncer de mama no SUS"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-23-1024x538.png\" alt=\"\" class=\"wp-image-24630\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-23-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-23-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-23-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-23.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Arquivo Ag\u00eancia Brasil<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Pacientes que sofrem em decorr\u00eancia do c\u00e2ncer de mama no Sistema \u00danico de Sa\u00fade (SUS) ainda precisam recorrer \u00e0 Justi\u00e7a para obter os rem\u00e9dios, em processo penoso que pode durar at\u00e9 6 meses para a entrega dos medicamentos. Dois anos ap\u00f3s a Comiss\u00e3o Nacional de Incorpora\u00e7\u00e3o de Tecnologia no SUS (Conitec) aprovar a inclus\u00e3o de medicamentos para o tratamento da doen\u00e7a.<\/p>\n\n\n\n<p>Mesmo sendo submetido \u00e0 consulta p\u00fablica e aprovado em abril um protocolo que garante a distribui\u00e7\u00e3o dos medicamentos pelo Sistema \u00danico de Sa\u00fade (SUS), o \u00f3rg\u00e3o ainda n\u00e3o publicou o documento no Di\u00e1rio Oficial da Uni\u00e3o (DOU). Com isso, n\u00e3o h\u00e1 oferta dos medicamentos no SUS, fazendo com que mulheres sofram por conta da n\u00e3o oferta.<\/p>\n\n\n\n<p>Segundo publica\u00e7\u00e3o do O GLOBO, na vers\u00e3o submetida \u00e0 consulta p\u00fablica, os novos protocolos projetavam a incorpora\u00e7\u00e3o de dois tipos de rem\u00e9dios para tratamento de c\u00e2ncer de mama no SUS: os inibidores de ciclina, que foram aprovados pela Conitec em dezembro de 2021 (oferta no SUS atrasada h\u00e1 mais de 764 dias) e o trastuzumabe entansina, que foi incorporado em setembro de 2022.<\/p>\n\n\n\n<p>Desde a aprova\u00e7\u00e3o, j\u00e1 foram acumulados mais de 488 dias sem o in\u00edcio da oferta do rem\u00e9dio no SUS. Os produtos s\u00e3o considerados de primeira linha para tratamento do c\u00e2ncer de mama, permitindo os melhores resultados com o menor n\u00famero de efeitos colaterais.<\/p>\n\n\n\n<p>A demora desrespeita os prazos da Conitec, j\u00e1 que os rem\u00e9dios devem ser incorporados pela pasta em at\u00e9 180 dias, com direito a 90 dias de prorroga\u00e7\u00e3o depois de ser aprovado pela Comiss\u00e3o.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pacientes que sofrem em decorr\u00eancia do c\u00e2ncer de mama no Sistema \u00danico de Sa\u00fade (SUS) ainda precisam recorrer \u00e0 Justi\u00e7a para obter os rem\u00e9dios, em processo penoso que pode durar at\u00e9 6 meses para a entrega dos medicamentos. Dois anos ap\u00f3s a Comiss\u00e3o Nacional de Incorpora\u00e7\u00e3o de Tecnologia no SUS (Conitec) aprovar a inclus\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24630,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-24621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24621"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24621\/revisions"}],"predecessor-version":[{"id":24631,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24621\/revisions\/24631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24630"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}