{"id":24632,"date":"2024-07-09T12:37:44","date_gmt":"2024-07-09T15:37:44","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24632"},"modified":"2024-07-09T12:37:45","modified_gmt":"2024-07-09T15:37:45","slug":"bahia-atualiza-sistema-e-passa-a-emitir-nova-carteira-de-identidade-nacional","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/07\/09\/bahia-atualiza-sistema-e-passa-a-emitir-nova-carteira-de-identidade-nacional\/","title":{"rendered":"Bahia atualiza sistema e passa a emitir nova Carteira de Identidade Nacional"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-24-1024x683.png\" alt=\"\" class=\"wp-image-24633\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-24-1024x683.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-24-300x200.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-24-768x512.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-24-1536x1024.png 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-24.png 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>\u201cEu acho que \u00e9 praticidade ter um \u00fanico documento universal. A gente pode sair de casa s\u00f3 com ele, j\u00e1 \u00e9 o suficiente. E de gra\u00e7a, a melhor parte\u201d. \u00c9 desta forma que a esteticista M\u00e1rcia Lopes comemora a retirada da nova Carteira de Identidade Nacional (CIN). \u00c9 que com o lan\u00e7amento, nesta ter\u00e7a-feira (9), do novo sistema de identifica\u00e7\u00e3o, a Bahia est\u00e1 apta para emitir a CIN.<\/p>\n\n\n\n<p>O ato aconteceu no posto SAC do Terminal de Pitua\u00e7u, em Salvador, e contou com a presen\u00e7a do governador Jer\u00f4nimo Rodrigues. \u201cO papel fundamental dessa documenta\u00e7\u00e3o \u00e9 a cidadania. As pessoas terem seu documento, se sentirem cidad\u00e3 ou cidad\u00e3o baiano, brasileiro. Ver esse documento no bolso, na carteira, por exemplo, me d\u00e1 muito orgulho. Ali eu sou gente, o Estado me reconhece, ali o Estado me viu\u201d, considerou o governador.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-26-1024x683.png\" alt=\"\" class=\"wp-image-24635\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-26-1024x683.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-26-300x200.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-26-768x512.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-26-1536x1024.png 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-26.png 1599w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>A primeira via do documento \u00e9 gratuita para todos os cidad\u00e3os. A solicita\u00e7\u00e3o deve ser feita no portal ou aplicativo\u00a0<a href=\"https:\/\/ba.gov.br\/\">ba.gov.br<\/a>. J\u00e1 a emiss\u00e3o ser\u00e1 realizada, inicialmente, nos postos SAC Pitua\u00e7u e Salvador Shopping. A previs\u00e3o \u00e9 que as demais unidades da rede, distribu\u00eddas em Salvador e no interior do estado, passem a emitir a CIN em breve.<\/p>\n\n\n\n<p>Foram investidos mais de R$ R$ 8,6 milh\u00f5es na contrata\u00e7\u00e3o do novo sistema. O contrato, com vig\u00eancia de cinco anos, prev\u00ea a presta\u00e7\u00e3o de servi\u00e7os e inclui implanta\u00e7\u00e3o, configura\u00e7\u00e3o, migra\u00e7\u00e3o de sistema e treinamento de pessoal.<\/p>\n\n\n\n<p>Com o novo documento, o Cadastro de Pessoa F\u00edsica (CPF) passa a ser o \u00fanico n\u00famero de identifica\u00e7\u00e3o, unificando o registro em todo o Brasil. O objetivo \u00e9 eliminar a duplicidade e reduzir as possibilidades de fraudes. O Departamento de Pol\u00edcia T\u00e9cnica (DPT), por meio do Instituto de Identifica\u00e7\u00e3o Pedro Mello (IIPM), \u00e9 o respons\u00e1vel pela emiss\u00e3o da nova identidade na Bahia. De acordo com a diretora-geral do DPT, Ana Cec\u00edlia Bandeira, vai facilitar a ades\u00e3o a programas e servi\u00e7os p\u00fablicos. \u201cEle nos permite o exerc\u00edcio da cidadania, o acesso a diversos servi\u00e7os e a popula\u00e7\u00e3o em situa\u00e7\u00e3o de vulnerabilidade, ele \u00e9 fundamental para acesso \u00e0s pol\u00edticas p\u00fablicas\u201d, disse.<\/p>\n\n\n\n<p>Para a emiss\u00e3o da nova identidade \u00e9 exigida apenas a certid\u00e3o de nascimento ou casamento. Outro elemento de seguran\u00e7a ser\u00e1 o QR Code para verifica\u00e7\u00e3o da autenticidade e se foi extraviado ou roubado, conferindo maior prote\u00e7\u00e3o aos dados, como explica o secret\u00e1rio da Seguran\u00e7a P\u00fablica, Marcelo Werner. \u201cEla traz a incorpora\u00e7\u00e3o dos sistemas estaduais com o sistema federal. Considerando que a nova identidade \u00fanica tem o CPF como seu registro, ent\u00e3o, isso vai alimentar todo o sistema do gov.br, al\u00e9m do&nbsp;<a href=\"https:\/\/bahia.gov.br\/\">bahia.gov.br<\/a>. Enfim, s\u00e3o v\u00e1rios avan\u00e7os a partir dessa identidade\u201d.<\/p>\n\n\n\n<p>Na sua vers\u00e3o digital, acessada pelo GOV.BR, ser\u00e1 poss\u00edvel a inclus\u00e3o de outros n\u00fameros de documentos como CNH, Carteira de Trabalho, T\u00edtulo de Eleitor, certificado militar, tamb\u00e9m condi\u00e7\u00f5es de sa\u00fade a exemplo do Transtorno do Espectro Autista (TEA), defici\u00eancias auditiva, visual, f\u00edsica e intelectual, a partir da apresenta\u00e7\u00e3o de relat\u00f3rio m\u00e9dico e informa\u00e7\u00f5es adicionais como tipo sangu\u00edneo, fator RH e op\u00e7\u00e3o por ser doador de \u00f3rg\u00e3o. Ser\u00e1 poss\u00edvel, ainda, incluir o nome social a pedido do pr\u00f3prio cidad\u00e3o, caso haja mudan\u00e7a de nome na certid\u00e3o de nascimento, valendo apenas este novo registro.<\/p>\n\n\n\n<p>O RG ser\u00e1 substitu\u00eddo gradativamente e perde a validade apenas em 2032, quando a nova Carteira de Identidade se torna o \u00fanico documento v\u00e1lido nacionalmente, de acordo com a Lei 14.534, de 11 de janeiro de 2023. \u201cN\u00e3o h\u00e1 necessidade de o cidad\u00e3o vir com certa pressa para fazer o documento, at\u00e9 porque o que ele tiver em casa, ele \u00e9 um documento atual, ele pode utilizar esse documento\u201d, afirmou a diretora do opera\u00e7\u00f5es da rede SAC, Nilza Rios.<\/p>\n\n\n\n<p>A CIN ter\u00e1 validade de acordo com a faixa et\u00e1ria do cidad\u00e3o: de 0 a 12 anos, expira em cinco anos; 12 a 60 anos incompletos, vale por 10 anos; acima de 60 anos, validade indeterminada.<\/p>\n\n\n\n<p><strong>Padr\u00f5es internacionais<\/strong><\/p>\n\n\n\n<p>A nova identidade segue padr\u00f5es internacionais e possui o c\u00f3digo MRZ \u2013 o mesmo do passaporte, que permite a entrada em pa\u00edses do Mercosul com maior facilidade. Para os demais pa\u00edses, ainda \u00e9 necess\u00e1rio a apresenta\u00e7\u00e3o do passaporte.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Rep\u00f3rter: Anderson Oliveira\/ GOVBA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEu acho que \u00e9 praticidade ter um \u00fanico documento universal. A gente pode sair de casa s\u00f3 com ele, j\u00e1 \u00e9 o suficiente. E de gra\u00e7a, a melhor parte\u201d. \u00c9 desta forma que a esteticista M\u00e1rcia Lopes comemora a retirada da nova Carteira de Identidade Nacional (CIN). \u00c9 que com o lan\u00e7amento, nesta ter\u00e7a-feira (9), [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24634,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-24632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24632"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24632\/revisions"}],"predecessor-version":[{"id":24636,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24632\/revisions\/24636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24634"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}