{"id":24639,"date":"2024-07-09T15:01:41","date_gmt":"2024-07-09T18:01:41","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24639"},"modified":"2024-07-09T15:01:42","modified_gmt":"2024-07-09T18:01:42","slug":"equipe-de-ze-vaqueiro-revela-causa-da-morte-do-filho-do-artista-aos-11-meses","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/07\/09\/equipe-de-ze-vaqueiro-revela-causa-da-morte-do-filho-do-artista-aos-11-meses\/","title":{"rendered":"Equipe de Z\u00e9 Vaqueiro revela causa da morte do filho do artista aos 11 meses"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-29-1024x538.png\" alt=\"\" class=\"wp-image-24646\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-29-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-29-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-29-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-29.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Instagram<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O cantor Z\u00e9 Vaqueiro e a esposa, Ingra Soares, est\u00e3o vivendo um momento delicado com a morte do pequeno Arthur Siqueira Duarte, filho do casal de 11 meses. O falecimento do herdeiro foi comunicado pelo artista na madrugada desta ter\u00e7a (9) sem a causa da morte.<\/p>\n\n\n\n<p>Pela manh\u00e3, a equipe do artista informou por meio de um comunicado enviado ao site Hugo Gloss que o beb\u00ea, que foi diagnosticado com a S\u00edndrome de Patau, faleceu devido a uma disfun\u00e7\u00e3o m\u00faltipla dos \u00f3rg\u00e3os. A morte de Arthur aconteceu por volta das 21h45 da segunda.<\/p>\n\n\n\n<p>Na web, o cantor deu um breve depoimento sobre a morte do herdeiro: \u201cDeus sabe de todas as coisas, e decidiu que era hora do nosso Arthur se juntar a Ele e descansar. Agradecemos do fundo de nossos cora\u00e7\u00f5es o amor e as ora\u00e7\u00f5es que nosso menino recebeu enquanto estava entre n\u00f3s\u201d.<\/p>\n\n\n\n<p><strong>O QUE \u00c9 A S\u00cdNDROME DE PATAU?<\/strong><\/p>\n\n\n\n<p>A doen\u00e7a, que foi diagnosticada em Arthur logo ap\u00f3s o nascimento, \u00e9 caracterizada por um cromossomo a mais no beb\u00ea. Ao inv\u00e9s dos 46 cromossomos divididos em pares, o portador da s\u00edndrome possui uma falha gen\u00e9tica e apresenta 3 cromossomos no grupo 13.<\/p>\n\n\n\n<p>O caso do filho de Z\u00e9 Vaqueiro \u00e9 raro, j\u00e1 que a condi\u00e7\u00e3o n\u00e3o heredit\u00e1ria costuma afetar mais crian\u00e7as do sexo feminino.<\/p>\n\n\n\n<p>A S\u00edndrome de Patau, que n\u00e3o tem cura, causa altera\u00e7\u00f5es no desenvolvimento do beb\u00ea, como atraso mental; m\u00e1-forma\u00e7\u00e3o nas orelhas, p\u00e9s e olhos; microcefalia; m\u00e3os com dedos a mais; tamanho reduzido do queixo; problemas no cora\u00e7\u00e3o e doen\u00e7as renais.<\/p>\n\n\n\n<p>O filho do artisa chegou a receber alta m\u00e9dica em maio deste ano, 9 meses ap\u00f3s o nascimento, mas voltiu a ser internado no dia seguinte ao deixar o hospital ap\u00f3s sofrer uma parada card\u00edaca.<\/p>\n\n\n\n<p>Z\u00e9 Vaqueiro chegou a ser criticado na internet por dar continuidade a agenda de trabalhos com o filho internado e por viajar com a fam\u00edlia para Fernando de Noronha. Em um desabafo, o artista afirmou que estava fazendo de tudo para tornar a vida saud\u00e1vel para toda a fam\u00edlia, mesmo com os problemas de sa\u00fade do ca\u00e7ula.<\/p>\n\n\n\n<p>&#8220;A gente foi para Fernando de Noronha para n\u00e3o &#8216;endoidar&#8217;. A gente foi para que os nossos filhos tivessem algum momento que n\u00e3o fosse igual ao que a gente est\u00e1 tendo nos \u00faltimos meses, para que fosse saud\u00e1vel para eles e para a gente (ele e a esposa) tamb\u00e9m&#8221;.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O cantor Z\u00e9 Vaqueiro e a esposa, Ingra Soares, est\u00e3o vivendo um momento delicado com a morte do pequeno Arthur Siqueira Duarte, filho do casal de 11 meses. O falecimento do herdeiro foi comunicado pelo artista na madrugada desta ter\u00e7a (9) sem a causa da morte. Pela manh\u00e3, a equipe do artista informou por meio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24646,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-24639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24639"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24639\/revisions"}],"predecessor-version":[{"id":24647,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24639\/revisions\/24647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24646"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}