{"id":24661,"date":"2024-07-10T16:33:58","date_gmt":"2024-07-10T19:33:58","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24661"},"modified":"2024-07-10T16:33:58","modified_gmt":"2024-07-10T19:33:58","slug":"paes-de-forma-tem-alto-teor-alcoolico-e-poderiam-ate-afetar-bafometro-diz-associacao","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/07\/10\/paes-de-forma-tem-alto-teor-alcoolico-e-poderiam-ate-afetar-bafometro-diz-associacao\/","title":{"rendered":"P\u00e3es de forma t\u00eam alto teor alco\u00f3lico e poderiam at\u00e9 afetar baf\u00f4metro, diz associa\u00e7\u00e3o"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-37-1024x538.png\" alt=\"\" class=\"wp-image-24675\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-37-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-37-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-37-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/image-37.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Arquivo \/ Ag\u00eancia Brasil<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Um estudo divulgado nesta quarta-feira (10) pela Associa\u00e7\u00e3o Brasileira de Defesa do Consumidor, conhecida como Proteste, do grupo Euroconsumers, apontou que algumas marcas populares de p\u00e3o de forma em supermercados apresentam alto teor alco\u00f3lico, o que na vis\u00e3o da organiza\u00e7\u00e3o \u00e9 prejudicial ao ser humano, em especial a gr\u00e1vidas e beb\u00eas.<\/p>\n\n\n\n<p>A pesquisa apontou tamb\u00e9m que, dos dez produtos analisados, seis seriam considerados alimentos alco\u00f3licos se existisse uma legisla\u00e7\u00e3o para a categoria semelhante \u00e0 de bebidas. O \u00e1lcool presente nesses produtos \u00e9 oriundo do processo de fermenta\u00e7\u00e3o e do uso de conservantes.<\/p>\n\n\n\n<p>Para chegar ao resultado, a Proteste analisou o teor alco\u00f3lico de dez marcas de p\u00e3o de forma, sendo quatro da empresa Wickbold. S\u00e3o eles: Visconti, Bauducco, Wickbold 5 zeros, Wickbold sem gl\u00faten, Wickbold leve, Panco, Seven Boys, Wickbold, Plusvita e Pulmann.<\/p>\n\n\n\n<p>Destes, a pesquisa concluiu que apenas os p\u00e3es das \u00faltimas quatro marcas t\u00eam teor de etanol abaixo de 0,5%, grau limite para que uma bebida seja considerada alco\u00f3lica. Um dos lotes analisados da Visconti, por exemplo, tinha teor de 3,37% e da Bauducco, de 1,17% (em compara\u00e7\u00e3o, a cerveja Brahma chopp tem 4,8%).<\/p>\n\n\n\n<p>Todas as marcas acusadas pela Proteste disseram \u00e0 reportagem respeitar a legisla\u00e7\u00e3o brasileira e submeter seus produtos a processos criteriosos de qualidade. As notas de cada uma est\u00e3o no final da reportagem.<\/p>\n\n\n\n<p>A organiza\u00e7\u00e3o de defesa ao consumidor separou a an\u00e1lise em duas partes: na primeira, avaliou quatro lotes do produto da Bauducco, um da Panco, um da Plusvita, um da Pullman, um da Seven Boys, tr\u00eas da Visconti, um da Wickbold zero, um da Wickbold leve e baixo em gorduras, um da Wickbold sem gl\u00faten e um da Wickbold.<\/p>\n\n\n\n<p>J\u00e1 na segunda parte, foram analisados tr\u00eas lotes da Bauducco, tr\u00eas da Visconti, um da Panco, tr\u00eas da Plusvita, um da Seven Boys, um da Wickbold 5 zeros, um da Wickbold leve e baixo em gorduras, um da Wickbold sem gl\u00faten, um da Wickbold e um da Pullman.<\/p>\n\n\n\n<p>Em alguns casos, houve varia\u00e7\u00f5es entre os teores alco\u00f3lico dos lotes das mesmas marcas. Os p\u00e3es da Bauducco analisados no segundo est\u00e1gio, por exemplo, variaram de 1,17% a 0,66% \u2013ainda que todos tenham registrado teor acima do permitido para uma bebida n\u00e3o ser classificada como alco\u00f3lica. O mesmo aconteceu com os p\u00e3es Visconti, que variaram de 0,95% a 3,37%.<\/p>\n\n\n\n<p>A varia\u00e7\u00e3o, segundo a Proteste, acontece devido ao processo de armazenamento e validade dos produtos. Para fazer a tabela publicada abaixo, a Folha e a organiza\u00e7\u00e3o consideraram o maior valor registrado por marca.<\/p>\n\n\n\n<p>&#8220;Ouvimos diversas vezes que alguns p\u00e3es de forma cheiravam \u00e1lcool, o que, no m\u00ednimo, \u00e9 estranho. Sabemos que a fermenta\u00e7\u00e3o implica a produ\u00e7\u00e3o de \u00e1lcool, mas em n\u00edveis t\u00e3o baixos que ele \u00e9 evaporado no momento em que o produto \u00e9 assado. Tamb\u00e9m sabemos que o \u00e1lcool entra na composi\u00e7\u00e3o do antimofo que \u00e9 aspergido sobre o produto pronto, mas, novamente, sua quantidade deveria ser t\u00e3o pequena que desaparecesse antes de ser consumido&#8221;, diz Henrique Lian, diretor-executivo da Proteste|Euroconsumers Brasil.<\/p>\n\n\n\n<p>Al\u00e9m de atestar o teor alco\u00f3lico dos produtos, a Proteste verificou a incid\u00eancia de algum motorista ser testado positivamente no baf\u00f4metro ap\u00f3s comer duas fatias do p\u00e3o de forma dessas marcas. O resultado (abaixo) \u00e9 que aquelas pessoas que comeram duas fatias dos lotes da Visconti, Bauducco e Wickbold 5 zeros com maior teor alco\u00f3lico correriam o risco de ser acusadas de embriaguez ao volante.<\/p>\n\n\n\n<p>Para chegar a essa conclus\u00e3o, a Proteste considerou a informa\u00e7\u00e3o dada pelo Detran do Rio Grande do Sul de que todo motorista que, ao fazer o teste do baf\u00f4metro, apresentar resultado superior a 0,04 miligramas de \u00e1lcool por litros de ar expelido estar\u00e1 cometendo infra\u00e7\u00e3o grav\u00edssima ou crime de tr\u00e2nsito.<\/p>\n\n\n\n<p>Neste caso, a organiza\u00e7\u00e3o considerou que 0,04mg\/l equivale a 0,08 gramas de \u00e1lcool por litro de sangue. Ou seja, uma pessoa que tiver 5,5 litros de sangue no organismo precisaria ter 0,44 gramas de \u00e1lcool em seu organismo para testar positivo no baf\u00f4metro. Assim, de acordo com as an\u00e1lises da Proteste, os motoristas que comerem duas fatias de p\u00e3es de forma de marcas que tenham mais de 0,22 gramas de etanol por fatia poder\u00e3o ser penalizados.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um estudo divulgado nesta quarta-feira (10) pela Associa\u00e7\u00e3o Brasileira de Defesa do Consumidor, conhecida como Proteste, do grupo Euroconsumers, apontou que algumas marcas populares de p\u00e3o de forma em supermercados apresentam alto teor alco\u00f3lico, o que na vis\u00e3o da organiza\u00e7\u00e3o \u00e9 prejudicial ao ser humano, em especial a gr\u00e1vidas e beb\u00eas. A pesquisa apontou tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24675,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-24661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24661"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24661\/revisions"}],"predecessor-version":[{"id":24676,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24661\/revisions\/24676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24675"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}