{"id":24736,"date":"2024-07-15T09:48:39","date_gmt":"2024-07-15T12:48:39","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=24736"},"modified":"2024-07-15T09:48:39","modified_gmt":"2024-07-15T12:48:39","slug":"vitima-de-acidente-de-moto-e-socorrida-pela-brigada-anjos-da-vida-em-coite","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/07\/15\/vitima-de-acidente-de-moto-e-socorrida-pela-brigada-anjos-da-vida-em-coite\/","title":{"rendered":"V\u00edtima de acidente de moto \u00e9 socorrida pela Brigada Anjos da Vida em Coit\u00e9"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-15-as-08.21.30_77026f5a-1024x768.jpg\" alt=\"\" class=\"wp-image-24737\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-15-as-08.21.30_77026f5a-1024x768.jpg 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-15-as-08.21.30_77026f5a-300x225.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-15-as-08.21.30_77026f5a-768x576.jpg 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-15-as-08.21.30_77026f5a-1536x1152.jpg 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-15-as-08.21.30_77026f5a-86x64.jpg 86w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/07\/Imagem-do-WhatsApp-de-2024-07-15-as-08.21.30_77026f5a.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Na manh\u00e3 desta segunda-feira (15), a equipe de socorristas da Brigada Anjos da Vida, foi acionada para socorrer uma pessoa ferida ap\u00f3s sofrer um acidente de moto na rua Ant\u00f4nio Calixto da Cunha, em Concei\u00e7\u00e3o do Coit\u00e9.<\/p>\n\n\n\n<p>O Informe Bahia apurou que, a v\u00edtima foi identificada como Itamara de Almeida, moradora no bairro Alto da Colina, que conduzia uma motocicleta e o outro condutor n\u00e3o estava no local, o mesmo n\u00e3o foi identificado.<\/p>\n\n\n\n<p>A mulher foi encaminha para o hospital da cidade para ser atendida pela equipe de plant\u00e3o. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta segunda-feira (15), a equipe de socorristas da Brigada Anjos da Vida, foi acionada para socorrer uma pessoa ferida ap\u00f3s sofrer um acidente de moto na rua Ant\u00f4nio Calixto da Cunha, em Concei\u00e7\u00e3o do Coit\u00e9. O Informe Bahia apurou que, a v\u00edtima foi identificada como Itamara de Almeida, moradora no bairro Alto da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24737,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-24736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=24736"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24736\/revisions"}],"predecessor-version":[{"id":24738,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/24736\/revisions\/24738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24737"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=24736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=24736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=24736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}