{"id":25023,"date":"2024-08-04T21:32:33","date_gmt":"2024-08-05T00:32:33","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25023"},"modified":"2024-08-13T06:42:19","modified_gmt":"2024-08-13T09:42:19","slug":"os-partidos-avante-e-pt-confirmam-os-candidatos-a-prefeito-e-vice-em-valente","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/04\/os-partidos-avante-e-pt-confirmam-os-candidatos-a-prefeito-e-vice-em-valente\/","title":{"rendered":"Os partidos Avante e PT confirmam os candidatos a prefeito e vice em Valente"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/01.jpg\" alt=\"\" class=\"wp-image-25024\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/01.jpg 600w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/01-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Foto: Informe Bahia<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Na manh\u00e3 deste domingo (04), aconteceu na Casa da Cultura na cidade de Valente, a conven\u00e7\u00e3o dos partidos Avante, PC do B, Podemos, PDT, PT e Uni\u00e3o Brasil. Na oportunidade foi confirmado a chapa Ubaldino Amaral (Avante) candidato a prefeito pela reelei\u00e7\u00e3o e o vice prefeito Dica (PT.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/02.jpg\" alt=\"\" class=\"wp-image-25025\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/02.jpg 600w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/02-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Foto: Informe Bahia<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Estavam presentes no evento: os deputados estaduais Marcinho Oliveira e Rosival Leite, a ent\u00e3o deputada federa Elisangela. Os presidentes dos partidos, Analdo Amaral (Avante), Adevaldo Silva (PC do B), Alicio Neto (Podemos), Jos\u00e9 Melqu\u00edades (PDT), Jos\u00e9 Silva (PT) e Mabel Amaral (Uni\u00e3o Brasil). Tamb\u00e9m estavam presente Leninha ex-vereadora, Ismael ex-prefeito e outras lideran\u00e7as comunit\u00e1rias.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"444\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/03.jpg\" alt=\"\" class=\"wp-image-25027\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/03.jpg 600w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/03-300x222.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/03-86x64.jpg 86w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Foto: Informe Bahia<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O deputado Marcinho destacou a sua parceria com Ubaldinho Amaral juntamente com o deputado federal Elmar Nascimento, e prometeu continuar essa parceria para trazer mais benef\u00edcios para a popula\u00e7\u00e3o valentense. O parlamentar destacou a uni\u00e3o de Ubaldino com outros partidos e em especial com o PT que indicou Dica como vice.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/04.jpg\" alt=\"\" class=\"wp-image-25029\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/04.jpg 600w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/04-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Foto: Informe Bahia<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O candidato a vice Dica, agradeceu ao seu partido pela sua escolha e que n\u00e3o pensou duas vez em aceitar o convite. Enfatizou a presen\u00e7a do ex-prefeito Ismael. \u201cO PT lan\u00e7ou inicialmente tr\u00eas pr\u00e9 candidatos, depois dois abriu m\u00e3o deixando para Ismael e agora decidimos se unir com Ubaldino Amaral para o bem do povo. Estou emocionado nesse momento sentindo a aus\u00eancia do meu pai nesse evento\u201d, enfatizou.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/05.jpg\" alt=\"\" class=\"wp-image-25031\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/05.jpg 600w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/05-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Foto: Informe Bahia<\/figcaption><\/figure>\n<\/div>\n\n\n<p>No seu discurso, Ubaldino Amaral agradeceu ao apoio das lideran\u00e7as pol\u00edticas que estavam presentes e do povo pelo reconhecimento do seu trabalho em prol dos moradores do munic\u00edpio de Valente. \u201cQuero agradecer a ele que est\u00e1 presente, ao ex-prefeito e grande lideran\u00e7a do PT Ismael, voc\u00ea sempre foi um empreendedor do munic\u00edpio. E agora que agradecer por essa uni\u00e3o, eu e Dica vamos visitar o povo e prometo juntos continuarmos para o bem de Valente, esse grupo \u00e9 o que gosta de gente\u201d, concluiu. &nbsp;&nbsp;<\/p>\n\n\n\n<p>*Informe Bahia<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/06.jpg\" alt=\"\" class=\"wp-image-25033\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/06.jpg 600w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/06-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Foto: Informe Bahia<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-right\">&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-text-align-left\">&nbsp;&nbsp;<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FInformeBahia%2Fposts%2Fpfbid0KiBnpnwEyjBk8GHPi4jhkw4DLFRwBueSZRsTFeykj98x59w37FvwH9CCNrqGxhVLl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"665\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 deste domingo (04), aconteceu na Casa da Cultura na cidade de Valente, a conven\u00e7\u00e3o dos partidos Avante, PC do B, Podemos, PDT, PT e Uni\u00e3o Brasil. Na oportunidade foi confirmado a chapa Ubaldino Amaral (Avante) candidato a prefeito pela reelei\u00e7\u00e3o e o vice prefeito Dica (PT. Estavam presentes no evento: os deputados estaduais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-25023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25023"}],"version-history":[{"count":2,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25023\/revisions"}],"predecessor-version":[{"id":25117,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25023\/revisions\/25117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25024"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}