{"id":25082,"date":"2024-08-07T09:53:03","date_gmt":"2024-08-07T12:53:03","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25082"},"modified":"2024-08-07T09:53:04","modified_gmt":"2024-08-07T12:53:04","slug":"estudante-do-colegio-da-policia-militar-morre-apos-cair-de-viaduto-na-bahia","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/07\/estudante-do-colegio-da-policia-militar-morre-apos-cair-de-viaduto-na-bahia\/","title":{"rendered":"Estudante do Col\u00e9gio da Pol\u00edcia Militar morre ap\u00f3s cair de viaduto na Bahia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-13.png\" alt=\"\" class=\"wp-image-25083\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-13.png 640w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-13-300x169.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n<p>Um estudante do 3\u00ba ano do Col\u00e9gio da Pol\u00edcia Militar (CPM), identificado como Tiago dos Santos Silva, idade n\u00e3o divulgada, morreu na manh\u00e3 desta quarta-feira (7), ap\u00f3s cair de uma das al\u00e7as do Complexo de Viadutos Miraldo Gomes, no bairro Cidade Nova, em Feira de Santana.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es apuradas do site Acorda Cidade no local, o estudante estava fardado e, segundo testemunhas, ele teria se jogado do viaduto.<\/p>\n\n\n\n<p>Ap\u00f3s a queda, o corpo do estudante ficou na pista no sentido Centro \u2013 bairro Cidade Nova. Uma ambul\u00e2ncia do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu), chegou a prestar os primeiros socorros, mas o estudante n\u00e3o resistiu aos ferimentos.<\/p>\n\n\n\n<p>De acordo com a equipe m\u00e9dica, o estudante teve fraturas no f\u00eamur e no rosto.<\/p>\n\n\n\n<p>Policiais militares deram apoio no tr\u00e2nsito, enquanto a ambul\u00e2ncia estava parada na via. At\u00e9 o fechamento desta reportagem, nenhum familiar tinha chegado no local.<\/p>\n\n\n\n<p>O corpo do estudante foi encaminhado para o Hospital Geral Cl\u00e9riston Andrade (HGCA). Diante do ocorrido, as aulas foram suspensas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um estudante do 3\u00ba ano do Col\u00e9gio da Pol\u00edcia Militar (CPM), identificado como Tiago dos Santos Silva, idade n\u00e3o divulgada, morreu na manh\u00e3 desta quarta-feira (7), ap\u00f3s cair de uma das al\u00e7as do Complexo de Viadutos Miraldo Gomes, no bairro Cidade Nova, em Feira de Santana. Segundo informa\u00e7\u00f5es apuradas do site Acorda Cidade no local, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25083,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-25082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25082"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25082\/revisions"}],"predecessor-version":[{"id":25084,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25082\/revisions\/25084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25083"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}