{"id":25105,"date":"2024-08-08T14:04:34","date_gmt":"2024-08-08T17:04:34","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25105"},"modified":"2024-08-08T14:04:35","modified_gmt":"2024-08-08T17:04:35","slug":"com-investimento-que-ultrapassa-r-60-milhoes-governador-entrega-e-autoriza-obras-para-a-educacao-em-feira-de-santana","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/08\/com-investimento-que-ultrapassa-r-60-milhoes-governador-entrega-e-autoriza-obras-para-a-educacao-em-feira-de-santana\/","title":{"rendered":"Com investimento que ultrapassa R$ 60 milh\u00f5es, governador entrega e autoriza obras para a educa\u00e7\u00e3o em Feira de Santana"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-20-1024x682.png\" alt=\"\" class=\"wp-image-25106\" style=\"width:600px;height:auto\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-20-1024x682.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-20-300x200.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-20-768x512.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-20-1536x1023.png 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-20.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto Thuane Maria<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Durante visita \u00e0 \u201cPrincesinha do Sert\u00e3o\u201d nesta quinta-feira (8), o governador Jer\u00f4nimo Rodrigues inaugurou e autorizou obras na \u00e1rea da educa\u00e7\u00e3o, que contemplam estudantes da sede e tamb\u00e9m de distritos de Feira de Santana. Os investimentos no setor ultrapassam os R$ 60 milh\u00f5es. Entre as a\u00e7\u00f5es, foi entregue a amplia\u00e7\u00e3o do Col\u00e9gio Estadual de Tempo Integral Carolina Maria de Jesus.<\/p>\n\n\n\n<p>\u201cMais um dia aqui em Feira de Santana, eu estou cumprindo tudo aquilo que eu programei com a popula\u00e7\u00e3o. N\u00f3s conclu\u00edmos o projeto dessa escola. Temos tamb\u00e9m, na Matinha, uma nova escola, porque n\u00e3o existe l\u00e1 uma escola estadual. Vamos construir em outra comunidade quilombola\u201d, pontuou o governador, ao explicar que a gest\u00e3o estadual j\u00e1 entregou 600 unidades novas ou reformadas e ampliadas.<\/p>\n\n\n\n<p>Com o objetivo de oferecer mais conforto e melhores condi\u00e7\u00f5es de estudo, o governador inaugurou as obras de amplia\u00e7\u00e3o, com moderniza\u00e7\u00e3o, do Col\u00e9gio Estadual de Tempo Integral Carolina Maria de Jesus, localizado no bairro do Tomba. Com isso, o pr\u00e9dio passa a contar com novos campos de futebol society, 10 salas, espa\u00e7o para atividades diversas, teatro e restaurante. Tamb\u00e9m foi realizada a reforma e cobertura da quadra poliesportiva, novos mobili\u00e1rios e equipamentos. As unidades contaram com recurso de R$ 11,9 milh\u00f5es. \u201cMuito melhor, porque tem v\u00e1rias escolas que n\u00e3o t\u00eam condi\u00e7\u00f5es de ter biblioteca, ter teatro, ter quadra. Eu acho bem melhor para a comunidade, para a escola tamb\u00e9m. Muito bom\u201d, comentou a estudante Ester Alves, do 6\u00ba ano.<\/p>\n\n\n\n<p>Com o valor de R$ 18 mil foram adquiridos 300 livros que v\u00e3o refor\u00e7ar o acervo bibliotec\u00e1rio de 12 unidades educacionais de Feira. Esta a\u00e7\u00e3o alcan\u00e7a o Col\u00e9gio Estadual Itan Guimar\u00e3es Cerqueira, no povoado de Santa Quit\u00e9ria; Col\u00e9gio Estadual do Campo Padre Henrique Alves Borges, no distrito de Humildes; Col\u00e9gio Estadual do Campo Maria Quit\u00e9ria e Centro Territorial de Educa\u00e7\u00e3o Profissional do Portal do Sert\u00e3o, ambos no distrito de Maria Quit\u00e9ria; Col\u00e9gio Estadual do Campo Jo\u00e3o Baptista Carneiro e Col\u00e9gio Estadual do Campo Edivaldo Machado Boaventura, ambos no distrito de Ipua\u00e7u; Col\u00e9gio Estadual do Campo de Jaguara, no distrito de Jaguara; Centro Educacional Cenecista do Campo C\u00f4nego Cupertino de Lacerda, no distrito de Bonfim de Feira; Col\u00e9gio Estadual de Tempo Integral Assis Chateaubriand; Col\u00e9gio Estadual de Tempo Integral Carolina Maria de Jesus; Col\u00e9gio Estadual de Tempo Integral Edith Machado Boaventura e Col\u00e9gio Estadual de Tempo Integral C\u00e9lia Santos Andrade. Cada unidade escolar receber\u00e1 um kit com 25 livros de diversos tipos de obras liter\u00e1rias.<\/p>\n\n\n\n<p>Os investimentos em Feira de Santana n\u00e3o param por a\u00ed. A Secretaria da Educa\u00e7\u00e3o do Estado (SEC) e a Companhia de Desenvolvimento Urbano (Conder) foram autorizadas a iniciar o processo licitat\u00f3rio para amplia\u00e7\u00e3o, com moderniza\u00e7\u00e3o, do Col\u00e9gio Estadual do Campo Maria Quit\u00e9ria, no distrito de Maria Quit\u00e9ria. Ser\u00e3o destinados R$ 17,7 milh\u00f5es para implanta\u00e7\u00e3o de salas, laborat\u00f3rios, restaurante, teatro, campo de futebol society com pista de atletismo, reforma e cobertura de quadra poliesportiva, al\u00e9m da requalifica\u00e7\u00e3o do pr\u00e9dio existente.<\/p>\n\n\n\n<p>O trabalho conjunto dos dois \u00f3rg\u00e3os tamb\u00e9m foi autorizado para a constru\u00e7\u00e3o de uma nova unidade escolar de tempo integral na comunidade quilombola de Matinha. Jer\u00f4nimo, acompanhado de diretores da Conder e da secret\u00e1ria Rowenna Brito, conheceu o projeto do pr\u00e9dio, que ser\u00e1 erguido seguindo o novo padr\u00e3o adotado pela gest\u00e3o estadual. O aporte estimado \u00e9 de R$ 20,6 milh\u00f5es. De acordo com a secret\u00e1ria da Educa\u00e7\u00e3o, Rowenna Brito, o governo baiano vem fazendo um grande investimento no setor para oferecer melhores oportunidades aos cidad\u00e3os.<\/p>\n\n\n\n<p>\u201cNa Bahia inteira n\u00f3s estamos com uma s\u00e9rie de investimentos. Estamos falando de R$ 5,4 bilh\u00f5es investidos nas obras, na reestrutura\u00e7\u00e3o das unidades escolares para esse novo padr\u00e3o que voc\u00eas j\u00e1 conhecem, com quadra, salas climatizadas\u201d, explicou a gestora, frisando que s\u00f3 em Feira de Santana foram inauguradas tr\u00eas escolas em tempo integral nos \u00faltimos meses.<\/p>\n\n\n\n<p>Por meio da parceria entre as Secretarias da Educa\u00e7\u00e3o e da Sa\u00fade teve in\u00edcio nesta quinta as atividades do Odontom\u00f3vel, servi\u00e7o de atendimento odontol\u00f3gico que percorre as escolas da rede estadual. O chefe do executivo baiano conferiu de perto as instala\u00e7\u00f5es. Por meio desta a\u00e7\u00e3o, que integra o projeto Sa\u00fade Mais Perto, os 1.154 estudantes do Col\u00e9gio Estadual do Campo Maria Quit\u00e9ria ter\u00e3o acesso a procedimentos de limpeza e retirada de placa bacteriana, aplica\u00e7\u00e3o de fl\u00faor, restaura\u00e7\u00f5es, tratamento de canal e de doen\u00e7as da gengiva, extra\u00e7\u00e3o dent\u00e1ria, orienta\u00e7\u00f5es para o cuidado bucal. O caminh\u00e3o fica estacionado no local at\u00e9 o pr\u00f3ximo dia 14. Ao fim deste per\u00edodo, se dirige para outras unidades da rede. Esta etapa tem um investimento de R$ 442 mil. A secret\u00e1ria da Sa\u00fade, Roberta Santana, lembrou do retorno de outra parceria com a SEC, para imuniza\u00e7\u00e3o da comunidade escolar.<\/p>\n\n\n\n<p>\u201cMais de 1.900 escolas participaram do programa e agora a gente volta, a partir do dia 12, a vacinar dentro da escola, porque a vacina salva vidas e a gente precisa refor\u00e7ar a preven\u00e7\u00e3o, o diagn\u00f3stico, para que a gente n\u00e3o tenha agravamento da sa\u00fade\u201d. A secret\u00e1ria lembrou que 58 mil estudantes j\u00e1 foram alcan\u00e7ados pela a\u00e7\u00e3o.<\/p>\n\n\n\n<p>O N\u00facleo Territorial de Educa\u00e7\u00e3o 19 (NTE 19), Portal do Sert\u00e3o, \u00e9 respons\u00e1vel por 68 col\u00e9gios e anexos, distribu\u00eddos em 17 cidades. Deste total de unidades de ensino, 46 est\u00e3o localizadas em Feira de Santana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante visita \u00e0 \u201cPrincesinha do Sert\u00e3o\u201d nesta quinta-feira (8), o governador Jer\u00f4nimo Rodrigues inaugurou e autorizou obras na \u00e1rea da educa\u00e7\u00e3o, que contemplam estudantes da sede e tamb\u00e9m de distritos de Feira de Santana. Os investimentos no setor ultrapassam os R$ 60 milh\u00f5es. Entre as a\u00e7\u00f5es, foi entregue a amplia\u00e7\u00e3o do Col\u00e9gio Estadual de Tempo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25106,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-25105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25105"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25105\/revisions"}],"predecessor-version":[{"id":25108,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25105\/revisions\/25108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25106"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}