{"id":25229,"date":"2024-08-19T10:13:03","date_gmt":"2024-08-19T13:13:03","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25229"},"modified":"2024-08-19T10:13:03","modified_gmt":"2024-08-19T13:13:03","slug":"acrilamida-causa-cancer-entenda-os-perigos-de-ingerir-a-substancia","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/19\/acrilamida-causa-cancer-entenda-os-perigos-de-ingerir-a-substancia\/","title":{"rendered":"Acrilamida causa c\u00e2ncer? Entenda os perigos de ingerir a subst\u00e2ncia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-64-1024x576.png\" alt=\"\" class=\"wp-image-25240\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-64-1024x576.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-64-300x169.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-64-768x432.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-64-1536x864.png 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-64.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagem Shutterstock\/Foto EvanLorne<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Imagine uma subst\u00e2ncia que surge durante o preparo dos alimentos e, ainda pode causar c\u00e2ncer. Esse \u00e9 o caso da acrilamida, descoberta em 2002 por pesquisadores suecos, o composto \u00e9 presente em alimentos, quando submetidos a temperaturas muito elevadas.<\/p>\n\n\n\n<p>Ent\u00e3o, quando exageramos no cozimento dos alimentos, al\u00e9m da perda de textura, sabor original, nutrientes e vitaminas, ainda podemos estar ingerindo uma subst\u00e2ncia cancer\u00edgena. Mas quando exatamente corremos tal risco? Que tipos de alimentos geram tal composto? Entenda a seguir.<\/p>\n\n\n\n<p><strong>Acrilamida \u00e9 cancer\u00edgena?<\/strong><\/p>\n\n\n\n<p>De acordo com um artigo da Fiocruz, embora os dados dispon\u00edveis sejam limitados na avalia\u00e7\u00e3o de risco da acrilamida em induzir tumores na popula\u00e7\u00e3o humana, ela foi classificada como um prov\u00e1vel carcin\u00f3geno humano, Grupo 2A, em 1994, pela Ag\u00eancia Internacional de Pesquisa em C\u00e2ncer (IARC), na Fran\u00e7a.<\/p>\n\n\n\n<p>Outro Relat\u00f3rio sobre Carcin\u00f3genos do Programa Nacional de Toxicologia dos EUA, tamb\u00e9m classificou a acrilamida como pertence ao grupo 2A, o que significa que o composto est\u00e1 entre os \u201ccarcin\u00f3genos prov\u00e1veis\u201d.<\/p>\n\n\n\n<p>Por outro lado, estudos toxicol\u00f3gicos demonstraram que os seres humanos e os roedores n\u00e3o s\u00f3 absorvem a acrilamida em taxas diferentes, como tamb\u00e9m a metabolizam de forma diferente.<\/p>\n\n\n\n<p>No Brasil, a Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa) orienta a popula\u00e7\u00e3o a ter cautela na ingest\u00e3o de alimentos que possam liberar tal subst\u00e2ncia. No entanto, deixa claro que ainda n\u00e3o foi poss\u00edvel comprovar o efeito carcinog\u00eanico da acrilamida observado em ratos nos seres humanos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-62.png\" alt=\"\" class=\"wp-image-25241\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-62.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-62-300x169.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-62-768x432.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagem Shutterstock\/Foto joshimerbin<\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong>Acrilamida: alimentos piores para consumir<\/strong><\/p>\n\n\n\n<p>Antes de mais nada, vamos entender qual o processo \u00e9 o gerador da acrilamida, denominado de rea\u00e7\u00e3o Maillard. Esse tipo de situa\u00e7\u00e3o acontece por meio da rea\u00e7\u00e3o de a\u00e7\u00facares e amino\u00e1cidos presentes em alimentos submetidos a altas temperaturas, geralmente acima de 120 \u00baC.<\/p>\n\n\n\n<p>Um bom exemplo, \u00e9 quando os alimentos mudam de aspecto ap\u00f3s sofrerem com altas temperaturas. Isso \u00e9 o que ocorre quando fazemos o nosso famoso \u201cp\u00e3o na chapa\u201d, por exemplo.<\/p>\n\n\n\n<p>Na maioria dos casos, a subst\u00e2ncia est\u00e1 presente em alimentos ricos em amido, como batata chips, batata frita industrializada, batata frita pr\u00e9-frita, batata frita feita em casa, p\u00e3es de leite, biscoitos (principalmente os recheados), mistura para mingau infantil, cereais matinais e at\u00e9 o simples caf\u00e9 instant\u00e2neo.<\/p>\n\n\n\n<p><strong>Por que a acrilamida \u00e9 perigosa no contexto atual?<\/strong><\/p>\n\n\n\n<p>De acordo com especialistas, alguns testes indicam altera\u00e7\u00f5es neurol\u00f3gicas, tumores (c\u00e2ncer) na regi\u00e3o ocular, altera\u00e7\u00f5es morfol\u00f3gicas nos nervos e tumores de mama para concentra\u00e7\u00f5es de 0,2 mg\/kg de peso corporal por dia.<\/p>\n\n\n\n<p>Embora, a estimativa indique que uma pessoa altamente exposta \u00e0 acrilamida por meio de alimenta\u00e7\u00e3o, consuma cerca de 0,004 mg\/kg de peso corporal por dia, os seus efeitos na sa\u00fade n\u00e3o devem passar despercebidos.<\/p>\n\n\n\n<p>Afinal de contas, houve muitas mudan\u00e7as no padr\u00e3o alimentar atualmente, fazendo que muitas pessoas n\u00e3o percebam o qu\u00e3o exagerado possa ser o consumo de produtos industrializados e ricos em amido. Sobretudo, porque em muitos pa\u00edses n\u00e3o existe ainda nenhuma regulamenta\u00e7\u00e3o espec\u00edfica para o consumo da subst\u00e2ncia.<\/p>\n\n\n\n<p>No entanto, em 2017, a Uni\u00e3o Europeia fez uma regulamenta\u00e7\u00e3o para que operadores de empresas do setor alimentar reduzam a presen\u00e7a de acrilamida nos alimentos.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Olhar Digital<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagine uma subst\u00e2ncia que surge durante o preparo dos alimentos e, ainda pode causar c\u00e2ncer. Esse \u00e9 o caso da acrilamida, descoberta em 2002 por pesquisadores suecos, o composto \u00e9 presente em alimentos, quando submetidos a temperaturas muito elevadas. Ent\u00e3o, quando exageramos no cozimento dos alimentos, al\u00e9m da perda de textura, sabor original, nutrientes e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25240,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-25229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25229"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25229\/revisions"}],"predecessor-version":[{"id":25242,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25229\/revisions\/25242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25240"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}