{"id":25257,"date":"2024-08-21T15:25:53","date_gmt":"2024-08-21T18:25:53","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25257"},"modified":"2024-08-27T09:34:45","modified_gmt":"2024-08-27T12:34:45","slug":"atraves-de-emenda-parlamentar-de-luciano-araujo-sao-domingos-e-contemplado-com-ambulancia","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/21\/atraves-de-emenda-parlamentar-de-luciano-araujo-sao-domingos-e-contemplado-com-ambulancia\/","title":{"rendered":"Atrav\u00e9s de emenda parlamentar de Luciano Araujo, S\u00e3o Domingos \u00e9 contemplado com ambul\u00e2ncia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"776\" height=\"467\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/luciano_ambulancia_sd.jpg\" alt=\"\" class=\"wp-image-25258\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/luciano_ambulancia_sd.jpg 776w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/luciano_ambulancia_sd-300x181.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/luciano_ambulancia_sd-768x462.jpg 768w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><\/figure>\n<\/div>\n\n\n<p>Atrav\u00e9s de uma emenda parlamentar do deputado estadual e presidente do Solidariedade na Bahia, Luciano Ara\u00fajo, o munic\u00edpio de S\u00e3o Domingos foi contemplado, hoje (20), com uma ambul\u00e2ncia. Al\u00e9m dele, a entrega do equipamento contou com a presen\u00e7a do governador Jer\u00f4nimo Rodrigues (PT), da secret\u00e1ria estadual de Sa\u00fade, Roberta Santana, e da secret\u00e1ria municipal de Sa\u00fade de S\u00e3o Domingos, Kelcya Cunha.&nbsp; O ato ocorreu no p\u00e1tio da Secretaria de Sa\u00fade do Estado da Bahia.&nbsp; &nbsp;&nbsp;<\/p>\n\n\n\n<p>&#8220;Comemoro a entrega de uma ambul\u00e2ncia para o munic\u00edpio de S\u00e3o Domingos, que \u00e9 o resultado de uma emenda parlamentar de nossa autoria. E nosso mandato parlamentar est\u00e1 sendo recordista, nesta legislatura, em entrega de ambul\u00e2ncias para a Regi\u00e3o do Sisal, atrav\u00e9s de emendas parlamentares. Coit\u00e9 e Valente j\u00e1 foram contemplados com esses equipamentos e agora chegou a vez de S\u00e3o Domingos. Tenho certeza que este equipamento ser\u00e1 de muita utilidade para as pessoas que necessitam deste atendimento num momento muito dif\u00edcil. Trabalhamos por toda a Bahia e beneficiar a Regi\u00e3o do Sisal tem sido um dos maiores focos do nosso mandato&#8221;, disse Luciano Araujo.<\/p>\n\n\n\n<p>Outros munic\u00edpios tamb\u00e9m foram contemplados hoje pelo Governo do Estado da Bahia. No total, foram 50 ambul\u00e2ncias e nove ve\u00edculos de Transporte Fora do Domic\u00edlio (TFD). A a\u00e7\u00e3o, de acordo com a gest\u00e3o estadual, tem como objetivo a amplia\u00e7\u00e3o no acesso ao atendimento de emerg\u00eancia e a melhoria no transporte de pacientes no interior da Bahia&#8221;.<\/p>\n\n\n\n<p>Hospital da Regi\u00e3o do Sisal<\/p>\n\n\n\n<p>Em outra a\u00e7\u00e3o para beneficiar a regi\u00e3o na \u00e1rea de sa\u00fade, em maio de 2023 Luciano Araujo apresentou uma indica\u00e7\u00e3o endere\u00e7ada ao governador Jer\u00f4nimo Rodrigues para a implanta\u00e7\u00e3o do Hospital Regional da Regi\u00e3o Sisaleira.<\/p>\n\n\n\n<p>O projeto para a constru\u00e7\u00e3o do Hospital Regional do Sisal est\u00e1 inclu\u00eddo no novo PAC. O governador Jer\u00f4nimo Rodrigues definir\u00e1, ap\u00f3s di\u00e1logos com os prefeitos da regi\u00e3o, em qual munic\u00edpio ser\u00e1 constru\u00eddo.<\/p>\n\n\n\n<p>&#8220;Desde o in\u00edcio da atual gest\u00e3o estadual uma das minhas prioridades foi solicitar ao governador Jer\u00f4nimo Rodrigues a implanta\u00e7\u00e3o do Hospital Regional do Sisal&#8221;, disse Araujo.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Fonte: Ascom do deputado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atrav\u00e9s de uma emenda parlamentar do deputado estadual e presidente do Solidariedade na Bahia, Luciano Ara\u00fajo, o munic\u00edpio de S\u00e3o Domingos foi contemplado, hoje (20), com uma ambul\u00e2ncia. Al\u00e9m dele, a entrega do equipamento contou com a presen\u00e7a do governador Jer\u00f4nimo Rodrigues (PT), da secret\u00e1ria estadual de Sa\u00fade, Roberta Santana, e da secret\u00e1ria municipal de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25258,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-25257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25257"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25257\/revisions"}],"predecessor-version":[{"id":25259,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25257\/revisions\/25259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25258"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}