{"id":25268,"date":"2024-08-22T16:44:36","date_gmt":"2024-08-22T19:44:36","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25268"},"modified":"2024-08-22T16:44:36","modified_gmt":"2024-08-22T19:44:36","slug":"gusttavo-lima-corta-bebida-alcoolica-apos-recomendacao-medica-tempo-de-mudanca","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/22\/gusttavo-lima-corta-bebida-alcoolica-apos-recomendacao-medica-tempo-de-mudanca\/","title":{"rendered":"Gusttavo Lima corta bebida alco\u00f3lica ap\u00f3s recomenda\u00e7\u00e3o m\u00e9dica: &#8220;Tempo de mudan\u00e7a&#8221;"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-68-1024x538.png\" alt=\"\" class=\"wp-image-25275\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-68-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-68-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-68-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-68.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Instagram<\/figcaption><\/figure>\n<\/div>\n\n\n<p>O \u00e1lcool n\u00e3o faz mais parte da realidade do cantor Gusttavo Lima, pelo menos at\u00e9 2025. A decis\u00e3o de parar de consumir bebidas alco\u00f3licas foi tomada pelo sertanejo ap\u00f3s uma recomenda\u00e7\u00e3o m\u00e9dica devido a problemas de sa\u00fade.<\/p>\n\n\n\n<p>Durante uma apresenta\u00e7\u00e3o na cidade de Brumadinho, em Minas Gerais, o artista revelou que foi diagnosticado com problemas no f\u00edgado e, por isso, pararia de beber at\u00e9 o ano que vem.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"pt\" dir=\"ltr\">Durante o @brumadinhorodeiofestival, <a href=\"https:\/\/twitter.com\/gusttavo_lima?ref_src=twsrc%5Etfw\">@gusttavo_lima<\/a> chamou aten\u00e7\u00e3o dos f\u00e3s por ficar s\u00f3 no caf\u00e9 em todo o show. Com o microfone em m\u00e3os, o Embaixador disse que s\u00f3 voltar\u00e1 a consumir bebidas alco\u00f3licas em janeiro, por orienta\u00e7\u00e3o m\u00e9dica. No mesmo show, o cantor revelou que pretende\u2026 <a href=\"https:\/\/t.co\/vzj8zesRGV\">pic.twitter.com\/vzj8zesRGV<\/a><\/p>&mdash; Conceito Sertanejo (@conceito_sert) <a href=\"https:\/\/twitter.com\/conceito_sert\/status\/1825632227507450281?ref_src=twsrc%5Etfw\">August 19, 2024<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p>&#8220;Agora volto a beber s\u00f3 em janeiro. \u00c9 tempo de mudan\u00e7a. Fui fazer um exame do meu f\u00edgado e s\u00f3 estava o &#8216;pl\u00e1stico&#8217;. O m\u00e9dico falou: &#8216;Se voc\u00ea continuar bebendo, vai dar ruim&#8217;. Mas nem um vinho? Ele falou: &#8216;Tudo que tem \u00e1lcool, voc\u00ea pode cortar da sua vida&#8217;.&#8221;<\/p>\n\n\n\n<p>Sem o \u00e1lcool, o artista substituiu o l\u00edquido do copo por caf\u00e9. &#8220;Agora estou bebendo caf\u00e9. A gente vai ficando velho e vai bebendo caf\u00e9. Antes, eu andava com garrafa de whisky dentro da mala, agora eu ando com uma de caf\u00e9. Que gra\u00e7a tem? Tem base um trem desse?&#8221;, disse.<\/p>\n\n\n\n<p>Al\u00e9m desta mudan\u00e7a, o artista tamb\u00e9m est\u00e1 com planos de diminuir o tempo na estrada. Em um bate-papo com os f\u00e3s, o cantor afirmou que se dedicar\u00e1 mais a fam\u00edlia, e por isso a m\u00e9dia de shows anual ser\u00e1 drasticamente reduzida.<\/p>\n\n\n\n<p>&#8220;No ano que vem a gente vai fazer uma m\u00e9dia de 50 shows do ano todo. A gente vai ficar com saudade um do outro, mas \u00e9 por uma raz\u00e3o bem gostosa, de fam\u00edlia e de descanso.&#8221;<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O \u00e1lcool n\u00e3o faz mais parte da realidade do cantor Gusttavo Lima, pelo menos at\u00e9 2025. A decis\u00e3o de parar de consumir bebidas alco\u00f3licas foi tomada pelo sertanejo ap\u00f3s uma recomenda\u00e7\u00e3o m\u00e9dica devido a problemas de sa\u00fade. Durante uma apresenta\u00e7\u00e3o na cidade de Brumadinho, em Minas Gerais, o artista revelou que foi diagnosticado com problemas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25275,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-25268","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25268"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25268\/revisions"}],"predecessor-version":[{"id":25276,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25268\/revisions\/25276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25275"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25268"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}