{"id":25328,"date":"2024-08-27T14:19:11","date_gmt":"2024-08-27T17:19:11","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25328"},"modified":"2024-08-27T14:19:11","modified_gmt":"2024-08-27T17:19:11","slug":"bahia-lidera-numero-de-voos-da-america-do-sul-para-o-nordeste-na-alta-temporada","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/27\/bahia-lidera-numero-de-voos-da-america-do-sul-para-o-nordeste-na-alta-temporada\/","title":{"rendered":"Bahia lidera n\u00famero de voos da Am\u00e9rica do Sul para o Nordeste na alta temporada"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-84-1024x681.png\" alt=\"\" class=\"wp-image-25329\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-84-1024x681.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-84-300x200.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-84-768x511.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-84-1536x1021.png 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-84.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto Tatiana Azeviche Ascom SeturBA<\/figcaption><\/figure>\n<\/div>\n\n\n<p>As a\u00e7\u00f5es do Governo do Estado, por meio da Secretaria de Turismo (Setur-BA), nas \u00e1reas de promo\u00e7\u00e3o do destino Bahia e capacita\u00e7\u00e3o de agentes de viagens, nos principais polos emissores de turistas da Am\u00e9rica do Sul, associadas \u00e0 parceria com o Salvador Bahia Airport (Rede Vinci) e empresas de avia\u00e7\u00e3o, resultaram na amplia\u00e7\u00e3o da malha a\u00e9rea baiana internacional.<\/p>\n\n\n\n<p>A partir de 18 de setembro, a Aerol\u00edneas Argentinas ter\u00e1 dois voos semanais de Buenos Aires para Porto Seguro. Em 13 de dezembro, a companhia inicia as linhas di\u00e1rias da capital portenha para Salvador. Ela tamb\u00e9m retomou a rota do destino argentino de C\u00f3rdoba para a capital baiana, uma vez por semana, com in\u00edcio em 4 de janeiro.<\/p>\n\n\n\n<p>A Sky Airline manteve os dois voos diretos de Santiago (Chile) para Salvador, semanalmente, e ampliou as linhas para a capital baiana, com escala em Montevid\u00e9u (Uruguai), para tr\u00eas frequ\u00eancias por semana, come\u00e7ando em 4 de dezembro.<\/p>\n\n\n\n<p>J\u00e1 a Gol Linhas A\u00e9reas aumentou de um para tr\u00eas voos semanais, a liga\u00e7\u00e3o entre as capitais da Argentina e da Bahia, a partir de 27 de dezembro.<\/p>\n\n\n\n<p>\u201cO destaque \u00e9 a volta da linha de C\u00f3rdoba, um polo emissor de turistas importante. Teremos um total de 16 voos, todas as semanas, ligando a Am\u00e9rica do Sul \u00e0 Bahia, o que coloca o estado na lideran\u00e7a, em n\u00famero de opera\u00e7\u00f5es a\u00e9reas do continente para o Nordeste brasileiro\u201d, ressalta o gerente de Marketing e Neg\u00f3cios da Vinci no Brasil, Marcus Campos.<\/p>\n\n\n\n<p>\u201cO Governo do Estado negociou essas rotas, para ampliar o fluxo de turistas sul-americanos na Bahia, visando uma alta temporada recorde de movimenta\u00e7\u00e3o nos aeroportos de Salvador e Porto Seguro. Isso \u00e9 o resultado de uma pol\u00edtica p\u00fablica voltada para o fortalecimento da nossa economia e gera\u00e7\u00e3o de empregos, por meio da ind\u00fastria do turismo, com inova\u00e7\u00e3o e sustentabilidade\u201d, explica o titular da Setur-BA, Maur\u00edcio Bacelar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As a\u00e7\u00f5es do Governo do Estado, por meio da Secretaria de Turismo (Setur-BA), nas \u00e1reas de promo\u00e7\u00e3o do destino Bahia e capacita\u00e7\u00e3o de agentes de viagens, nos principais polos emissores de turistas da Am\u00e9rica do Sul, associadas \u00e0 parceria com o Salvador Bahia Airport (Rede Vinci) e empresas de avia\u00e7\u00e3o, resultaram na amplia\u00e7\u00e3o da malha [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25329,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-25328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25328"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25328\/revisions"}],"predecessor-version":[{"id":25330,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25328\/revisions\/25330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25329"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}