{"id":25355,"date":"2024-08-29T08:07:50","date_gmt":"2024-08-29T11:07:50","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25355"},"modified":"2024-08-29T08:07:50","modified_gmt":"2024-08-29T11:07:50","slug":"policlinica-de-escada-ultrapassa-a-marca-de-500-mil-atendimentos-e-assegura-resolutividade-para-milhares-de-soteropolitanos","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/29\/policlinica-de-escada-ultrapassa-a-marca-de-500-mil-atendimentos-e-assegura-resolutividade-para-milhares-de-soteropolitanos\/","title":{"rendered":"Policl\u00ednica de Escada ultrapassa a marca de 500 mil atendimentos e assegura resolutividade para milhares de soteropolitanos"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"490\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/ff04158e-d4d0-4925-9243-30bba7f069b4.jpg\" alt=\"\" class=\"wp-image-25357\" style=\"width:602px;height:auto\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/ff04158e-d4d0-4925-9243-30bba7f069b4.jpg 600w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/ff04158e-d4d0-4925-9243-30bba7f069b4-300x245.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o Ascom FESF-SUS<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Quando a assistente social Ana L\u00facia Garrido esteve na Policl\u00ednica Regional de Escada pela primeira vez, as d\u00favidas sobre o atendimento eram in\u00fameras. \u201cN\u00e3o sabia direito como funcionava, mas me surpreendi com a possibilidade de eu mesma poder agendar meus atendimentos pelo aplicativo\u201d, lembra.<\/p>\n\n\n\n<p>Hoje, ap\u00f3s dois anos de opera\u00e7\u00e3o, Ana L\u00facia conta que a policl\u00ednica fez a diferen\u00e7a na vida dela e de toda a comunidade. \u201cResolvi fazer a carta em agradecimento a todo o carinho e compet\u00eancia que encontro aqui na Policl\u00ednica de Escada. Sempre fui muito bem atendida por uma equipe maravilhosa, tendo a possibilidade de ter acesso a diversas especialidades m\u00e9dicas\u201d, completa.<\/p>\n\n\n\n<p>Assim como Ana L\u00facia, nos \u00faltimos dois anos a Policl\u00ednica Regional de Escada, unidade da Secretaria da Sa\u00fade da Bahia (Sesab) gerida pela Funda\u00e7\u00e3o Estatal Sa\u00fade da Fam\u00edlia (FESF-SUS), assegurou assist\u00eancia de excel\u00eancia para milhares de baianos, ultrapassando a marca de 500 mil atendimentos.<\/p>\n\n\n\n<p>Desde a sua inaugura\u00e7\u00e3o, em junho de 2022, a Policl\u00ednica de Escada realizou um total de 504.436 atendimentos, sendo 427.859 procedimentos com finalidade diagn\u00f3stica e 76.577 consultas. Em 2023, foram realizados 230.608 atendimentos, contribuindo para amenizar a baixa cobertura da Aten\u00e7\u00e3o Prim\u00e1ria de Salvador, tendo em vista a falta de m\u00e9dicos especialistas na rede municipal.<\/p>\n\n\n\n<p>\u201cA marca de 500 mil atendimentos na Policl\u00ednica de Escada \u00e9 um marco que representa mais do que apenas n\u00fameros. Ela simboliza o resultado de um trabalho feito a muitas m\u00e3os, um esfor\u00e7o coletivo que envolveu dedica\u00e7\u00e3o, planejamento e compromisso com a qualidade em cada atendimento realizado\u201d, afirma o diretor na unidade, Heder Silva.<\/p>\n\n\n\n<p>A Policl\u00ednica Regional de Escada oferece consultas em anestesiologia, angiologia, cardiologia, coloproctologia, endocrinologia, gastroenterologia, cirurgia-geral, ginecologia, otorrinolaringologia, mastologia, al\u00e9m de avalia\u00e7\u00f5es com a equipe de enfermagem.<\/p>\n\n\n\n<p>No local, a popula\u00e7\u00e3o tamb\u00e9m tem a possibilidade de realizar exames como ultrassonografia, ultrassom, ultrassonografia com doppler, ecocardiografia, tomografia, eletrocardiograma, teste ergom\u00e9trico, videolaringoscopia, bi\u00f3psia mam\u00e1ria, endoscopia digestiva alta, colonoscopia\/retossigmoidoscopia, histeroscopia, citopatol\u00f3gicos e colposcopia. Procedimentos que necessitam de contraste s\u00e3o acompanhados por profissionais m\u00e9dicos, com resultados entregues em at\u00e9 oito dias. Al\u00e9m da sala do p\u00e9 diab\u00e9tico com acompanhamento da equipe multiprofissional.<\/p>\n\n\n\n<p>Secret\u00e1ria da Sa\u00fade da Bahia, Roberta Santana, destaca a resolutividade das policl\u00ednicas, modelo que vem sendo implantado em toda a Bahia. \u201cA Policl\u00ednica de Escada \u00e9 um caso de sucesso, os mais de 500 mil atendimentos mostram que esse \u00e9 um modelo que deu certo e conta com a ades\u00e3o da popula\u00e7\u00e3o. Nas policl\u00ednicas \u00e9 poss\u00edvel resolver diversos problemas de sa\u00fade, sem a necessidade de o paciente sair da sua regi\u00e3o, exemplificando de forma simples o que chamamos de regionaliza\u00e7\u00e3o da sa\u00fade\u201d, explica.<\/p>\n\n\n\n<p><strong>Saiba como agendar<\/strong><\/p>\n\n\n\n<p>O atendimento \u00e9 realizado de segunda a sexta-feira, das 8h \u00e0s 17h, mediante agendamento digital ou por telefone. Os interessados podem acessar os servi\u00e7os pelo SAC Digital (<a href=\"https:\/\/www.sacdigital.ba.gov.br\/\">www.sacdigital.ba.gov.br<\/a>&nbsp;ou aplicativo) e pelo telefone 0800 071 5353, realizando o cadastro e enviando os documentos necess\u00e1rios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando a assistente social Ana L\u00facia Garrido esteve na Policl\u00ednica Regional de Escada pela primeira vez, as d\u00favidas sobre o atendimento eram in\u00fameras. \u201cN\u00e3o sabia direito como funcionava, mas me surpreendi com a possibilidade de eu mesma poder agendar meus atendimentos pelo aplicativo\u201d, lembra. Hoje, ap\u00f3s dois anos de opera\u00e7\u00e3o, Ana L\u00facia conta que a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25357,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-25355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25355"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25355\/revisions"}],"predecessor-version":[{"id":25358,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25355\/revisions\/25358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25357"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}