{"id":25366,"date":"2024-08-29T16:31:05","date_gmt":"2024-08-29T19:31:05","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25366"},"modified":"2024-08-29T16:31:05","modified_gmt":"2024-08-29T19:31:05","slug":"relembre-ultima-partida-em-que-o-vitoria-venceu-o-vasco-no-brasileirao","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/08\/29\/relembre-ultima-partida-em-que-o-vitoria-venceu-o-vasco-no-brasileirao\/","title":{"rendered":"Relembre \u00faltima partida em que o Vit\u00f3ria venceu o Vasco no Brasileir\u00e3o"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-95-1024x538.png\" alt=\"\" class=\"wp-image-25372\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-95-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-95-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-95-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/08\/image-95.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Carlos Greg\u00f3rio Jr\/Vasco<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Na noite deste domingo (1\u00ba), o Vit\u00f3ria recebe o Vasco da Gama, pela 25\u00aa rodada do Campeonato Brasileiro, \u00e0s 18h30, no Manoel Barradas. H\u00e1 seis anos, as equipes se enfrentaram no mesmo est\u00e1dio, pela 24\u00aa rodada do Brasileir\u00e3o de 2018. Na ocasi\u00e3o, o Le\u00e3o venceu por 1 a 0.<\/p>\n\n\n\n<p>Naquela ocasi\u00e3o, o Rubro-Negro Baiano, comandado por Paulo C\u00e9sar Carpegiani, iniciou a partida com Ronaldo; Jeferson, Lucas Ribeiro, Ramon e Fabiano; L\u00e9o Gomes, Rodrigo Andrade e Marcelo Meli; Erick, Neilton e L\u00e9o Cear\u00e1. Andr\u00e9 Lima, Lucas Fernandes e Aderllan entraram durante o jogo.<\/p>\n\n\n\n<p>J\u00e1 o Cruzmaltino, sob o comando de Alberto Valentim, escalou Mart\u00edn Silva; Lenon, Luiz Gustavo, Werley e Ramon; Leandro Des\u00e1bato, Willian Maranh\u00e3o, Wagner e Raul; Andr\u00e9s Rios e Maxi L\u00f3pez. Yago Pikachu, Marrony e Kelvin foram os substitutos utilizados.<\/p>\n\n\n\n<p>O gol da vit\u00f3ria rubro-negra foi marcado por Erick aos 73 minutos do segundo tempo. Curiosamente, Lucas Ribeiro foi expulso dois minutos depois, e o Le\u00e3o da Barra jogou os \u00faltimos 15 minutos com um jogador a menos.<\/p>\n\n\n\n<p>Com esse resultado, o Vit\u00f3ria subiu para a 12\u00aa posi\u00e7\u00e3o na tabela e abriu cinco pontos da zona de rebaixamento, enquanto o Vasco caiu para a 16\u00aa posi\u00e7\u00e3o, empatado em pontos com Sport e Cear\u00e1, que estavam na zona de degola.<\/p>\n\n\n\n<p>Apesar da melhora na tabela ap\u00f3s esse confronto, o Vit\u00f3ria acabou sendo rebaixado para a S\u00e9rie B ao final do campeonato, com apenas 37 pontos. Al\u00e9m do time baiano, Paran\u00e1, Sport e Am\u00e9rica-MG foram rebaixados. O Gigante da Colina, por sua vez, escapou da degola por apenas tr\u00eas pontos.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite deste domingo (1\u00ba), o Vit\u00f3ria recebe o Vasco da Gama, pela 25\u00aa rodada do Campeonato Brasileiro, \u00e0s 18h30, no Manoel Barradas. H\u00e1 seis anos, as equipes se enfrentaram no mesmo est\u00e1dio, pela 24\u00aa rodada do Brasileir\u00e3o de 2018. Na ocasi\u00e3o, o Le\u00e3o venceu por 1 a 0. Naquela ocasi\u00e3o, o Rubro-Negro Baiano, comandado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25372,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-25366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25366"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25366\/revisions"}],"predecessor-version":[{"id":25373,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25366\/revisions\/25373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25372"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}