{"id":25529,"date":"2024-09-09T18:00:04","date_gmt":"2024-09-09T21:00:04","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25529"},"modified":"2024-09-09T18:00:04","modified_gmt":"2024-09-09T21:00:04","slug":"ministra-diz-que-queimadas-tem-impacto-forte-no-sistema-de-saude","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/09\/09\/ministra-diz-que-queimadas-tem-impacto-forte-no-sistema-de-saude\/","title":{"rendered":"Ministra diz que queimadas t\u00eam impacto forte no sistema de sa\u00fade"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-35-1024x613.png\" alt=\"\" class=\"wp-image-25539\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-35-1024x613.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-35-300x179.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-35-768x459.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-35.png 1170w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Marcelo Camargo\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Apesar de n\u00e3o faltarem leitos, o grande volume de queimadas no pa\u00eds tem pressionado o sistema de sa\u00fade e causa preocupa\u00e7\u00e3o, principalmente com idosos e crian\u00e7as com problemas respirat\u00f3rios. O diagn\u00f3stico foi feito nesta segunda-feira (9) pela ministra da Sa\u00fade, N\u00edsia Trindade.<\/p>\n\n\n\n<p>\u201cH\u00e1 um impacto forte no sistema de sa\u00fade, nas unidades de sa\u00fade, uma maior procura e, principalmente, uma preocupa\u00e7\u00e3o n\u00e3o s\u00f3 com os efeitos de curto prazo, mas tamb\u00e9m de m\u00e9dio prazo na sa\u00fade das pessoas\u201d, disse a ministra.<\/p>\n\n\n\n<p>N\u00edsia Trindade ressaltou que \u201cneste momento, n\u00e3o estamos vivendo uma situa\u00e7\u00e3o, desse ponto de vista, de falta de leitos acentuada\u201d.<\/p>\n\n\n\n<p>As declara\u00e7\u00f5es da ministra foram feitas ap\u00f3s participa\u00e7\u00e3o na abertura de confer\u00eancia com institutos nacionais de sa\u00fade p\u00fablica, no Rio de Janeiro. O encontro aconteceu no \u00e2mbito do G20, grupo que re\u00fane as maiores economias do mundo.<\/p>\n\n\n\n<p>De acordo com o Programa Queimadas, do Instituto Nacional de Pesquisas Espaciais (Inpe), o pa\u00eds iniciou o m\u00eas de setembro com mais de 154 mil focos de calor registrados no ano. A Amaz\u00f4nia concentra 42,7% dos focos. Embora a Amaz\u00f4nia seja o bioma mais atingido, o munic\u00edpio mais afetado foi Corumb\u00e1, em Mato Grosso do Sul, onde o bioma predominante \u00e9 o Pantanal, e foram detectados 4.245 focos.<\/p>\n\n\n\n<p>Por causa das queimadas, cidades em diversas partes do pa\u00eds foram atingidas por nuvens de fuma\u00e7a, o que prejudica a qualidade do ar.<\/p>\n\n\n\n<p>Segundo a ministra da Sa\u00fade, essa condi\u00e7\u00e3o causa uma \u201csitua\u00e7\u00e3o muito preocupante\u201d em um per\u00edodo que j\u00e1 tende a aumento de casos de s\u00edndrome respirat\u00f3ria aguda grave.<\/p>\n\n\n\n<p>\u201cA grande preocupa\u00e7\u00e3o s\u00e3o com os idosos e as crian\u00e7as, em fun\u00e7\u00e3o dos problemas respirat\u00f3rios\u201d, ressaltou.<\/p>\n\n\n\n<p>\u201cMuitas pessoas sofrem, principalmente quem tem quadros de problemas al\u00e9rgicos, mais intensamente ainda. \u00c9 um motivo de grande aten\u00e7\u00e3o\u201d, disse a ministra.<\/p>\n\n\n\n<p>N\u00edsia Trindade disse que, liderado pelo Minist\u00e9rio do Meio Ambiente e Mudan\u00e7a do Clima (MMA), todo o governo est\u00e1 empenhado no esfor\u00e7o de enfrentar a situa\u00e7\u00e3o. N\u00edsia lembrou que alguns inc\u00eandios t\u00eam origem criminosa, segundo den\u00fancias.<\/p>\n\n\n\n<p>A ministra informou que a For\u00e7a Nacional do Sistema \u00danico de Sa\u00fade (FN-SUS) est\u00e1 em atua\u00e7\u00e3o para auxiliar estados e munic\u00edpios a lidar com os efeitos das queimadas na sa\u00fade humana. \u201cApoiando no que for necess\u00e1rio\u201d, garantiu.<\/p>\n\n\n\n<p>O Minist\u00e9rio da Sa\u00fade orienta que pessoas em regi\u00f5es atingidas por nevoeiros de fuma\u00e7a evitem, ao m\u00e1ximo, a exposi\u00e7\u00e3o ao ar livre e a pr\u00e1tica de atividades f\u00edsicas.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar de n\u00e3o faltarem leitos, o grande volume de queimadas no pa\u00eds tem pressionado o sistema de sa\u00fade e causa preocupa\u00e7\u00e3o, principalmente com idosos e crian\u00e7as com problemas respirat\u00f3rios. O diagn\u00f3stico foi feito nesta segunda-feira (9) pela ministra da Sa\u00fade, N\u00edsia Trindade. \u201cH\u00e1 um impacto forte no sistema de sa\u00fade, nas unidades de sa\u00fade, uma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25539,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-25529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25529"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25529\/revisions"}],"predecessor-version":[{"id":25540,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25529\/revisions\/25540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25539"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}