{"id":25530,"date":"2024-09-09T18:11:55","date_gmt":"2024-09-09T21:11:55","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25530"},"modified":"2024-09-09T18:11:56","modified_gmt":"2024-09-09T21:11:56","slug":"veneno-de-marimbondo-brasileiro-pode-combater-cancer","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/09\/09\/veneno-de-marimbondo-brasileiro-pode-combater-cancer\/","title":{"rendered":"Veneno de marimbondo brasileiro pode combater c\u00e2ncer"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-38-1024x683.png\" alt=\"\" class=\"wp-image-25544\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-38-1024x683.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-38-300x200.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-38-768x512.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-38.png 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Imagem: Judson Castro\/Shutterstock<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Um grupo internacional de pesquisadores fez uma descoberta que pode ajudar a melhorar o tratamento contra o c\u00e2ncer. A equipe, composta inclusive por cientistas da Universidade de Bras\u00edlia (UnB), identificou que uma mol\u00e9cula presente no veneno do marimbondo Chartergellus communis, que vive no cerrado, pode combater tumores.<\/p>\n\n\n\n<p><strong>Resultados promissores contra o c\u00e2ncer de mama e de pele<\/strong><\/p>\n\n\n\n<p>Durante testes realizados em laborat\u00f3rio, os pesquisadores observaram que o pept\u00eddeo Chartergellus-CP1, presente no veneno do animal, pode combater c\u00e9lulas cancer\u00edgenas tanto do c\u00e2ncer de mama quanto do melanoma, tipo mais agressivo do c\u00e2ncer de pele.<\/p>\n\n\n\n<p>Foram testados, com sucesso, as respostas contra duas linhagens de c\u00e9lulas do c\u00e2ncer de mama: o HR+ e o triplo-negativo. Segundo os pesquisadores, a mol\u00e9cula \u201cpode representar uma nova estrat\u00e9gia terap\u00eautica no tratamento do melanoma\u201d.<\/p>\n\n\n\n<p>O pr\u00f3ximo passo \u00e9 realizar novos estudos para aprofundar os efeitos do veneno em modelos de c\u00e9lulas n\u00e3o tumorais, al\u00e9m do potencial terap\u00eautico contra outros tipos de c\u00e2ncer. Os estudos cl\u00ednicos, com a participa\u00e7\u00e3o de humanos, ainda n\u00e3o t\u00eam data para acontecer.<\/p>\n\n\n\n<p>Os resultados foram descritos em estudo publicado na revista Biochimie.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"597\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-37.png\" alt=\"\" class=\"wp-image-25542\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-37.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-37-300x175.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-37-768x448.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Queimadas no cerrado podem colocar popula\u00e7\u00e3o de marimbondos em risco (Imagem: Jose Cruz\/Ag\u00eancia Brasil)<\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong>Devasta\u00e7\u00e3o do cerrado pode colocar em riso o potencial terap\u00eautico<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Os venenos de insetos e\u00a0animais pe\u00e7onhentos\u00a0sempre despertaram interesse cient\u00edfico.<\/li>\n\n\n\n<li>S\u00e3o v\u00e1rios os exemplos de potencial uso medicinal das subst\u00e2ncias.<\/li>\n\n\n\n<li>No caso do veneno do marimbondo, h\u00e1 uma diversidade de compostos com atividade antimicrobiana, anti-inflamat\u00f3ria e antitumoral.<\/li>\n\n\n\n<li>O diferencial do novo estudo \u00e9 que est\u00e1 esp\u00e9cie de inseto sempre foi pouco estudada pela ci\u00eancia.<\/li>\n\n\n\n<li>Al\u00e9m das descobertas, o trabalho aponta para a necessidade de preserva\u00e7\u00e3o da fauna e da flora brasileira.<\/li>\n\n\n\n<li>Os pr\u00f3prios pesquisadores lembram que o cerrado, que \u00e9 o habitat dos marimbondos, \u00e9 um dos biomas mais devastados do pa\u00eds.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-right\">*Olhar Digital<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um grupo internacional de pesquisadores fez uma descoberta que pode ajudar a melhorar o tratamento contra o c\u00e2ncer. A equipe, composta inclusive por cientistas da Universidade de Bras\u00edlia (UnB), identificou que uma mol\u00e9cula presente no veneno do marimbondo Chartergellus communis, que vive no cerrado, pode combater tumores. Resultados promissores contra o c\u00e2ncer de mama e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25544,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-25530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25530"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25530\/revisions"}],"predecessor-version":[{"id":25545,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25530\/revisions\/25545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25544"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}