{"id":25743,"date":"2024-09-26T17:55:03","date_gmt":"2024-09-26T20:55:03","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25743"},"modified":"2024-09-26T17:55:03","modified_gmt":"2024-09-26T20:55:03","slug":"gustavo-mosquito-conta-bastidores-da-sua-chegada-ao-vitoria-questao-de-dias","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/09\/26\/gustavo-mosquito-conta-bastidores-da-sua-chegada-ao-vitoria-questao-de-dias\/","title":{"rendered":"Gustavo Mosquito conta bastidores da sua chegada ao Vit\u00f3ria: &#8220;Quest\u00e3o de dias&#8221;"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-93-1024x538.png\" alt=\"\" class=\"wp-image-25749\" style=\"width:500px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-93-1024x538.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-93-300x158.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-93-768x403.png 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-93.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Victor Ferreira \/ EC Vit\u00f3ria<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Em entrevista ao Podcast do Le\u00e3o na \u00faltima quarta-feira (25), o atacante Gustavo Mosquito falou sobre os bastidores de sua chegada ao Vit\u00f3ria ap\u00f3s ter seu contrato com o Corinthians rescindido. O camisa 7 contou que, ao longo do processo de negocia\u00e7\u00e3o, recebeu uma liga\u00e7\u00e3o do t\u00e9cnico do clube, Thiago Carpini. Mosquito contou que Carpini falou sobre o desejo de contar com ele para o restante da temporada de 2024.<\/p>\n\n\n\n<p>\u201cEu estava em casa, porque tinha sa\u00eddo do Corinthians. Estava treinando em casa, doido para voltar a jogar. J\u00e1 estava ficando ansioso. Estava treinando, mas n\u00e3o \u00e9 a mesma coisa que voc\u00ea estar em um clube. Mas chegou a proposta do Vit\u00f3ria. Foi quest\u00e3o de dias para resolver. Fiquei muito feliz com o convite. Carpini ligou para refor\u00e7ar o desejo de eu vir\u201d, disse o camisa 7.<\/p>\n\n\n\n<p>Logo na chegada, o jogador caiu nas gra\u00e7as da torcida. Em tr\u00eas jogos disputados, o atacante j\u00e1 conta com um gol e uma assist\u00eancia pelo Le\u00e3o, que luta pela perman\u00eancia na S\u00e9rie A do Campeonato Brasileiro.<\/p>\n\n\n\n<p>\u201cEu fui muito bem recebido pelo grupo, pelos torcedores, pela diretoria, comiss\u00e3o t\u00e9cnica. \u00c9 muito importante para um atleta se sentir bem, leve. Feliz por esse momento. \u00c9 uma responsabilidade muito grande vestir a camisa do Vit\u00f3ria nesse momento que estamos passando. Pude dar essa resposta r\u00e1pida, o que n\u00e3o \u00e9 o normal. Eu estava h\u00e1 dois meses sem jogar. Espero ficar muito tempo no Vit\u00f3ria para conquistar coisas grandes\u201d, destacou Gustavo.<\/p>\n\n\n\n<p>Com 28 pontos, o Vit\u00f3ria ocupa a 16\u00aa coloca\u00e7\u00e3o na tabela do Brasileir\u00e3o. A pontua\u00e7\u00e3o \u00e9 a mesma do Corinthians, primeiro time da zona. O pr\u00f3ximo desafio do Le\u00e3o ser\u00e1 diante do Internacional, no domingo (29), \u00e0s 18h30, no Beira-Rio, em partida v\u00e1lida pela 28\u00aa rodada da competi\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Bahia Not\u00edcias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em entrevista ao Podcast do Le\u00e3o na \u00faltima quarta-feira (25), o atacante Gustavo Mosquito falou sobre os bastidores de sua chegada ao Vit\u00f3ria ap\u00f3s ter seu contrato com o Corinthians rescindido. O camisa 7 contou que, ao longo do processo de negocia\u00e7\u00e3o, recebeu uma liga\u00e7\u00e3o do t\u00e9cnico do clube, Thiago Carpini. Mosquito contou que Carpini [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25749,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-25743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25743"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25743\/revisions"}],"predecessor-version":[{"id":25750,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25743\/revisions\/25750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25749"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}