{"id":25764,"date":"2024-09-27T07:48:33","date_gmt":"2024-09-27T10:48:33","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25764"},"modified":"2024-10-02T07:59:44","modified_gmt":"2024-10-02T10:59:44","slug":"medico-acusado-de-matar-colega-que-morava-e-trabalhava-em-araci-e-condenado-a-17-anos-de-prisao","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/09\/27\/medico-acusado-de-matar-colega-que-morava-e-trabalhava-em-araci-e-condenado-a-17-anos-de-prisao\/","title":{"rendered":"M\u00e9dico acusado de matar colega que morava e trabalhava em Araci \u00e9 condenado a 17 anos de pris\u00e3o"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"616\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-99.png\" alt=\"\" class=\"wp-image-25765\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-99.png 984w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-99-300x188.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-99-768x481.png 768w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><\/figure>\n<\/div>\n\n\n<p>O m\u00e9dico Geraldo Freitas Junior,\u00a0acusado de matar o colega\u00a0acreano Andrade Lopes Santana, foi condenado a 17 anos, 10 meses e 15 dias de reclus\u00e3o, no F\u00f3rum Filinto Barros, em\u00a0Feira de Santana, a 100 km de Salvador.<\/p>\n\n\n\n<p>O julgamento durou 20 horas e contou a presen\u00e7a de amigos e familiares de Andrade Lopes.<\/p>\n\n\n\n<p>O crime ocorreu em maio de 2021 e o julgamento foi agendado inicialmente para dezembro de 2023, por\u00e9m, mas foi adiado ap\u00f3s a defesa de Geraldo Freitas J\u00fanior solicitar a mudan\u00e7a da comarca de origem, alegando que o corpo de Andrade Lopes foi encontrado em\u00a0S\u00e3o Gon\u00e7alo dos Campos, o que poderia influenciar na senten\u00e7a final.<\/p>\n\n\n\n<p>Geraldo Freitas foi preso quatro dias ap\u00f3s o sumi\u00e7o de Andrade, no dia 28 de maio de 2021 \u2013 mesmo dia em que o corpo do m\u00e9dico acreano foi encontrado no Rio Jacu\u00edpe, em S\u00e3o Gon\u00e7alo dos Campos, a 20 km de Feira de Santana.<\/p>\n\n\n\n<p>Geraldo Freitas estava preso no Conjunto Penal de\u00a0Jequi\u00e9\u00a0desde 9 de agosto de 2023. A pedido da defesa, foi transferido do\u00a0Conjunto Penal de Feira de Santana, onde estava desde a pris\u00e3o. Os advogados alegaram que os familiares da esposa dele moram no sudoeste da Bahia, regi\u00e3o para onde foi transferido.<\/p>\n\n\n\n<p>Apesar da transfer\u00eancia, Geraldo Freitas permanece \u00e0 disposi\u00e7\u00e3o da vara do j\u00fari de Feira de Santana.<\/p>\n\n\n\n<p>Durante o depoimento, o m\u00e9dico\u00a0confessou\u00a0o crime \u00e0 Pol\u00edcia Civil. Depois de matar Andrade, Geraldo buscou a delegacia para registrar o desaparecimento da v\u00edtima. As\u00a0investiga\u00e7\u00f5es\u00a0da pol\u00edcia apontaram que ele agiu sozinho no crime<a class=\"\" href=\"https:\/\/g1.globo.com\/ba\/bahia\/noticia\/2021\/07\/07\/investigacoes-apontam-que-medico-suspeito-de-matar-colega-acreano-na-bahia-agiu-sozinho.ghtml\">.<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"606\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-100.png\" alt=\"\" class=\"wp-image-25766\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-100.png 984w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-100-300x185.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-100-768x473.png 768w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Relembrar o caso<\/strong><\/p>\n\n\n\n<p>O m\u00e9dico Andrade Lopes\u00a0desapareceu\u00a0em 24 de maio de 2021, quando saiu da cidade de Araci, onde morava e trabalhava, com destino a Feira de Santana. Neste mesmo dia, o sumi\u00e7o foi registrado em delegacia por Geraldo.<\/p>\n\n\n\n<p>Depois que o corpo de Andrade foi encontrado, o Departamento de Pol\u00edcia T\u00e9cnica (DPT), constatou que ele foi assassinado um tiro na nuca. Al\u00e9m disso, Geraldo amarrou uma \u00e2ncora no corpo de Andrade, para evitar que o corpo dele emergisse das \u00e1guas do Rio Jacu\u00edpe.<\/p>\n\n\n\n<p>Na \u00e9poca, o delegado Roberto Leal, respons\u00e1vel pela investiga\u00e7\u00e3o, explicou que o crime foi motivado por um desentendimento entre os dois m\u00e9dicos. Geraldo comprou uma caminhonete em nome de Andrade, porque n\u00e3o tinha nome limpo no Serasa, e n\u00e3o fez o pagamento acordado.<\/p>\n\n\n\n<p>A defesa de Geraldo alega que ele n\u00e3o tinha a inten\u00e7\u00e3o de matar Andrade. A pol\u00edcia, no entanto, acredita que houve premedita\u00e7\u00e3o, j\u00e1 que o acusado levou Andrade para o meio do rio de prop\u00f3sito, a fim de cometer o crime e, al\u00e9m da arma, levou uma \u00e2ncora para o local do passeio.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Por G1 Bahia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O m\u00e9dico Geraldo Freitas Junior,\u00a0acusado de matar o colega\u00a0acreano Andrade Lopes Santana, foi condenado a 17 anos, 10 meses e 15 dias de reclus\u00e3o, no F\u00f3rum Filinto Barros, em\u00a0Feira de Santana, a 100 km de Salvador. O julgamento durou 20 horas e contou a presen\u00e7a de amigos e familiares de Andrade Lopes. O crime ocorreu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25765,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-25764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25764"}],"version-history":[{"count":3,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25764\/revisions"}],"predecessor-version":[{"id":25771,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25764\/revisions\/25771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25765"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}