{"id":25792,"date":"2024-09-30T09:37:54","date_gmt":"2024-09-30T12:37:54","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25792"},"modified":"2024-09-30T09:37:55","modified_gmt":"2024-09-30T12:37:55","slug":"filha-de-policial-militar-de-26-anos-e-encontrada-morta","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/09\/30\/filha-de-policial-militar-de-26-anos-e-encontrada-morta\/","title":{"rendered":"Filha de policial militar de 26 anos \u00e9 encontrada morta"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"639\" height=\"426\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-104.png\" alt=\"\" class=\"wp-image-25794\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-104.png 639w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/09\/image-104-300x200.png 300w\" sizes=\"auto, (max-width: 639px) 100vw, 639px\" \/><\/figure>\n<\/div>\n\n\n<p>Uma jovem de 26 anos, identificada como Gabrielle Rayane Oliveira Ribeiro, foi encontrada morta na tarde deste domingo (29), por volta das 16h, dentro do quarto de sua resid\u00eancia, na Avenida prefeito Olimar Oliveira, bairro Ov\u00eddio Teixeira, na cidade de Caetit\u00e9. A informa\u00e7\u00e3o foi confirmada ao site Achei Sudoeste pela Companhia Independente de Pol\u00edcia Militar (CIPM).<\/p>\n\n\n\n<p>O Samu 192 confirmou o \u00f3bito de Rayane. No quarto da jovem, a PM encontrou uma pistola .40. Gabrielle \u00e9 filha do sargento da pol\u00edcia militar Andr\u00e9 Marcos. Segundo o major Roberto Suarez, comandante da 94\u00aa CIPM, o Departamento de Pol\u00edcia T\u00e9cnica (DPT) foi acionado para realizar o levantamento cadav\u00e9rico.<\/p>\n\n\n\n<p>O corpo de Gabrielle ser\u00e1 encaminhado para o Instituto M\u00e9dico Legal (IML) em Guanambi para ser necropsiado. N\u00e3o h\u00e1 informa\u00e7\u00f5es sobre vel\u00f3rio e sepultamento.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Fonte: Achei Sudoeste<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma jovem de 26 anos, identificada como Gabrielle Rayane Oliveira Ribeiro, foi encontrada morta na tarde deste domingo (29), por volta das 16h, dentro do quarto de sua resid\u00eancia, na Avenida prefeito Olimar Oliveira, bairro Ov\u00eddio Teixeira, na cidade de Caetit\u00e9. A informa\u00e7\u00e3o foi confirmada ao site Achei Sudoeste pela Companhia Independente de Pol\u00edcia Militar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25794,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-25792","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25792"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25792\/revisions"}],"predecessor-version":[{"id":25795,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25792\/revisions\/25795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25794"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}