{"id":25811,"date":"2024-10-01T09:34:18","date_gmt":"2024-10-01T12:34:18","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=25811"},"modified":"2024-10-04T08:12:49","modified_gmt":"2024-10-04T11:12:49","slug":"pf-cumpre-mandados-contra-crimes-eleitorais-em-conceicao-do-coite-ilheus-e-capital-baiana","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/10\/01\/pf-cumpre-mandados-contra-crimes-eleitorais-em-conceicao-do-coite-ilheus-e-capital-baiana\/","title":{"rendered":"PF cumpre mandados contra crimes eleitorais em Concei\u00e7\u00e3o do Coit\u00e9, Ilh\u00e9us e capital baiana"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"315\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/IMAGEM_NOTICIA_9.jpg\" alt=\"\" class=\"wp-image-25812\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/IMAGEM_NOTICIA_9.jpg 600w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/IMAGEM_NOTICIA_9-300x158.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>Candidatos dos munic\u00edpios de\u00a0Ilh\u00e9us, no Sul;\u00a0Concei\u00e7\u00e3o do Coit\u00e9, na regi\u00e3o sisaleira; e em Salvador, s\u00e3o alvos de mandados da Pol\u00edcia Federal (PF) na manh\u00e3 desta ter\u00e7a-feira (1\u00b0). Ao todo, nove mandados de busca e apreens\u00e3o s\u00e3o cumpridos no \u00e2mbito da Opera\u00e7\u00e3o Coronelismo.<\/p>\n\n\n\n<p>As a\u00e7\u00f5es visam combater crimes eleitorais e conexos praticados. Segundo a PF, as investiga\u00e7\u00f5es apontam o uso ilegal da estrutura p\u00fablica municipal, com emprego de servidores, ve\u00edculos e combust\u00edveis p\u00fablicos, em benef\u00edcio de determinada coliga\u00e7\u00e3o partid\u00e1ria, ocasionado preju\u00edzo aos cofres p\u00fablicos municipais.<\/p>\n\n\n\n<p>No decorrer das investiga\u00e7\u00f5es tamb\u00e9m foram identificadas supostas fraudes documentais, com superfaturamento de contratos, praticadas, em tese, para encobrir o uso ilegal da estrutura p\u00fablica em benef\u00edcio privado.<\/p>\n\n\n\n<p>Em Ilh\u00e9us, viaturas foram vistas na sede da prefeitura e em outros locais, como o comit\u00ea de campanha de Bento Lima, localizado na Avenida Soares Lopes, e no posto de gasolina Leleu, situado na Avenida Itabuna.<\/p>\n\n\n\n<p>Na \u00faltima semana, a PF deflagrou a\u00a0Opera\u00e7\u00e3o Barganha, que tem como alvos o prefeito da cidade, M\u00e1rio Alexandre (PSD), al\u00e9m do candidato a prefeito e ex-secret\u00e1rio municipal Bento Lima (PSD), um ex-procurador e dois empres\u00e1rios. Na resid\u00eancia de um dos empres\u00e1rios, a pol\u00edcia encontrou R$ 915,9 mil em esp\u00e9cie.<\/p>\n\n\n\n<p>Segundo o\u00a0Pol\u00edticos do Sul da Bahia, parceiro do Bahia Not\u00edcias, as a\u00e7\u00f5es ocorrem na sede da prefeitura e em outros locais, como o comit\u00ea de campanha\u00a0<\/p>\n\n\n\n<p>Os investigados podem responder pelo crime de utiliza\u00e7\u00e3o de ve\u00edculo p\u00fablico em campanha eleitoral (Art. 11, V e par\u00e1grafo \u00fanico, da Lei 6.091\/1974), cuja pena \u00e9 o cancelamento do registro do candidato ou de seu diploma, bem como pelos crimes de peculato (Art. 312 do C\u00f3digo Penal), de falsifica\u00e7\u00e3o de documento p\u00fablico (Art. 297 do C\u00f3digo Penal) e de associa\u00e7\u00e3o criminosa (Art. 288 do C\u00f3digo Penal).<\/p>\n\n\n\n<p>Os crimes investigados nos autos tamb\u00e9m podem configurar abuso do poder econ\u00f4mico e improbidade administrativa.<\/p>\n\n\n\n<p>O nome da opera\u00e7\u00e3o, diz a PF, remete a um per\u00edodo da pol\u00edtica brasileira em que coron\u00e9is se julgavam os donos do munic\u00edpio, manipulando a popula\u00e7\u00e3o e utilizando o poder p\u00fablico para fins privados, cometendo in\u00fameras ilegalidades. (<em>Atualizado \u00e0s 8h38<\/em>)<\/p>\n\n\n\n<p class=\"has-text-align-right\">Por Pol\u00edticos do Sul<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Candidatos dos munic\u00edpios de\u00a0Ilh\u00e9us, no Sul;\u00a0Concei\u00e7\u00e3o do Coit\u00e9, na regi\u00e3o sisaleira; e em Salvador, s\u00e3o alvos de mandados da Pol\u00edcia Federal (PF) na manh\u00e3 desta ter\u00e7a-feira (1\u00b0). Ao todo, nove mandados de busca e apreens\u00e3o s\u00e3o cumpridos no \u00e2mbito da Opera\u00e7\u00e3o Coronelismo. As a\u00e7\u00f5es visam combater crimes eleitorais e conexos praticados. Segundo a PF, as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25813,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-25811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=25811"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25811\/revisions"}],"predecessor-version":[{"id":25814,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/25811\/revisions\/25814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/25813"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=25811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=25811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=25811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}