{"id":26052,"date":"2024-10-18T13:54:52","date_gmt":"2024-10-18T16:54:52","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=26052"},"modified":"2024-10-18T13:54:53","modified_gmt":"2024-10-18T16:54:53","slug":"bahia-recebe-nova-frota-de-viaturas-e-equipamentos-para-a-seguranca-publica","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/10\/18\/bahia-recebe-nova-frota-de-viaturas-e-equipamentos-para-a-seguranca-publica\/","title":{"rendered":"Bahia recebe nova frota de viaturas e equipamentos para a seguran\u00e7a p\u00fablica"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"701\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-18-as-13.01.33_6a997bca-1024x701.jpg\" alt=\"\" class=\"wp-image-26053\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-18-as-13.01.33_6a997bca-1024x701.jpg 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-18-as-13.01.33_6a997bca-300x205.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-18-as-13.01.33_6a997bca-768x525.jpg 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-18-as-13.01.33_6a997bca-1536x1051.jpg 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/10\/Imagem-do-WhatsApp-de-2024-10-18-as-13.01.33_6a997bca.jpg 1548w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Mateus Pereira\u00a0Gov\/ba<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Em uma iniciativa para aprimorar o trabalho da seguran\u00e7a p\u00fablica na Bahia, o Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica (MJSP) e a Secretaria da Seguran\u00e7a P\u00fablica do Estado da Bahia (SSP-BA) realizaram, nesta sexta-feira (18), no Farol da Barra, em Salvador, a entrega de 127 viaturas \u00e0 Pol\u00edcia Militar da Bahia (PMBA), Pol\u00edcia Civil da Bahia (PCBA) e Departamento de Pol\u00edcia T\u00e9cnica (DPT). O aporte de R$ 26 milh\u00f5es do Estado e da Uni\u00e3o vai atender n\u00e3o s\u00f3 a capital baiana, mas, tamb\u00e9m, a outras cidades como: Feira de Santana, Paulo Afonso, Porto Seguro, Lauro de Freitas, Barreiras, Brumado, Itabuna, Teixeira de Freitas e Juazeiro.<\/p>\n\n\n\n<p>Caminhonetes, micro\u00f4nibus, motos e carros de passeio foram alguns dos ve\u00edculos entregues pelo governador Jer\u00f4nimo Rodrigues. Ele estava acompanhado do ministro Ricardo Lewandowski, da Justi\u00e7a e Seguran\u00e7a P\u00fablica do Brasil, e do secret\u00e1rio Marcelo Werner, da Seguran\u00e7a P\u00fablica da Bahia (SSP-BA).<\/p>\n\n\n\n<p>O chefe do Executivo enfatizou que a integra\u00e7\u00e3o dos poderes \u00e9 um objetivo di\u00e1rio na atua\u00e7\u00e3o das for\u00e7as de seguran\u00e7a da Bahia e tem sido alcan\u00e7ada com bons resultados, gra\u00e7as ao apoio da Uni\u00e3o. \u201cEssa parceria da Uni\u00e3o, com fundo, com planejamento, reduz o custo dos Estados na aquisi\u00e7\u00e3o de um ve\u00edculo desses. Al\u00e9m de aportar or\u00e7amento, o Governo Federal tamb\u00e9m aporta estrat\u00e9gia. Ent\u00e3o, \u00e9 fundamental a gente fazer uma entrega, e com o governo Lula, sens\u00edvel ao tema da seguran\u00e7a, com um ministro que conhece por dentro o tema da lei. Isso nos d\u00e1 seguran\u00e7a naquilo que estamos fazendo\u201d, afirmou Jer\u00f4nimo Rodrigues.<\/p>\n\n\n\n<p>O ministro Lewandowski acrescentou que a a\u00e7\u00e3o conjunta com o governo baiano demonstra que \u00e9 poss\u00edvel ter estrat\u00e9gia entre Uni\u00e3o e os Estados brasileiros: \u201cn\u00f3s estamos apresentando um SUS da seguran\u00e7a p\u00fablica no plano constitucional, com recursos permanentes que possam irrigar todo o sistema, que possam conjugar as dez pol\u00edcias que existem no Brasil, contando as federais, as estaduais e as guardas municipais. A Bahia pode representar um modelo para as outras unidades da Federa\u00e7\u00e3o Brasileira\u201d.<\/p>\n\n\n\n<p>Do total das viaturas, 97 v\u00e3o para 45 unidades da Pol\u00edcia Militar, em 16 munic\u00edpios; 26 para a Pol\u00edcia Civil, beneficiando 25 unidades policiais em 12 munic\u00edpios, e mais quatro para o DPT. Al\u00e9m dos ve\u00edculos destinados \u00e0s for\u00e7as de seguran\u00e7a estaduais, foram entregues seis ve\u00edculos para a PRF da Bahia. Quatro viaturas tamb\u00e9m v\u00e3o atender Delegacias Especializadas de Atendimento \u00e0 Mulher (Deams) em Porto Seguro, Cama\u00e7ari, Serrinha e Valen\u00e7a.<\/p>\n\n\n\n<p>H\u00e1 31 anos na Pol\u00edcia Militar, o sargento Francisco Accacio trabalha em uma das unidades da Pol\u00edcia Rodovi\u00e1ria Estadual (PRE) e entende que a nova frota vai garantir mais agilidade e qualidade no trabalho dos agentes da seguran\u00e7a. \u201cEssas viaturas novas melhoram muito o nosso servi\u00e7o, melhora para o policial, da \u00e1rea operacional, mas o cidad\u00e3o \u00e9 quem mais sente cada investimento desse. Ent\u00e3o, s\u00e3o muitos benef\u00edcios. N\u00f3s estamos satisfeitos, tamb\u00e9m, pela valoriza\u00e7\u00e3o que isso representa do nosso trabalho\u201d, avaliou.<\/p>\n\n\n\n<p>Desde 2023, o Estado j\u00e1 investiu R$ 246 milh\u00f5es em entregas de viaturas, drones, helic\u00f3pteros para as policias civil e militar, para o DPT e o Corpo de Bombeiros. O projeto de reestrutura\u00e7\u00e3o da Seguran\u00e7a P\u00fablica tamb\u00e9m tem sido focado no aporte em tecnologias, intelig\u00eancia e na entrega de novas unidades f\u00edsicas para atendimento \u00e0 popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>\u201cDe alguns anos para c\u00e1, h\u00e1 necessidade de viaturas semiblindadas, refor\u00e7ando o trabalho ostensivo de policiamento e garantindo a seguran\u00e7a do nosso policial, que \u00e9 o nosso maior patrim\u00f4nio. \u00c9 importante destacar que a frota entregue hoje \u00e9 uma frota diversificada, para atender diversas miss\u00f5es e fun\u00e7\u00f5es das atividades policiais\u201d, lembrou o titular da SSP-BA.<\/p>\n\n\n\n<p>Na cerim\u00f4nia, o ministro Ricardo Lewandowski tamb\u00e9m oficializou a entrega, pelo Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica, de 17.900 muni\u00e7\u00f5es qu\u00edmicas n\u00e3o-letais, como granadas e sprays de pimenta, \u00e0s for\u00e7as policiais da PMBA e PCBA.<\/p>\n\n\n\n<p>Sa\u00fade dos profissionais<\/p>\n\n\n\n<p>O governo estadual tamb\u00e9m anunciou sua ades\u00e3o ao projeto de interven\u00e7\u00e3o psicol\u00f3gica online para profissionais da seguran\u00e7a p\u00fablica, coordenado pela Secretaria Nacional de Seguran\u00e7a P\u00fablica (Senasp\/MJSP). Em conv\u00eanio com universidades p\u00fablicas, a iniciativa prev\u00ea a assist\u00eancia gratuita e especializada para policiais civis e militares, bombeiros, peritos criminais e policiais penais.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Rep\u00f3rter: Milena fahel\/GOVBA<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em uma iniciativa para aprimorar o trabalho da seguran\u00e7a p\u00fablica na Bahia, o Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica (MJSP) e a Secretaria da Seguran\u00e7a P\u00fablica do Estado da Bahia (SSP-BA) realizaram, nesta sexta-feira (18), no Farol da Barra, em Salvador, a entrega de 127 viaturas \u00e0 Pol\u00edcia Militar da Bahia (PMBA), Pol\u00edcia Civil da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26053,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-26052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=26052"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26052\/revisions"}],"predecessor-version":[{"id":26054,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26052\/revisions\/26054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/26053"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=26052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=26052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=26052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}