{"id":26212,"date":"2024-11-06T09:34:19","date_gmt":"2024-11-06T12:34:19","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=26212"},"modified":"2024-11-12T09:10:41","modified_gmt":"2024-11-12T12:10:41","slug":"mulher-sofre-tentativa-de-feminicidio-na-zona-rural-de-retirolandia","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/11\/06\/mulher-sofre-tentativa-de-feminicidio-na-zona-rural-de-retirolandia\/","title":{"rendered":"Mulher sofre tentativa de feminicidio na zona rural \u00a0de Retirol\u00e2ndia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"303\" height=\"166\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/11\/image-19.png\" alt=\"\" class=\"wp-image-26213\" style=\"width:550px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/11\/image-19.png 303w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/11\/image-19-300x164.png 300w\" sizes=\"auto, (max-width: 303px) 100vw, 303px\" \/><\/figure>\n<\/div>\n\n\n<p>Nesta ter\u00e7a-feira (5), uma guarni\u00e7\u00e3o da pol\u00edcia militar de Retirol\u00e2ndia foi informada de uma tentativa de feminicidio na zona rural do munic\u00edpio. Chegando no local, os agentes foram informados que uma mulher teria sido agredida pelo seu companheiro e que estaria perseguindo no intuito de ceifar a vida da v\u00edtima.<\/p>\n\n\n\n<p>Ainda segundo informa\u00e7\u00f5es, a guarni\u00e7\u00e3o realizou rondas com objetivo de encontrar o acusado e a mulher. Em seguida a v\u00edtima de iniciais I.C.O, 36 anos, foi encontrada dentro de uma casa, a mesma estava em p\u00e2nico com o ocorrido, a guarni\u00e7\u00e3o orientou ela a pegar seus pertences na sua casa e procurar apoio da fam\u00edlia, no dia seguinte procurar a delegacia e registrar um boletim.<\/p>\n\n\n\n<p>O acusado de iniciais M.S e L, de 41 anos, morador na localidade conhecida como Lagoa dos Bois, em Retirol\u00e2ndia, conseguiu fugir pelo matagal, mas foi localizado, inicialmente foi levado para o hospital devido aos ferimentos e em seguida para a delegacia.<\/p>\n\n\n\n<p>Foram apreendidos uma faca quebrada em tr\u00eas lugares, fac\u00e3o e uma espingarda que foram apresentados a autoridade policial.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Informe Bahia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta ter\u00e7a-feira (5), uma guarni\u00e7\u00e3o da pol\u00edcia militar de Retirol\u00e2ndia foi informada de uma tentativa de feminicidio na zona rural do munic\u00edpio. Chegando no local, os agentes foram informados que uma mulher teria sido agredida pelo seu companheiro e que estaria perseguindo no intuito de ceifar a vida da v\u00edtima. Ainda segundo informa\u00e7\u00f5es, a guarni\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26213,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-26212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=26212"}],"version-history":[{"count":2,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26212\/revisions"}],"predecessor-version":[{"id":26216,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26212\/revisions\/26216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/26213"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=26212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=26212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=26212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}