{"id":26413,"date":"2024-11-26T10:39:59","date_gmt":"2024-11-26T13:39:59","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=26413"},"modified":"2024-11-27T09:02:47","modified_gmt":"2024-11-27T12:02:47","slug":"mais-de-130-trouxinha-de-drogas-e-armas-sao-apreendidas-em-araci","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/11\/26\/mais-de-130-trouxinha-de-drogas-e-armas-sao-apreendidas-em-araci\/","title":{"rendered":"Mais de 130 trouxinha de drogas e armas s\u00e3o apreendidas em Araci"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"880\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/11\/Imagem-do-WhatsApp-de-2024-11-25-as-21.53.45_7cebde57-1024x880.jpg\" alt=\"\" class=\"wp-image-26414\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/11\/Imagem-do-WhatsApp-de-2024-11-25-as-21.53.45_7cebde57-1024x880.jpg 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/11\/Imagem-do-WhatsApp-de-2024-11-25-as-21.53.45_7cebde57-300x258.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/11\/Imagem-do-WhatsApp-de-2024-11-25-as-21.53.45_7cebde57-768x660.jpg 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/11\/Imagem-do-WhatsApp-de-2024-11-25-as-21.53.45_7cebde57.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Durante rondas realizadas na zona rural do munic\u00edpio de Araci nesta segunda-feira (25), uma guarni\u00e7\u00e3o da pol\u00edcia militar recebeu informa\u00e7\u00f5es de comercializa\u00e7\u00e3o de drogas no povoado de Barbosa em uma casa abandonada.<\/p>\n\n\n\n<p>Segundo a guarni\u00e7\u00e3o, ao chegar no local da den\u00fancia, visualizou um indiv\u00edduo de posse de uma bolsa artesanal. Durante a abordagem foi encontrado uma certa quantidade de drogas, sendo 133 trouxinha de maconha, 1 tablete pesando 229 gramas do mesmo entorpecente, 3 espingardas, 2 balan\u00e7as de precis\u00e3o, um caderno com anota\u00e7\u00f5es e uma pequena quantia em dinheiro. <\/p>\n\n\n\n<p>O suspeito de iniciais A.L.J, de 24 anos, residente no povoado onde aconteceu a\u00e7\u00e3o e o material apreendido foi apresentado \u00e0 delegacia para o registro da ocorr\u00eancia. \u00a0<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Informe Bahia <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante rondas realizadas na zona rural do munic\u00edpio de Araci nesta segunda-feira (25), uma guarni\u00e7\u00e3o da pol\u00edcia militar recebeu informa\u00e7\u00f5es de comercializa\u00e7\u00e3o de drogas no povoado de Barbosa em uma casa abandonada. Segundo a guarni\u00e7\u00e3o, ao chegar no local da den\u00fancia, visualizou um indiv\u00edduo de posse de uma bolsa artesanal. Durante a abordagem foi encontrado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26414,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-26413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=26413"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26413\/revisions"}],"predecessor-version":[{"id":26415,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26413\/revisions\/26415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/26414"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=26413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=26413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=26413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}