{"id":26424,"date":"2024-11-26T16:19:05","date_gmt":"2024-11-26T19:19:05","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=26424"},"modified":"2024-11-26T16:19:05","modified_gmt":"2024-11-26T19:19:05","slug":"luciano-araujo-apresenta-pl-para-reconhecer-o-sisal-como-patrimonio-cultural-imaterial-da-bahia","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/11\/26\/luciano-araujo-apresenta-pl-para-reconhecer-o-sisal-como-patrimonio-cultural-imaterial-da-bahia\/","title":{"rendered":"Luciano Ara\u00fajo apresenta PL para reconhecer o sisal como patrim\u00f4nio cultural imaterial da Bahia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/luciano-araujo-explica-proposta-dos-trabalhadores-da-regiao-do-sisal-o-produtor-tem-que-ter-realmente-condicoes-de-trabalhoassista734468920-1024x768.jpeg\" alt=\"\" class=\"wp-image-24260\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/luciano-araujo-explica-proposta-dos-trabalhadores-da-regiao-do-sisal-o-produtor-tem-que-ter-realmente-condicoes-de-trabalhoassista734468920-1024x768.jpeg 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/luciano-araujo-explica-proposta-dos-trabalhadores-da-regiao-do-sisal-o-produtor-tem-que-ter-realmente-condicoes-de-trabalhoassista734468920-300x225.jpeg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/luciano-araujo-explica-proposta-dos-trabalhadores-da-regiao-do-sisal-o-produtor-tem-que-ter-realmente-condicoes-de-trabalhoassista734468920-768x576.jpeg 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/luciano-araujo-explica-proposta-dos-trabalhadores-da-regiao-do-sisal-o-produtor-tem-que-ter-realmente-condicoes-de-trabalhoassista734468920-1536x1152.jpeg 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/luciano-araujo-explica-proposta-dos-trabalhadores-da-regiao-do-sisal-o-produtor-tem-que-ter-realmente-condicoes-de-trabalhoassista734468920-86x64.jpeg 86w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/06\/luciano-araujo-explica-proposta-dos-trabalhadores-da-regiao-do-sisal-o-produtor-tem-que-ter-realmente-condicoes-de-trabalhoassista734468920.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>O deputado estadual Luciano Ara\u00fajo (Solidariedade) apresentou Projeto de Lei que reconhece como patrim\u00f4nio cultural imaterial do Estado da Bahia, a cultura do Sisal.<\/p>\n\n\n\n<p>A Bahia \u00e9 o maior produtor de sisal do planeta e det\u00e9m em torno de 90% da produ\u00e7\u00e3o nacional do Brasil, pa\u00eds que mais cultiva a agave no mundo. De acordo com a Empresa Brasileira de Pesquisa Agropecu\u00e1ria (EMBRAPA), a Bahia produz anualmente 140 mil toneladas de fibra de sisal e que cerca de 50% desta produ\u00e7\u00e3o \u00e9 escoada para o exterior.<\/p>\n\n\n\n<p>\u201cO cultivo do Sisal faz da Bahia um fen\u00f4meno mundial. S\u00e3o quase 70 munic\u00edpios baianos envolvidos com a sua produ\u00e7\u00e3o. A Bahia, ao criar os 27 Territ\u00f3rios de Identidade, reconheceu a import\u00e2ncia do sisal ao denominar a regi\u00e3o dos munic\u00edpios de Araci, Barrocas, Biritinga, Candeal, Cansan\u00e7\u00e3o, Concei\u00e7\u00e3o do Coit\u00e9, Ichu, Iti\u00faba, Lamar\u00e3o, Monte Santo, Nordestina, Queimadas, Quijingue, Retirol\u00e2ndia, Santaluz, S\u00e3o Domingos, Serrinha, Teofil\u00e2ndia, Tucano, Jacobina, Ourol\u00e2ndia, V\u00e1rzea Nova e Valente como sendo a regi\u00e3o do sisal ou regi\u00e3o sisaleira. Com isso, podemos observar a import\u00e2ncia cultural do sisal ou o \u201couro verde do sert\u00e3o\u201d, informou o parlamentar.<\/p>\n\n\n\n<p>\u201cA aprova\u00e7\u00e3o deste projeto de lei contribuir\u00e1, com efeito, para o reconhecimento da import\u00e2ncia da cultura do sisal para o nosso Estado cumprindo com o papel de resgate hist\u00f3rico de uma das mais importantes cadeias produtivas do Estado respons\u00e1vel por elevar o nome do Estado da Bahia no mundo e da caracteriza\u00e7\u00e3o pr\u00f3pria de toda uma regi\u00e3o que funciona cultural e economicamente em torno desta cultura\u201d, frisou Luciano Araujo.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Via Da Bahia News<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O deputado estadual Luciano Ara\u00fajo (Solidariedade) apresentou Projeto de Lei que reconhece como patrim\u00f4nio cultural imaterial do Estado da Bahia, a cultura do Sisal. A Bahia \u00e9 o maior produtor de sisal do planeta e det\u00e9m em torno de 90% da produ\u00e7\u00e3o nacional do Brasil, pa\u00eds que mais cultiva a agave no mundo. De acordo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24260,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-26424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=26424"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26424\/revisions"}],"predecessor-version":[{"id":26425,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26424\/revisions\/26425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/24260"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=26424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=26424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=26424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}