{"id":26737,"date":"2024-12-23T11:17:14","date_gmt":"2024-12-23T14:17:14","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=26737"},"modified":"2024-12-27T08:50:22","modified_gmt":"2024-12-27T11:50:22","slug":"condenado-por-trafico-de-drogas-na-regiao-metropolitana-de-salvador-e-preso-na-regiao-sisaleira","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2024\/12\/23\/condenado-por-trafico-de-drogas-na-regiao-metropolitana-de-salvador-e-preso-na-regiao-sisaleira\/","title":{"rendered":"Condenado por tr\u00e1fico de drogas na regi\u00e3o metropolitana de Salvador \u00e9 preso na regi\u00e3o sisaleira"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"405\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/12\/image-70.png\" alt=\"\" class=\"wp-image-26738\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/12\/image-70.png 540w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/12\/image-70-300x225.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2024\/12\/image-70-86x64.png 86w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/figure>\n<\/div>\n\n\n<p>Um homem de 34 anos, condenado por tr\u00e1fico de drogas na regi\u00e3o metropolitana de Salvador, foi preso no s\u00e1bado (21) em Serrinha, na regi\u00e3o sisaleira da Bahia. Ele estava foragido h\u00e1 dois anos, desde que saiu do Conjunto Penal de Lauro de Freitas para o Natal de 2022 e n\u00e3o voltou mais.<\/p>\n\n\n\n<p>A pris\u00e3o foi realizada pela Pol\u00edcia Militar com o apoio do sistema de reconhecimento facial da Secretaria de Seguran\u00e7a P\u00fablica da Bahia (SSP-BA). De acordo com a PM, o homem, que \u00e9 natural de Salvador e tinha um mandado de pris\u00e3o em aberto, foi levado para a Delegacia Territorial de Serrinha, onde ficou \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n\n\n\n<p>Segundo a SSP, o reconhecimento facial j\u00e1 ajudou a capturar mais de mil foragidos em 2024. Esse \u00e9 o maior n\u00famero registrado desde que o sistema come\u00e7ou a ser usado, em 2019.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Por Not\u00edcias de Santaluz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 34 anos, condenado por tr\u00e1fico de drogas na regi\u00e3o metropolitana de Salvador, foi preso no s\u00e1bado (21) em Serrinha, na regi\u00e3o sisaleira da Bahia. Ele estava foragido h\u00e1 dois anos, desde que saiu do Conjunto Penal de Lauro de Freitas para o Natal de 2022 e n\u00e3o voltou mais. A pris\u00e3o foi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26738,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-26737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=26737"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26737\/revisions"}],"predecessor-version":[{"id":26739,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/26737\/revisions\/26739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/26738"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=26737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=26737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=26737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}