{"id":27294,"date":"2025-02-22T12:01:51","date_gmt":"2025-02-22T15:01:51","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=27294"},"modified":"2025-02-28T09:11:50","modified_gmt":"2025-02-28T12:11:50","slug":"policia-prende-pm-suspeito-de-matar-advogado-no-carro-em-conceicao-do-coite","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2025\/02\/22\/policia-prende-pm-suspeito-de-matar-advogado-no-carro-em-conceicao-do-coite\/","title":{"rendered":"Pol\u00edcia prende PM suspeito de matar advogado no carro em Concei\u00e7\u00e3o do Coit\u00e9"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"696\" height=\"392\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/02\/image-52.png\" alt=\"\" class=\"wp-image-27296\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/02\/image-52.png 696w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/02\/image-52-300x169.png 300w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/figure>\n<\/div>\n\n\n<p>O suspeito de matar o advogado Elido Ernesto Reyes J\u00fanior, de 53 anos, em Concei\u00e7\u00e3o do Coit\u00e9, foi preso na manh\u00e3 deste s\u00e1bado (22). A informa\u00e7\u00e3o foi confirmada pelo delegado F\u00e1bio de Melo Nobre, da 15\u00aa COORPIN de Serrinha. A identidade do homem n\u00e3o foi revelada.<\/p>\n\n\n\n<p>Segundo apura\u00e7\u00e3o do site Informe Baiano, o suspeito seria um policial militar. Agora, a Pol\u00edcia Civil procura o mandante do crime.<\/p>\n\n\n\n<p>Ernesto foi alvejado a tiros enquanto dirigia seu carro na rua Bailon Lopes Carneiro, no centro da cidade. O crime, que tem caracter\u00edsticas de execu\u00e7\u00e3o, foi cometido por um homem que se aproximou da v\u00edtima em uma motocicleta e efetuou os disparos.<\/p>\n\n\n\n<p>Ele era um dos profissionais mais conhecidos da cidade e s\u00f3cio do escrit\u00f3rio Ernesto Reyes &amp; Lopes Advocacia. Em um v\u00eddeo gravado no final do ano passado e enviado a amigos, o advogado relatou que vinha sofrendo amea\u00e7as devido a uma disputa por um im\u00f3vel da fam\u00edlia, al\u00e9m de um inquilino ligado \u00e0 propriedade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O suspeito de matar o advogado Elido Ernesto Reyes J\u00fanior, de 53 anos, em Concei\u00e7\u00e3o do Coit\u00e9, foi preso na manh\u00e3 deste s\u00e1bado (22). A informa\u00e7\u00e3o foi confirmada pelo delegado F\u00e1bio de Melo Nobre, da 15\u00aa COORPIN de Serrinha. A identidade do homem n\u00e3o foi revelada. Segundo apura\u00e7\u00e3o do site Informe Baiano, o suspeito seria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27296,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-27294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=27294"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27294\/revisions"}],"predecessor-version":[{"id":27297,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27294\/revisions\/27297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/27296"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=27294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=27294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=27294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}