{"id":27355,"date":"2025-03-11T09:15:13","date_gmt":"2025-03-11T12:15:13","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=27355"},"modified":"2025-03-11T09:15:14","modified_gmt":"2025-03-11T12:15:14","slug":"cachorros-causam-acidente-de-moto-e-condutor-fica-ferido-em-conceicao-do-coite","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2025\/03\/11\/cachorros-causam-acidente-de-moto-e-condutor-fica-ferido-em-conceicao-do-coite\/","title":{"rendered":"Cachorros causam acidente de moto e condutor fica ferido em Concei\u00e7\u00e3o do Coit\u00e9"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"608\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/Imagem-do-WhatsApp-de-2025-03-11-as-08.56.18_3439f978-1024x608.jpg\" alt=\"\" class=\"wp-image-27356\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/Imagem-do-WhatsApp-de-2025-03-11-as-08.56.18_3439f978-1024x608.jpg 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/Imagem-do-WhatsApp-de-2025-03-11-as-08.56.18_3439f978-300x178.jpg 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/Imagem-do-WhatsApp-de-2025-03-11-as-08.56.18_3439f978-768x456.jpg 768w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/Imagem-do-WhatsApp-de-2025-03-11-as-08.56.18_3439f978-1536x912.jpg 1536w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/Imagem-do-WhatsApp-de-2025-03-11-as-08.56.18_3439f978.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Por volta das 7h53 desta ter\u00e7a-feira (11), a equipe de socorristas \u00c1guia Resgate foi acionada para comparecer na localidade conhecida como P\u00e9ba, regi\u00e3o do distrito de Salgadalia, zona rural de Concei\u00e7\u00e3o do Coit\u00e9-Ba, para socorrer um homem que ficou ferido ap\u00f3s sofrer um acidente de moto.<\/p>\n\n\n\n<p>Segundo apurou o Informe Bahia, atrav\u00e9s do socorrista Evandro, o motociclista identificado como Irenildo Costa dos Reis, 38 anos, morador na localidade onde aconteceu o acidente, ficou ferido com escoria\u00e7\u00f5es pelo corpo e suspeita de fratura em uma das pernas. Informa\u00e7\u00f5es d\u00e3o conta que o acidente foi provocado por ataques de cachorro, quando ele perdeu o controle e caiu.<\/p>\n\n\n\n<p>A v\u00edtima foi encaminhada para a emerg\u00eancia do Hospital Portugu\u00eas, em Concei\u00e7\u00e3o do Coit\u00e9 onde seria atendido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 7h53 desta ter\u00e7a-feira (11), a equipe de socorristas \u00c1guia Resgate foi acionada para comparecer na localidade conhecida como P\u00e9ba, regi\u00e3o do distrito de Salgadalia, zona rural de Concei\u00e7\u00e3o do Coit\u00e9-Ba, para socorrer um homem que ficou ferido ap\u00f3s sofrer um acidente de moto. Segundo apurou o Informe Bahia, atrav\u00e9s do socorrista Evandro, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27356,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=27355"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27355\/revisions"}],"predecessor-version":[{"id":27357,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27355\/revisions\/27357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/27356"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=27355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=27355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=27355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}