{"id":27416,"date":"2025-03-20T13:45:47","date_gmt":"2025-03-20T16:45:47","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=27416"},"modified":"2025-03-20T13:45:48","modified_gmt":"2025-03-20T16:45:48","slug":"motorista-morre-em-capotamento-na-br-324-apos-evitar-colisao-frontal-com-uma-carreta","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2025\/03\/20\/motorista-morre-em-capotamento-na-br-324-apos-evitar-colisao-frontal-com-uma-carreta\/","title":{"rendered":"Motorista morre em capotamento na BR 324 ap\u00f3s evitar colis\u00e3o frontal com uma carreta"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"375\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/image-15.png\" alt=\"\" class=\"wp-image-27417\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/image-15.png 750w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/image-15-300x150.png 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/div>\n\n\n<p>Um grav\u00edssimo acidente no fim da manh\u00e3 desta quinta-feira, 20, na Rodovia BR 324, trecho Riach\u00e3o do Jacu\u00edpe \u2013 Tanquinho, resultou na morte do motorista de um Fiat Strada, pertencente a uma empresa de Minas Gerais, Grupo Tonaco do Tri\u00e2ngulo, que atua no ramo de sementes de pastagem e estava com uma carga de palma.<\/p>\n\n\n\n<p>A Brigada Volunt\u00e1ria Anjos Jacuipenses foi acionada pontualmente ao meio-dia, para prestar socorro a v\u00edtima do acidente ocorrido pr\u00f3ximo ao Posto Carreteiro, distante cerca de 5 km da sede de Riach\u00e3o do Jacu\u00edpe, mas ao chegar no local constatou que o motorista identificado como Carlos Roberto Pita Louredo, 59 anos, n\u00e3o apresentava os sinais vitais.<\/p>\n\n\n\n<p>Lucival Souza, coordenador da Brigada, disse ao Calila Not\u00edcias que uma testemunha relatou que o motorista do Fiat Strada seguia no sentido Riach\u00e3o e teria sa\u00eddo da pista para evitar uma colis\u00e3o frontal com uma carreta, quando capotou ap\u00f3s atingir uma cerca de arame de uma fazenda.<\/p>\n\n\n\n<p>Ainda de acordo com Lucival, teve acesso ao n\u00famero do telefone da empresa que fica em Corinto\u2013MG, que consta na porta do ve\u00edculo, e j\u00e1 manteve contato, tendo sido informado que outros funcion\u00e1rios est\u00e3o na Bahia e que ir\u00e1 comunicar para que eles possam fazer o reconhecimento e libera\u00e7\u00e3o do corpo.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Por Calila Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um grav\u00edssimo acidente no fim da manh\u00e3 desta quinta-feira, 20, na Rodovia BR 324, trecho Riach\u00e3o do Jacu\u00edpe \u2013 Tanquinho, resultou na morte do motorista de um Fiat Strada, pertencente a uma empresa de Minas Gerais, Grupo Tonaco do Tri\u00e2ngulo, que atua no ramo de sementes de pastagem e estava com uma carga de palma. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27417,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-27416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaq"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=27416"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27416\/revisions"}],"predecessor-version":[{"id":27418,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27416\/revisions\/27418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/27417"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=27416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=27416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=27416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}