{"id":27492,"date":"2025-03-27T14:07:55","date_gmt":"2025-03-27T17:07:55","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=27492"},"modified":"2025-04-02T13:08:54","modified_gmt":"2025-04-02T16:08:54","slug":"suspeito-de-tentativa-de-homicidio-e-preso-com-drogas-em-santaluz","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2025\/03\/27\/suspeito-de-tentativa-de-homicidio-e-preso-com-drogas-em-santaluz\/","title":{"rendered":"Suspeito de tentativa de homic\u00eddio \u00e9 preso com drogas em Santaluz"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"414\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/cats-5.jpg\" alt=\"\" class=\"wp-image-27493\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/cats-5.jpg 540w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/cats-5-300x230.jpg 300w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o da PM<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Ap\u00f3s tomar conhecimento de uma tentativa de homic\u00eddio ocorrido em Santaluz, a pol\u00edcia militar estava realizando rondas na tentativa de prender o suspeito. Por volta das 18h10 desta quarta-feira (26), uma guarni\u00e7\u00e3o recebeu informa\u00e7\u00f5es de que o mesmo estaria homiziado em uma resid\u00eancia no bairro S\u00e3o Pedro.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, o suspeito empreendeu fuga para dentro da resid\u00eancia e logo ap\u00f3s pulou um muro lateral da casa. Na fuga o suspeito se chocou com uma cerca de arame farpado e caiu ao solo deixando cair o celular e uma sacola contendo drogas.<\/p>\n\n\n\n<p>O suspeito de iniciais E.B.S., 18 anos, morador na Quadra D, no bairro JK, em Santaluz, foi conduzido para a delegacia de Serrinha. Na a\u00e7\u00e3o foram apreendidas 26 trouxinhas de coca\u00edna, 4 trouxinhas de maconha e uma por\u00e7\u00e3o de maconha pesando aproximadamente 125 gramas.<\/p>\n\n\n\n<p class=\"has-text-align-right\">*Informe Bahia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s tomar conhecimento de uma tentativa de homic\u00eddio ocorrido em Santaluz, a pol\u00edcia militar estava realizando rondas na tentativa de prender o suspeito. Por volta das 18h10 desta quarta-feira (26), uma guarni\u00e7\u00e3o recebeu informa\u00e7\u00f5es de que o mesmo estaria homiziado em uma resid\u00eancia no bairro S\u00e3o Pedro. Segundo informa\u00e7\u00f5es, o suspeito empreendeu fuga para dentro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27493,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-27492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fatospolicias"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=27492"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27492\/revisions"}],"predecessor-version":[{"id":27494,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27492\/revisions\/27494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/27493"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=27492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=27492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=27492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}