{"id":27514,"date":"2025-03-31T15:28:29","date_gmt":"2025-03-31T18:28:29","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=27514"},"modified":"2025-03-31T15:28:30","modified_gmt":"2025-03-31T18:28:30","slug":"odonto-movel-leva-atendimentos-odontologicos-para-diversas-localidades-de-coite-em-abril","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2025\/03\/31\/odonto-movel-leva-atendimentos-odontologicos-para-diversas-localidades-de-coite-em-abril\/","title":{"rendered":"Odonto M\u00f3vel leva atendimentos odontol\u00f3gicos para diversas localidades de Coit\u00e9 em abril"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/image-36.png\" alt=\"\" class=\"wp-image-27516\" style=\"width:550px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/image-36.png 1024w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/image-36-300x188.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/03\/image-36-768x480.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>A Prefeitura de Concei\u00e7\u00e3o do Coit\u00e9 segue levando sa\u00fade bucal para mais perto da popula\u00e7\u00e3o. O programa Odonto M\u00f3vel, realizado pela Secretaria de Sa\u00fade do munic\u00edpio, inicia no m\u00eas de abril uma nova etapa de atendimentos odontol\u00f3gicos itinerantes em comunidades da zona rural, ampliando o acesso da popula\u00e7\u00e3o a servi\u00e7os gratuitos e de qualidade.<\/p>\n\n\n\n<p>Os atendimentos come\u00e7am no dia 1\u00ba de abril, contemplando localidades estrat\u00e9gicas com a\u00e7\u00f5es de preven\u00e7\u00e3o, diagn\u00f3stico e tratamento odontol\u00f3gico. O objetivo \u00e9 garantir o cuidado integral com a sa\u00fade bucal, promovendo bem-estar e qualidade de vida para os coiteenses.<\/p>\n\n\n\n<p>Confira a programa\u00e7\u00e3o completa:<\/p>\n\n\n\n<p>\u2022 Gangorra I<\/p>\n\n\n\n<p>01 de abril, a partir das 08h<\/p>\n\n\n\n<p>Localidades contempladas: Gangorra I, Gangorra II e Tamburi<\/p>\n\n\n\n<p>\u2022 Cruzeiro de Aroeira<\/p>\n\n\n\n<p>02 de abril, a partir das 08h<\/p>\n\n\n\n<p>Localidades contempladas: Cruzeiro de Aroeira e Martinho<\/p>\n\n\n\n<p>\u2022 Fazenda Boa Vista<\/p>\n\n\n\n<p>03 e 07 de abril, a partir das 08h<\/p>\n\n\n\n<p>Localidades contempladas: Fazenda Boa Vista de Aroeira, Umburana, Queimadinha, Fazenda Jacu, Fazenda Alagadi\u00e7o, Ilha, Martins e Cruzeiro Pintado<\/p>\n\n\n\n<p>\u2022 Vila Novo Horizonte<\/p>\n\n\n\n<p>08 de abril, a partir das 08h<\/p>\n\n\n\n<p>Localidade contemplada: Vila Novo Horizonte<\/p>\n\n\n\n<p>\u2022 A\u00e7ude de Aroeira<\/p>\n\n\n\n<p>09 e 10 de abril, a partir das 08h<\/p>\n\n\n\n<p>Localidades contempladas: A\u00e7ude de Aroeira, Melancia, Vassoura e Jurema<\/p>\n\n\n\n<p>\u2022 Lagoa Ferrada<\/p>\n\n\n\n<p>11 e 14 de abril, a partir das 08h<\/p>\n\n\n\n<p>Localidade contemplada: Lagoa Ferrada<\/p>\n\n\n\n<p>A coordenadora do programa, Fernanda Ara\u00fajo, destaca a import\u00e2ncia dessa iniciativa. \u201cO Odonto M\u00f3vel tem transformado a realidade de muitas comunidades, levando atendimento de qualidade para onde antes o acesso era mais dif\u00edcil. Nosso objetivo \u00e9 cuidar das pessoas, prevenir doen\u00e7as e garantir sorrisos saud\u00e1veis em cada canto de Coit\u00e9.\u201d<\/p>\n\n\n\n<p>Os atendimentos acontecem sempre a partir das 8h da manh\u00e3, com distribui\u00e7\u00e3o de senhas por ordem de chegada. A unidade m\u00f3vel conta com estrutura equipada para oferecer todos os cuidados necess\u00e1rios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Concei\u00e7\u00e3o do Coit\u00e9 segue levando sa\u00fade bucal para mais perto da popula\u00e7\u00e3o. O programa Odonto M\u00f3vel, realizado pela Secretaria de Sa\u00fade do munic\u00edpio, inicia no m\u00eas de abril uma nova etapa de atendimentos odontol\u00f3gicos itinerantes em comunidades da zona rural, ampliando o acesso da popula\u00e7\u00e3o a servi\u00e7os gratuitos e de qualidade. Os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27516,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-27514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=27514"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27514\/revisions"}],"predecessor-version":[{"id":27517,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27514\/revisions\/27517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/27516"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=27514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=27514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=27514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}