{"id":27766,"date":"2025-05-06T11:12:25","date_gmt":"2025-05-06T14:12:25","guid":{"rendered":"https:\/\/informebahia.com\/site\/?p=27766"},"modified":"2025-05-08T15:27:25","modified_gmt":"2025-05-08T18:27:25","slug":"cinco-homens-morrem-apos-batida-entre-dois-carros-na-bahia-quatro-vitimas-eram-da-mesma-familia","status":"publish","type":"post","link":"https:\/\/informebahia.com\/site\/2025\/05\/06\/cinco-homens-morrem-apos-batida-entre-dois-carros-na-bahia-quatro-vitimas-eram-da-mesma-familia\/","title":{"rendered":"Cinco homens morrem ap\u00f3s batida entre dois carros na Bahia; quatro v\u00edtimas eram da mesma fam\u00edlia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"616\" src=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/05\/image-22.png\" alt=\"\" class=\"wp-image-27768\" style=\"width:600px\" srcset=\"https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/05\/image-22.png 984w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/05\/image-22-300x188.png 300w, https:\/\/informebahia.com\/site\/wp-content\/uploads\/2025\/05\/image-22-768x481.png 768w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><\/figure>\n<\/div>\n\n\n<p>Cinco homens morreram ap\u00f3s uma batida entre dois carros na tarde desta segunda-feira (5), na BR-030, em trecho da cidade de\u00a0Guanambi, no sudoeste da Bahia. Segundo a Pol\u00edcia Militar, quatro v\u00edtimas eram da mesma fam\u00edlia.<\/p>\n\n\n\n<p>O acidente aconteceu por volta das 12h, no Km 14, na zona rural do munic\u00edpio. As v\u00edtimas foram identificadas como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jonas da Silva Marques, de 34 anos (dirigia um dos carros);<\/li>\n\n\n\n<li>Obaldo Silva Marques, de 62 anos (pai de Jonas);<\/li>\n\n\n\n<li>Fl\u00e1vio Menezes da Silva, de 52 anos (tio de Jonas e irm\u00e3o de Obaldo e de Ivalter);<\/li>\n\n\n\n<li>Ivalter da Silva Marques, de 51 anos (tio de Jonas e irm\u00e3o de Obaldo e Fl\u00e1vio);<\/li>\n\n\n\n<li>Alex Mendes de Oliveira, 36 anos (condutor do outro carro).<\/li>\n<\/ul>\n\n\n\n<p>Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es sobre o que motivou a batida. Todas as v\u00edtimas morreram no local do acidente.<\/p>\n\n\n\n<p>Todas os homens moravam na cidade de\u00a0Palmas de Monte Alto, que tamb\u00e9m fica no sudoeste do estado. Os corpos deles foram levados para o Instituto M\u00e9dico Legal (IML) de Guanambi. O acidente foi registrado na delegacia do munic\u00edpio.<\/p>\n\n\n\n<p class=\"has-text-align-right\">Por G1 Bahia<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cinco homens morreram ap\u00f3s uma batida entre dois carros na tarde desta segunda-feira (5), na BR-030, em trecho da cidade de\u00a0Guanambi, no sudoeste da Bahia. Segundo a Pol\u00edcia Militar, quatro v\u00edtimas eram da mesma fam\u00edlia. O acidente aconteceu por volta das 12h, no Km 14, na zona rural do munic\u00edpio. As v\u00edtimas foram identificadas como: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27768,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-27766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/comments?post=27766"}],"version-history":[{"count":1,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27766\/revisions"}],"predecessor-version":[{"id":27769,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/posts\/27766\/revisions\/27769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media\/27768"}],"wp:attachment":[{"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/media?parent=27766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/categories?post=27766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/informebahia.com\/site\/wp-json\/wp\/v2\/tags?post=27766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}